{"id":48294,"date":"2024-06-27T13:41:44","date_gmt":"2024-06-27T11:41:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=48294"},"modified":"2024-06-27T13:41:47","modified_gmt":"2024-06-27T11:41:47","slug":"inspecteur-commercial-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/inspecteur-commercial-2\/","title":{"rendered":"INSPECTEUR Commercial"},"content":{"rendered":"\n<p>Localisation : Yaound\u00e9 \u2014 Cameroun<br>Nature du contrat : CDD<br>Mission principale : D\u00e9velopper et assurer le suivi du portefeuille commercial.<br>\u00a0<br><strong>Responsabilit\u00e9s<\/strong><br>I. Gestion de l&rsquo;\u00e9quipe de vente :<br>Recruter, former et encadrer les conseillers en assurance vie.<br>Motiver l&rsquo;\u00e9quipe pour atteindre et d\u00e9passer les objectifs de vente.<br>\u00a0 Organiser des r\u00e9unions r\u00e9guli\u00e8res pour discuter des strat\u00e9gies de vente, des performances et des plans d&rsquo;action.<br>2. D\u00e9veloppement des ventes :<br>\u00a0\u00a0\u00a0 \u00a0Elaborer et mettre en \u0153uvre des strat\u00e9gies de vente efficaces.<br>\u00a0\u00a0\u00a0 \u00a0Analyser les tendances du march\u00e9 et ajuster les plans de vente en cons\u00e9quence.<br>\u00a0\u00a0\u00a0 \u00a0Identifier et d\u00e9velopper de nouvelles opportunit\u00e9s de march\u00e9.<br>3. Suivi et analyse des performances :<br>&#8211;\u00a0\u00a0 \u00a0Surveiller les performances de l&rsquo;\u00e9quipe de vente et fournir des rapports r\u00e9guliers \u00e0 la direction.<br>&#8211;\u00a0\u00a0 \u00a0Utiliser des indicateurs de performance cl\u00e9s (KPI) pour \u00e9valuer l&rsquo;efficacit\u00e9 des conseillers.<br>&#8211;\u00a0\u00a0 \u00a0Proposer des actions correctives en cas de sous performance.<br>4. Relations clients :<br>\u00a0 Assurer un service client de haute qualit\u00e9.<br>\u00a0\u00a0\u00a0 \u00a0G\u00e9rer les plaintes et les retours des clients de mani\u00e8re efficace.<br>\u00a0\u00a0\u00a0 \u00a0Maintenir et d\u00e9velopper les relations avec les clients cl\u00e9s.<br>5. Conformit\u00e9 et r\u00e9glementation :<br>\u00a0\u00a0\u00a0 \u00a0Veiller \u00e0 ce que l&rsquo;\u00e9quipe respecte toutes les r\u00e9glementations en mati\u00e8re d&rsquo;assurance vie.<br>\u00a0\u00a0\u00a0 \u00a0Former l&rsquo;\u00e9quipe sur les nouvelles lois et r\u00e9glementations en vigueur.<br>Comp\u00e9tences requises<br>1. Comp\u00e9tences en gestion :<br>\u00a0\u00a0\u00a0 \u00a0Capacit\u00e9 \u00e0 diriger et motiver une \u00e9quipe.<br>\u00a0\u00a0\u00a0 \u00a0Comp\u00e9tences en gestion du temps et en organisation.<br>2. Comp\u00e9tences en vente :<br>\u00a0\u00a0\u00a0 \u00a0Excellentes comp\u00e9tences en n\u00e9gociation et en persuasion.<br>\u00a0\u00a0\u00a0 \u00a0Connaissance approfondie des produits d&rsquo;assurance vie.<br>0 3) Chanas Assurances www.chanasassurances.com<br>3.\u00a0\u00a0 \u00a0Comp\u00e9tences analytiques :<br>Capacit\u00e9 \u00e0 analyser les de vente et \u00e0 tirer des conclusions pour am\u00e9liorer les performances. Comp\u00e9tences en r\u00e9solution de probl\u00e8mes.<br>4.\u00a0\u00a0 \u00a0Communication :<br>\u00a0 Excellentes comp\u00e9tences en communication orale et \u00e9crite.<br>\u00a0 Capacit\u00e9 \u00e0 pr\u00e9senter des informations complexes de mani\u00e8re claire et concise<br>5.\u00a0\u00a0 \u00a0Connaissance du secteur :<br>\u00a0 Compr\u00e9hension approfondie du secteur de l&rsquo;assurance vie.<br>\u00a0 Connaissance des r\u00e9glementations et des lois pertinentes.<br>6.\u00a0\u00a0 \u00a0Comp\u00e9tences interpersonnelles :<br>\u00a0 Capacit\u00e9 \u00e0 \u00e9tablir des relations solides avec les clients et les membres de l&rsquo;\u00e9quipe\u00a0\u00a0\u00a0 Empathie et \u00e9coute active.<br>Qualifications<br>\u00a0 Dipl\u00f4me en commerce, en gestion, ou dans un domaine connexe.<br>\u00a0 Exp\u00e9rience pr\u00e9alable en tant que conseiller en assurance vie ou dans un r\u00f4le similaire.<br>\u00a0 Exp\u00e9rience en gestion d&rsquo;\u00e9quipe est un atout.<br>Attitudes :<br>\u00a0 Bonne prise de contact ,<br>\u00a0 Dynamisme ,<br>\u00a0 Esprit de synth\u00e8se et d&rsquo;analyse ;<br>\u00a0 Bonne pr\u00e9sentation ,<br>\u00a0 Gestion du stress et de ses \u00e9motions ,<br>\u00a0 Sens \u00e9thique, int\u00e9grit\u00e9 et probit\u00e9 ,<br>\u00a0 Forte r\u00e9sistance au stress ;<\/p>\n\n\n\n<p><strong>Dossier de candidature :<\/strong><br>Le dossier de candidature, constitu\u00e9 d&rsquo;une lettre de motivation adress\u00e9e au Directeur G\u00e9n\u00e9ral, d&rsquo;un CV d\u00e9taill\u00e9 avec contacts t\u00e9l\u00e9phoniques et adresse e-mail et de tout \u00e9l\u00e9ment de qualification attestant de la comp\u00e9tence dans le domaine (dipl\u00f4me, certificat de travail, certificat de formation)&#8230;,&nbsp;devra \u00eatre d\u00e9pos\u00e9 exclusivement \u00e0 l&rsquo;adresse e-mail&nbsp;chanasvie@ chanasassurancesvie.com&nbsp;avec objet \u00ab CANDIDATURE AU POSTE DE&nbsp;INSPECTEUR&nbsp;COMMERCIAL))&nbsp;au plus tard le 28 juin 2024<\/p>\n\n\n\n<p><em>Chanas Assurances<\/em><\/p>\n\n\n\n<p><em>www.chanasassurances.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via chanasvie@ chanasassurancesvie.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[136],"contrats":[236],"diplomes":[212],"louma_meta":{"emploi_title":"INSPECTEUR Commercial","emplois_employeur":20976,"emplois_date_publication":"2024-06-27","emplois_heure_publication":"12:41","emplois_date_cloture":"2024-06-28","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"chanasvie@ chanasassurancesvie.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48294"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48294"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/20977"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48294"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48294"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48294"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}