{"id":48285,"date":"2024-06-25T13:10:00","date_gmt":"2024-06-25T11:10:00","guid":{"rendered":""},"modified":"2024-06-25T15:33:19","modified_gmt":"2024-06-25T13:33:19","slug":"barman-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/barman-3\/","title":{"rendered":"BARMAN"},"content":{"rendered":"<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>R&ocirc;le :&nbsp; &nbsp; BARMAN<\/div>\n<div>Lieu du travail : BANA- Cameroun&nbsp;&nbsp;<\/div>\n<div>Conditions : Temps-plein&nbsp;&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>CONTEXTE&nbsp;<\/div>\n<div>L&rsquo;h&ocirc;tel LA VALLEE DE BANA recrute un BARMAN, Le Barman est celui qui tient le bar de l&rsquo;&eacute;tablissement. Il &eacute;labore des cocktails, imagine de nouvelles cr&eacute;ations, fid&eacute;liser ses clients et cr&eacute;&eacute; une atmosph&egrave;re chaleureuse adapt&eacute;e &agrave; l&rsquo;&eacute;tablissement et contribue ainsi &agrave; sa renomm&eacute;e.&nbsp;<\/div>\n<div>Le Barman v&eacute;hicule l&rsquo;image de l&rsquo;h&ocirc;tel par son attitude exemplaire, son accueil chaleureux et convivial, son professionnalisme et sa disponibilit&eacute;.<\/div>\n<div>&nbsp;<\/div>\n<div>TACHES ET RESPONSABILITES\u202f:&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Sous la supervision du Responsable Mythe :&nbsp;&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;TACHES ET RESPONSABILITES :<\/div>\n<div>&nbsp;<\/div>\n<div>Il\/Elle est charg&eacute; (e)&nbsp; de :<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Approvisionner en produits le bar et ranger<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Suivre l&rsquo;&eacute;tat des stocks, identifier les besoins en approvisionnement et &eacute;tablir les r&eacute;quisitions<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Effecteur l&rsquo;inventaire des besoins journaliers<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>R&eacute;ceptionner les produits et en effectuer le stockage<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>R&eacute;aliser la mise en place des produits et mat&eacute;riels selon les proc&eacute;dures de travail &eacute;tablies<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Accueillir le client et pr&eacute;parer les boissons selon les fiches techniques &eacute;tablies<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Servir les clients au comptoir, en salle, en terrasse \/ lounge<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Proc&eacute;der &agrave; la facturation et &agrave; l&rsquo;encaissement des consommations<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>D&eacute;barrasser les tables, le comptoir, et effectuer l&rsquo;entretien et le nettoyage du bar et salle<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Effectuer la plonge de la verrerie<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Renseignement du client sur les activit&eacute;s de l&rsquo;&eacute;tablissement<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>Appliquer la politique commerciale de l&rsquo;&eacute;tablissement<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>S&rsquo;enqu&eacute;rir de la satisfaction des clients<\/div>\n<div>&#8211;<span style=\"white-space: pre;\"> <\/span>D&eacute;tecter les comportements &agrave; risques et informer son sup&eacute;rieur ou ses coll&egrave;gues<\/div>\n<div>&nbsp;<\/div>\n<div>PROFIL RECHERCHE\u202f:&nbsp;<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Minimum CAP\/ BEPC<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Qualit&eacute;s requises\u202f:&nbsp;<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Excellentes capacit&eacute;s de relations personnelles<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Excellent relationnel<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Autorit&eacute; personnelle et diplomatie.<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Habilet&eacute; et rapidit&eacute; d&rsquo;ex&eacute;cution.<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Esprit d&rsquo;&eacute;quipe.<\/div>\n<div>&bull;<span style=\"white-space: pre;\"> <\/span>Bonne m&eacute;moire.&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Vous pouvez faire acte de candidature en envoyant votre dossier (CV, lettre de motivation ) &agrave; l&rsquo;adresse suivante : recrutement@iccnet.cm au plus tard le 05\/07\/2024 ins&eacute;rant comme objet : BARMAN<\/div>\n<div>&nbsp;<\/div>\n<div>\u202f&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; R&ocirc;le :&nbsp; &nbsp; BARMAN Lieu du travail : BANA- Cameroun&nbsp;&nbsp; Conditions : Temps-plein&nbsp;&nbsp; &nbsp; CONTEXTE&nbsp; L&rsquo;h&ocirc;tel LA VALLEE DE BANA recrute un BARMAN,&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[4027],"tags":[],"villes":[3457],"contrats":[148],"diplomes":[156],"louma_meta":{"emploi_title":"BARMAN","emplois_employeur":19719,"emplois_date_publication":"2024-06-25","emplois_heure_publication":"","emplois_date_cloture":"2024-07-05","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@iccnet.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48285"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48285"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/19737"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48285"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48285"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48285"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}