{"id":48008,"date":"2024-06-06T11:11:37","date_gmt":"2024-06-06T09:11:37","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=48008"},"modified":"2024-06-06T11:11:40","modified_gmt":"2024-06-06T09:11:40","slug":"vendeur-euse-en-magasin","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/vendeur-euse-en-magasin\/","title":{"rendered":"VENDEUR (EUSE) EN MAGASIN"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Une entreprise commerciale bas\u00e9e \u00e0 Yaound\u00e9 recherche pour le renforcement de son effectif&nbsp;&nbsp;un(e) Vendeur (e) motiv\u00e9 (e) et ayant de forte capacit\u00e9 d\u2019adaptation.&nbsp;Poste ouvert en urgence. Le d\u00e9pouillement se fera au fur et \u00e0 mesure de la r\u00e9ception des candidatures.<\/h3>\n\n\n\n<p>\u00d8&nbsp;&nbsp;<strong><em>Les principales missions&nbsp;:<\/em><\/strong><\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Accueillir, orienter et conseiller les clients d\u00e8s leur entr\u00e9e dans le point de vente ;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Veiller en permanence \u00e0 l\u2019accroissement de l\u2019effectif de la client\u00e8le ;<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&#038;client=ca-pub-8127528471213975&#038;output=html&#038;h=280&#038;adk=426197639&#038;adf=2326235259&#038;pi=t.aa~a.3706345623~i.10~rp.4&#038;w=722&#038;abgtt=3&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1717664726&#038;num_ads=1&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=1921297977&#038;ad_type=text_image&#038;format=722&#215;280&#038;url=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F27966%2Favis-de-recrutement-vendeur-euse-en-magasin-at-entreprise-de-la-place&#038;fwr=0&#038;pra=3&#038;rh=181&#038;rw=722&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiOC4wLjAiLCJ4ODYiLCIiLCIxMjUuMC42NDIyLjE0MiIsbnVsbCwwLG51bGwsIjY0IixbWyJHb29nbGUgQ2hyb21lIiwiMTI1LjAuNjQyMi4xNDIiXSxbIkNocm9taXVtIiwiMTI1LjAuNjQyMi4xNDIiXSxbIk5vdC5BL0JyYW5kIiwiMjQuMC4wLjAiXV0sMF0.&#038;dt=1717664725437&#038;bpp=3&#038;bdt=2381&#038;idt=-M&#038;shv=r20240604&#038;mjsv=m202406030101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3Da5aa87fa38aba6d1-228197773ae00024%3AT%3D1689062877%3ART%3D1717664550%3AS%3DALNI_MYckMmVo2Vfswn95MHPiBhd5UjiAQ&#038;gpic=UID%3D00000c68629dfc2c%3AT%3D1689062877%3ART%3D1717664550%3AS%3DALNI_MZDFyoF212apRPpMbleAC7ctF2XXA&#038;eo_id_str=ID%3D3a28f95a7d6a69b8%3AT%3D1706630356%3ART%3D1717664550%3AS%3DAA-Afjb1UvVEMQvUXZIfIVO0mC3X&#038;prev_fmts=752&#215;280%2C722x433%2C0x0%2C314x250&#038;nras=2&#038;correlator=4111943312925&#038;frm=20&#038;pv=1&#038;ga_vid=701105570.1717664724&#038;ga_sid=1717664724&#038;ga_hid=1100036263&#038;ga_fc=0&#038;u_tz=120&#038;u_his=11&#038;u_h=768&#038;u_w=1366&#038;u_ah=728&#038;u_aw=1366&#038;u_cd=24&#038;u_sd=1&#038;dmc=4&#038;adx=142&#038;ady=805&#038;biw=1349&#038;bih=607&#038;scr_x=0&#038;scr_y=0&#038;eid=44759876%2C44759927%2C44759842%2C31084023%2C95334525%2C95334565%2C95334572%2C95334053%2C95334156%2C31078663%2C31078665%2C31078668%2C31078670&#038;oid=2&#038;pvsid=1807438387596117&#038;tmod=994698784&#038;uas=0&#038;nvt=1&#038;fc=384&#038;brdim=0%2C0%2C0%2C0%2C1366%2C0%2C1366%2C728%2C1366%2C607&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1&#038;td=1&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;ifi=5&#038;uci=a!5&#038;btvi=3&#038;fsb=1&#038;dtd=623<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Assurer le suivi et la fid\u00e9lisation de la client\u00e8le ;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Veiller \u00e0 la mise \u00e0 jours des documents mis \u00e0 votre disposition ;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Participer aux publications et ventes sur les diff\u00e9rents r\u00e9seaux sociaux.<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Gestion des stocks\u2026<\/p>\n\n\n\n<p>\u00d8&nbsp;&nbsp;<strong><em>Comp\u00e9tences et qualit\u00e9s&nbsp;:<\/em><\/strong><\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Minimum bac +2 en action commerciale, commerce international, communication d\u2019entreprise, gestion d\u2019entreprise, marketing ou dipl\u00f4me \u00e9quivalent<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Une exp\u00e9rience en pr\u00eat \u00e0 porter et en animation des ventes sur r\u00e9seaux sociaux&nbsp;&nbsp;sera un atout<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00catre \u00e2g\u00e9(e) de 28 ans minimum&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Avoir une aisance communicationnelle&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Savoir convaincre&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Forte r\u00e9sistance au stress et \u00e0 la pression&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Bonne maitrise de l\u2019outil informatique (le pack Office)&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Capacit\u00e9 de travailler en \u00e9quipe&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ma\u00eetrise des r\u00e9seaux sociaux&nbsp;;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00catre bilingue<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Disponibilit\u00e9 imm\u00e9diate.<\/p>\n\n\n\n<p>QUALITES<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Tact, politesse&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sens de l\u2019\u00e9coute,<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Sens esth\u00e9tique d\u00e9velopp\u00e9&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Pr\u00e9sentation soign\u00e9e&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Capacit\u00e9s d\u2019expression orale&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Bonne r\u00e9sistance physique du stress<\/p>\n\n\n\n<p><strong>Comment postuler&nbsp;:<\/strong><\/p>\n\n\n\n<p>&nbsp;CV et lettre de motivation \u00e0 l\u2019adresse&nbsp;<a href=\"mailto:gn24careers@gmail.com\">gn24careers@gmail.com<\/a>&nbsp;&nbsp;avec en objet la mention&nbsp;<strong>VENDEUR(EUSE) EN MAGASIN<\/strong><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>D\u00e9lai&nbsp;: 11 juin&nbsp;&nbsp;2024 \u00e0 20H<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via gn24careers@gmail.com\u00a0<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,24],"tags":[],"villes":[136],"contrats":[148],"diplomes":[248],"louma_meta":{"emploi_title":"VENDEUR (EUSE) EN MAGASIN","emplois_employeur":3046,"emplois_date_publication":"2024-06-06","emplois_heure_publication":"10:11","emplois_date_cloture":"2024-06-11","emplois_heure_cloture":"17:00","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"gn24careers@gmail.com\u00a0"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48008"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=48008"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/48008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=48008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=48008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=48008"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=48008"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=48008"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=48008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}