{"id":47805,"date":"2024-05-21T11:19:19","date_gmt":"2024-05-21T09:19:19","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=47805"},"modified":"2024-05-21T11:19:23","modified_gmt":"2024-05-21T09:19:23","slug":"meal-lead","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/meal-lead\/","title":{"rendered":"MEAL Lead"},"content":{"rendered":"\n<p>Lieu de travail Bangui, RCA<br>Type de contrat Expatri\u00e9<br>Dur\u00e9e du contrat 24 mois (renouvelable)<br>Date de d\u00e9but du contrat 01.07.2024<br><strong>FAIRMED, ONG internationale<\/strong>&nbsp;bas\u00e9e en Suisse. Notre vision est que personne ne doit ni<br>souffrir ni mourir d\u2019une maladie curable. Nous voulons que toutes les personnes aient un acc\u00e8s<br>\u00e9quitable \u00e0 la pr\u00e9vention et \u00e0 des soins de sant\u00e9 acceptables, d\u2019une qualit\u00e9 satisfaisante et d\u2019un<br>co\u00fbt abordable et b\u00e9n\u00e9ficient d\u2019un environnement sain et marqu\u00e9 d\u2019\u00e9quit\u00e9. Afin de briser le<br>cercle vicieux de la pauvret\u00e9 et de la maladie, nous permettons aux plus d\u00e9munis en Afrique<br>(bassin du Congo) et dans le sous-continent indien (du N\u00e9pal au Sri Lanka), d\u2019avoir l\u2019\u00e9galit\u00e9 des<br>chances en mati\u00e8re de sant\u00e9. Nous contribuons \u00e0 l\u2019all\u00e9gement du fardeau que repr\u00e9sentent les<br>maladies li\u00e9es \u00e0 la pauvret\u00e9, notamment les maladies tropicales n\u00e9glig\u00e9es.<\/p>\n\n\n\n<p><strong>Responsabilit\u00e9s et t\u00e2ches sp\u00e9cifiques:&nbsp;<\/strong>Sous la supervision du coordonnateur pays, la\/le MEAL<br>Lead est charg\u00e9 de concevoir, d\u00e9velopper, coordonner et mettre en \u0153uvre le syst\u00e8me de suivi \u2013<\/p>\n\n\n\n<p><br>\u00e9valuation-apprentissage-redevabilit\u00e9 de tous les projets ex\u00e9cut\u00e9s par la Fondation FAIRMED en<br>RCA. Sp\u00e9cifiquement, elle\/il aura pour responsabilit\u00e9s de:<\/p>\n\n\n\n<p><strong>Responsabilit\u00e9 n\u00b01: Suivi , Evaluation<\/strong><br>&#8211; Coordonner l\u2019\u00e9laboration des outils et strat\u00e9gies de recueil des donn\u00e9es requises<br>pour le calcul des indicateurs de performance des projets et des cadres logiques<br>en lien avec le coordonnateur de programme ;<br>&#8211; Organiser et superviser la collecte r\u00e9guli\u00e8re des donn\u00e9es requises pour le calcul<br>des indicateurs de performance du projet dans la r\u00e9gion d\u2019affectation ;<br>&#8211; Assurer la qualit\u00e9 des donn\u00e9es collect\u00e9es et rapport\u00e9es des projets de tout le<br>programme RCA ;<br>&#8211; Analyser les donn\u00e9es et d\u00e9gager les tendances et les changements induits si<br>possible ;<br>&#8211; Promouvoir un syst\u00e8me efficace et coh\u00e9rent d\u2019analyse, de diss\u00e9mination et de<br>gestion de l\u2019information permettant l\u2019utilisation efficiente des r\u00e9sultats pour la<br>prise de d\u00e9cision fond\u00e9e sur l\u2019\u00e9vidence, \u00e0 tous les niveaux d\u2019intervention ;<br>&#8211; Fournir un appui technique pour le renforcement de capacit\u00e9s et de formation sur<br>les aspects de suivi\/\u00e9valuation du programmes aux diff\u00e9rents collaborateurs et<br>partenaires au niveau national, r\u00e9gional et district ;<br>&#8211; Fournir les informations requises et contribuer \u00e0 l\u2019\u00e9laboration des rapports<br>d\u2019activit\u00e9s p\u00e9riodiques de projets ;<br>&#8211; Assurer la mise \u00e0 jour r\u00e9guli\u00e8re de la base de donn\u00e9es nationale dans le logiciel<br>Logalto ;<br>&#8211; Participer \u00e0 la supervision r\u00e9guli\u00e8re des activit\u00e9s sur le terrain pour la triangulation<br>des donn\u00e9es collect\u00e9es et l\u2019appui des coordonnateurs de projets;<\/p>\n\n\n\n<p><br>&#8211; Veiller \u00e0 l\u2019archivage de tous les outils et documents pertinents produits paf l\u2019unit\u00e9<br>MEAL ;<br>&#8211; Mettre en place un syst\u00e8me de collecte des donn\u00e9es des projets FAIRMED RCA<br>en am\u00e9liorant la qualit\u00e9 des outils primaires utilis\u00e9es dans les formations<br>sanitaires et en internes :<br><strong>Responsabilit\u00e9 N\u00b02 : Redevabilit\u00e9<\/strong><br>&#8211; Veiller aux respect des exigences minimales en mati\u00e8re de redevabilit\u00e9 (partage<br>d\u2019information, participation et m\u00e9canismes de r\u00e9troaction et de retour d\u2019information)<br>dans tous les projets ;<br>&#8211; Soutenir le d\u00e9veloppement et la mise en \u0153uvre de m\u00e9canismes de redevabilit\u00e9<br>(m\u00e9canismes de plaintes\/feedback) appropri\u00e9s dans le cadre du syst\u00e8me global ;<br>&#8211; Soutenir le renforcement des capacit\u00e9s du personnel et des partenaires dans le<br>domaine de la redevabilit\u00e9 ;<br>&#8211; G\u00e9rer et coordonner les bases des donn\u00e9es du m\u00e9canisme des plaintes de tous les<br>projets.<br><strong>Responsabilit\u00e9 N\u00b03 : Apprentissage<\/strong><br>&#8211; Veiller \u00e0 l\u2019assurance que l\u2019apprentissage est int\u00e9gr\u00e9 dans toutes les activit\u00e9s du<br>programme ;<br>&#8211; Participer \u00e0 l\u2019assurance que les r\u00e9sultats et les le\u00e7ons apprises par le syst\u00e8me de<br>suivi, \u00e9valuation, redevabilit\u00e9 et apprentissage sont partag\u00e9s avec les b\u00e9n\u00e9ficiaires et<\/p>\n\n\n\n<p><br>les intervenants d\u2019une mani\u00e8re significative et appropri\u00e9e ;<br>&#8211; Assurer la documentation des \u00e9tudes des cas, des exp\u00e9riences r\u00e9ussies, des le\u00e7ons<br>apprises et des meilleurs pratiques ;<br>&#8211; Appuyer l\u2019identification des besoins de formation dans ces domaines pour le<br>personnel du projet et des partenaires pour les zones de projet couverts ;<br>&#8211; Coordonner les op\u00e9rations de recherche actions et \u00e9tudes sp\u00e9ciales dans la mesure<br>du possible ;<br><strong>Responsabilit\u00e9 N\u00b04 : Contribution aux management des projets<\/strong><br>&#8211; Participer \u00e0 la planification annuelle ou pluriannuelle des projets en veillant \u00e0 la mise<br>en place d\u2019une logique d\u2019intervention coh\u00e9rente et d\u2019un mod\u00e8le logique pour tous les<br>nouveaux projets ;<br>&#8211; Coordonner les missions d\u2019\u00e9valuation \u00e0 mi-parcours \/ fin de parcours des projets ;<br>&#8211; Assurer le suivi de la mise en \u0153uvre des recommandations des supervisions et des<br>\u00e9valuations;<br>&#8211; Avoir une sensibilit\u00e9 aux th\u00e8mes transversaux et exp\u00e9rience d\u2019int\u00e9gration de ces<br>th\u00e8mes dans les programmes de d\u00e9veloppement ;<br>Avoir les capacit\u00e9s r\u00e9dactionnelles av\u00e9r\u00e9es.<br><strong>Connaissances et comp\u00e9tences techniques (essentielles)<\/strong><br>\u27a2 Avoir une exp\u00e9rience av\u00e9r\u00e9e dans la mise en \u0153uvre des projets de sant\u00e9, de lutte contre<br>les Maladies Tropicales n\u00e9glig\u00e9es et de Sant\u00e9 Maternelle et Infantile.<br>\u27a2 \u00catre capable de travailler dans une zone dont le contexte s\u00e9curitaire est volatil.<\/p>\n\n\n\n<p><br>\u27a2 Ma\u00eetrise des outils, techniques et processus de cr\u00e9ation, gestion et administration de<br>base de donn\u00e9es de sant\u00e9 sp\u00e9cifiquement pour le \u00ab tracking \u00bb des indicateurs de<br>Maladies Tropicales N\u00e9glig\u00e9es \u00e0 manifestations cutan\u00e9es, de Sant\u00e9 Maternelle et<br>Infantile et du DHIS2 ;<br>\u27a2 Comp\u00e9tence en logiciel d\u2019analyse et d\u2019outils informatiques sp\u00e9cifiquement dans les<br>paquets (SPSS, EPI info, Excel, Power Point, Access, KOBO et autres)<br>\u27a2 Bonne compr\u00e9hension des approches fond\u00e9es sur l\u2019\u00e9galit\u00e9 de genre , le d\u00e9veloppement<br>inclusif pour les personnes en situation de handicap , le Renforcement du syst\u00e8me de<br>sant\u00e9 ,l\u2019approche triple Nexus , et le d\u00e9veloppement des approches participatives<br>\u27a2 Bonne exp\u00e9rience dans la formation \/ facilitation pour une vari\u00e9t\u00e9 de groupes.<br>\u27a2 Excellentes aptitudes \u00e0 communiquer en Fran\u00e7ais, \u00e0 la fois orales et \u00e9crites ; La maitrise<br>de la langue anglaise est un ATOUT<br>\u27a2 Engagement pour la compr\u00e9hension de la vision, la mission, et les valeurs de FAIRMED;<br>\u27a2 Expertise av\u00e9r\u00e9e en gestion de Redevabilit\u00e9 (mise en place, op\u00e9rationnalisation des<br>m\u00e9canismes etc.\u2026)<br>\u27a2 Capacit\u00e9 \u00e0 se d\u00e9placer \u00e0 l\u2019int\u00e9rieur et hors du pays<br>\u27a2 Les t\u00e2ches et responsabilit\u00e9s comme \u00e9nonc\u00e9es ci-dessus ne sont pas exhaustifs et le<\/p>\n\n\n\n<p><br>d\u00e9tenteur du r\u00f4le peut \u00eatre appel\u00e9 \u00e0 effectuer des t\u00e2ches suppl\u00e9mentaires de mani\u00e8re<br>raisonnable en fonction de leur niveau de comp\u00e9tences et d\u2019exp\u00e9rience.<br><strong>Comp\u00e9tences transverses (essentielles)<\/strong><br>\u27a2 Int\u00e9grit\u00e9 personnelle et fiabilit\u00e9<br>\u27a2 Autonomie et Fort sens de l\u2019organisation,<br>\u27a2 Adaptabilit\u00e9 \/ r\u00e9activit\u00e9<br>\u27a2 Gestion des priorit\u00e9s<br>\u27a2 Communication<br>\u27a2 Esprit d\u2019\u00e9quipe<br>\u27a2 Capacit\u00e9 \u00e0 g\u00e9rer avec tacts les conflits ;<br>\u27a2 Sens de l\u2019initiative et de l\u2019anticipation<br>Exp\u00e9rience (essentiel)<br>\u27a2 Au moins 5 ans d\u2019exp\u00e9rience dans le MEAL (Suivi \u00e9valuation, redevabilit\u00e9 et<br>apprentissage)<br>\u27a2 Exp\u00e9rience av\u00e9r\u00e9e dans un environnement multiculturel<br><strong>Qualification (essentiel)<\/strong><br>\u00catre titulaire d\u2019un dipl\u00f4me universitaire (BAC +5) en statistiques, sciences sociales, gestion de<br>projet de d\u00e9veloppement, coop\u00e9ration internationale en sant\u00e9, en, o\u00f9 disciplines connexes<br>pertinentes.<br><strong>Comment postuler<\/strong><br>Toute personne int\u00e9ress\u00e9e est pri\u00e9e de transmettre son dossier (CV, lettre de motivation,<br>copies scann\u00e9es des dipl\u00f4mes et certificats de travail) par mail\u00a0jusqu\u2019 au 07.06.2024\u00a0au contact<br>suivant : infosecretariatrca@fairmed.cm<br><em>Seul les candidat(e)s pr\u00e9s\u00e9lectionn\u00e9(e)s seront contact\u00e9(e)s.<\/em><br>Candidatures f\u00e9minines fortement encourag\u00e9es. La Fondation FAIRMED applique une politique<br>de tol\u00e9rance z\u00e9ro \u00e0 l&rsquo;\u00e9gard de la fraude, de l&rsquo;exploitation sexuelle, des abus, du harc\u00e8lement<br>sexuel, de l&rsquo;abus de pouvoir et de la discrimination. C\u2019est pourquoi elle s\u2019arroge le droit<br>d\u2019enqu\u00eater sur les candidats.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via infosecretariatrca@fairmed.cm<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2986,2554],"tags":[],"villes":[4061],"contrats":[236],"diplomes":[159],"louma_meta":{"emploi_title":"MEAL Lead","emplois_employeur":5463,"emplois_date_publication":"2024-05-21","emplois_heure_publication":"10:19","emplois_date_cloture":"2024-05-31","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47805"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=47805"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5464"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=47805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=47805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=47805"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=47805"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=47805"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=47805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}