{"id":47794,"date":"2024-05-21T10:11:09","date_gmt":"2024-05-21T08:11:09","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=47794"},"modified":"2024-05-21T10:11:24","modified_gmt":"2024-05-21T08:11:24","slug":"technico-commerciale-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/technico-commerciale-2\/","title":{"rendered":"TECHNICO-COMMERCIAL(E)"},"content":{"rendered":"\n<p>BLESSING PETROLEUM S.A. est une entreprise de Droit Camerounais sp\u00e9cialis\u00e9e dans le stockage et la distribution des produits p\u00e9troliers. Dans le cadre du d\u00e9veloppement de ses activit\u00e9s, BLESSING PETROLEUM S.A. lance un appel \u00e0 candidature pour le recrutement d\u2019un (e) (01) technico-Commercial(e) dans la ville de Douala.<br><br><strong>DESCRIPTION DU POSTE<\/strong><br>En qualit\u00e9 de technico-Commercial(e) vous allez Contribuer au d\u00e9veloppement commercial de BLESSING PETROLEUM et de son chiffre d\u2019affaires en dynamisant la performance commerciale de son p\u00e9rim\u00e8tre d\u2019activit\u00e9s. Vous participerez ainsi au pilotage du segment lubrifiant \u00e0 travers l\u2019encadrement des \u00e9quipes techniques internes, des partenaires et clients dans le d\u00e9veloppement des lubrifiants tout en veillant \u00e0 la mise en place de proc\u00e9d\u00e9s et dispositifs performants destin\u00e9s \u00e0 assurer l\u2019atteinte des objectifs de vente et de performance de ce segment. Vous r\u00e9pondrez \u00e9galement aux demandes sp\u00e9cifiques des clients et des orientations strat\u00e9giques qui vous seront donn\u00e9es, dans le but de garantir l\u2019application des standards commerciaux en vue d\u2019une meilleure satisfaction et fid\u00e9lisation de la client\u00e8le de BLESSING PETROLEUM.<br><br>MISSIONS<br><br>Plac\u00e9(e) sous la supervision du Directeur Commercial, vos principales missions sont les suivantes. :<br>\u2022&nbsp;&nbsp;&nbsp; D\u00e9velopper le portefeuille du segment lubrifiants en prospectant de nouveaux clients et en&nbsp;&nbsp;&nbsp; fid\u00e9lisant ceux existants ;<\/p>\n\n\n\n<p><br>\u2022\u00a0\u00a0\u00a0 Orienter et conseiller les clients sur les lubrifiants propos\u00e9s par BLESSING PETROLEUM afin de faciliter la compr\u00e9hension de leurs besoins ;<br>\u2022\u00a0\u00a0\u00a0 Assurer l\u2019assistance technique, la promotion technique, la formation, le recyclage technique des forces de vente, partenaires sur les lubrifiants et sp\u00e9cialit\u00e9s propos\u00e9es par BLESSING PETROLEUM ;<br>\u2022\u00a0\u00a0\u00a0 Concevoir et d\u00e9velopper des strat\u00e9gies de vente lubrifiants sur l\u2019ensemble du r\u00e9seau stations- services et aupr\u00e8s des clients industriels, en assurer la veille concurrentielle ;<br>\u2022\u00a0\u00a0\u00a0 Elaborer des pr\u00e9conisations de lubrification et des plans de graissage aupr\u00e8s des clients, analyser et d\u00e9velopper l&rsquo;offre d&rsquo;entretien automobile en station-service ;<br>\u2022\u00a0\u00a0\u00a0 Participer au bon d\u00e9roulement des approvisionnements en lubrifiants ;<br>\u2022\u00a0\u00a0\u00a0 R\u00e9diger les proc\u00e9dures pour l&rsquo;activit\u00e9 Lubrifiants ;<br>\u2022\u00a0\u00a0\u00a0 Participer \u00e0 l&rsquo;anticipation des besoins et des \u00e9volutions du march\u00e9 des lubrifiants et proposer des strat\u00e9gies d\u2019am\u00e9lioration ;<br>\u2022\u00a0\u00a0\u00a0 R\u00e9aliser des \u00e9tudes de rentabilit\u00e9 et des revues des contrats p\u00e9riodiques ;<br>\u2022\u00a0\u00a0\u00a0 R\u00e9aliser les objectifs de vente fix\u00e9s par la hi\u00e9rarchie<br>\u2022\u00a0\u00a0\u00a0 G\u00e9rer les r\u00e9clamations des clients ;<br>\u2022\u00a0\u00a0\u00a0 Assurer le suivi des commandes de la livraison \u00e0 la facturation<br>\u2022\u00a0\u00a0\u00a0 Assurer le reporting de son activit\u00e9 ;<br>\u2022\u00a0\u00a0\u00a0 Veiller \u00e0 l&rsquo;application des r\u00e8gles d&rsquo;\u00e9thique professionnelle et de RSE.<\/p>\n\n\n\n<p><strong>PROFIL<\/strong><\/p>\n\n\n\n<p><strong>Qualifications exig\u00e9es :<\/strong><br>\u2022&nbsp;&nbsp;&nbsp; Dipl\u00f4me d\u2019Ing\u00e9nieur ou \u00e9quivalent en G\u00e9nie m\u00e9canique, G\u00e9nie industriel, Maintenance Industrielle avec une formation dans la lubrification (id\u00e9alement)<br>\u2022&nbsp;&nbsp;&nbsp; Excellentes capacit\u00e9s de n\u00e9gociation et de vente<br>\u2022&nbsp;&nbsp;&nbsp; \u00catre \u00e2g\u00e9(e) de 40 ans au plus<br>\u2022&nbsp;&nbsp;&nbsp; Bonne maitrise du pack Microsoft, notamment d\u2019Excel<br>\u2022&nbsp;&nbsp;&nbsp; Excellente connaissance des lubrifiants et processus associ\u00e9s<\/p>\n\n\n\n<p><br>\u2022\u00a0\u00a0\u00a0 Comp\u00e9tence en m\u00e9canique, maintenance industrielle et automobile<br>\u2022\u00a0\u00a0\u00a0 Cr\u00e9ativit\u00e9 et habilet\u00e9 manuelle<br>\u2022\u00a0\u00a0\u00a0 Excellente pratique du Fran\u00e7ais et Anglais courant<br>\u2022\u00a0\u00a0\u00a0 Exp\u00e9rience professionnelle r\u00e9ussie d\u2019au moins 05 ans \u00e0 un poste similaire ou dans une entreprise de distribution des produits p\u00e9troliers ou de lubrifiants<br>\u2022\u00a0\u00a0\u00a0 Permis de conduire B valide<br><strong>Qualifications souhait\u00e9es :<\/strong><br>\u2022\u00a0\u00a0\u00a0 R\u00e9daction des proc\u00e9dures techniques, r\u00e9alisation d\u2019audit techniques<br>\u2022\u00a0\u00a0\u00a0 Bonne maitrise de la l\u00e9gislation en vigueur en relation avec l\u2019activit\u00e9<br>\u2022\u00a0\u00a0\u00a0 Elaboration et management d\u2019un budget op\u00e9rationnel<br>\u2022\u00a0\u00a0\u00a0 Analyse commerciale et r\u00e9alisation d\u2019\u00e9tudes de rentabilit\u00e9<br>\u2022\u00a0\u00a0\u00a0 Management de Projets<br>\u2022\u00a0\u00a0\u00a0 Exp\u00e9rience r\u00e9ussie dans la formation et l\u2019encadrement des \u00e9quipes<br>Savoirs :<br>\u2022\u00a0\u00a0\u00a0 Techniques de vente et de marketing<br>\u2022\u00a0\u00a0\u00a0 M\u00e9thode et techniques de recouvrement des cr\u00e9ances<br>\u2022\u00a0\u00a0\u00a0 M\u00e9canique automobile et industrielle, lubrifiants et proc\u00e9d\u00e9s connexes<\/p>\n\n\n\n<p><br>\u2022\u00a0\u00a0\u00a0 R\u00e8gles de Qualit\u00e9, Hygi\u00e8ne, s\u00e9curit\u00e9 et environnement<br>Savoir-faire :<br>\u2022\u00a0\u00a0\u00a0 Techniques de communication et de management<br>\u2022\u00a0\u00a0\u00a0 Maitrise des techniques de vente et de n\u00e9gociation commerciales<br>\u2022\u00a0\u00a0\u00a0 Bonne communication \u00e9crite et orale\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<br>\u2022\u00a0\u00a0\u00a0 Analyse du portefeuille et gestion des comptes clients<br>\u2022\u00a0\u00a0\u00a0 Organisation et planification des activit\u00e9s<br>Savoir-\u00eatre :<br>\u2022\u00a0\u00a0\u00a0 Force de conviction, temp\u00e9rament commercial et esprit de conqu\u00eate\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<br>\u2022\u00a0\u00a0\u00a0 Ecoute, aisance relationnelle, curiosit\u00e9 et ouverture d\u2019esprit<br>\u2022\u00a0\u00a0\u00a0 Culte de l\u2019excellence et orientation r\u00e9sultats<br>\u2022\u00a0\u00a0\u00a0 Bonne capacit\u00e9 de travail en \u00e9quipe, d\u2019animation et de motivation\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<br>\u2022\u00a0\u00a0\u00a0 Disponibilit\u00e9, r\u00e9activit\u00e9 et dynamisme<\/p>\n\n\n\n<p><strong>CONSTITUTION DU DOSSIER DE CANDIDATURE<\/strong><br>\u2022&nbsp;&nbsp;&nbsp; 01 lettre de motivation adress\u00e9e \u00e0 Madame le Directeur G\u00e9n\u00e9ral de BLESSING PETROLEUM S.A. avec pour objet \u00ab Recrutement d\u2019un(e) technico-Commercial(e) dans la ville de Douala \u00bb.<br>\u2022&nbsp;&nbsp;&nbsp; 01 CV actualis\u00e9 avec demie-carte photo, Noms et contacts de 01 \u00e0 02 r\u00e9f\u00e9rences professionnelles<br>\u2022&nbsp;&nbsp;&nbsp; 01 photocopie de la carte nationale d\u2019identit\u00e9 et du dipl\u00f4me le plus \u00e9lev\u00e9<\/p>\n\n\n\n<p><strong>RECEVABILITE DES DOSSIER<\/strong><br>Par email:<br>recrutement.rh@blessingpetroleum.net ou d\u00e9pos\u00e9s \u00e0 la r\u00e9ception de notre Si\u00e8ge.<br>&nbsp;&nbsp; &nbsp;<br><strong>DATE LIMITE :&nbsp;&nbsp;<\/strong>24 Mai 2024&nbsp; \u00e0 18h<br>&nbsp;&nbsp; &nbsp;<br><strong>AUTRES CRITERES<\/strong><br>Seul(e)s les candidat(e)s retenu(e)s seront individuellement contact\u00e9(e)s.<\/p>\n\n\n\n<p><em>Soci\u00e9t\u00e9 Anonyme&nbsp; &#8211; BLESSING PEACE Buildng. Akwa. Rue Boue Lapeyr\u00e8re B.P: 5405 Dia &#8211; CMR T\u00e9t: +237 655 55 01 55 1 4237 233 42 50 71 &#8211; Fax *237 23342 50 72 RC: Dia,oo\u0153\/B\/1802- No cont, M 1109000293558<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement.rh@blessingpetroleum.net<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2630],"tags":[],"villes":[135],"contrats":[148],"diplomes":[160],"louma_meta":{"emploi_title":"TECHNICO-COMMERCIAL(E)","emplois_employeur":11674,"emplois_date_publication":"2024-05-21","emplois_heure_publication":"09:10","emplois_date_cloture":"2024-05-24","emplois_heure_cloture":"18:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement.rh@blessingpetroleum.net"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47794"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=47794"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/11675"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=47794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=47794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=47794"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=47794"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=47794"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=47794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}