{"id":47558,"date":"2024-05-07T11:18:16","date_gmt":"2024-05-07T09:18:16","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=47558"},"modified":"2024-05-07T11:18:20","modified_gmt":"2024-05-07T09:18:20","slug":"responsable-de-secteur-produits-frais-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/responsable-de-secteur-produits-frais-h-f\/","title":{"rendered":"RESPONSABLE DE SECTEUR Produits Frais H\/F"},"content":{"rendered":"\n<p>Commerce &#8211; Wholesale\/ Retail \/ E-Commerce<br>Nombre de postes vacants<br><br>1<br><br>Type d&#8217;emploi<br><br>\u00c0 temps plein<br><br>Responsabilit\u00e9s<br><br><strong>Missions du poste:<\/strong><br><br>Piloter les activit\u00e9s des rayons Produits Frais;<br><br>Coordonner les achats des produits frais traditionnels pour la ville de Douala;<br><br>G\u00e9rer la fabrication, les ventes, les r\u00e9sultats en assurant l\u2019atteinte des objectifs qu\u2019il contribue \u00e0 d\u00e9finir avec son Directeur dans le respect des politiques de l\u2019enseigne ;<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&#038;client=ca-pub-8127528471213975&#038;output=html&#038;h=280&#038;adk=2276785327&#038;adf=319012167&#038;pi=t.aa~a.4269927312~i.28~rp.1&#038;w=722&#038;abgtt=3&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1715073358&#038;num_ads=1&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=1921297977&#038;ad_type=text_image&#038;format=722&#215;280&#038;url=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F27491%2Favis-de-recrutement-responsable-de-secteur-produits-frais-hf-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fwr=0&#038;pra=3&#038;rh=181&#038;rw=722&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiOC4wLjAiLCJ4ODYiLCIiLCIxMjQuMC42MzY3LjExOSIsbnVsbCwwLG51bGwsIjY0IixbWyJDaHJvbWl1bSIsIjEyNC4wLjYzNjcuMTE5Il0sWyJHb29nbGUgQ2hyb21lIiwiMTI0LjAuNjM2Ny4xMTkiXSxbIk5vdC1BLkJyYW5kIiwiOTkuMC4wLjAiXV0sMF0.&#038;dt=1715073357871&#038;bpp=4&#038;bdt=1369&#038;idt=-M&#038;shv=r20240502&#038;mjsv=m202405020101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3Da5aa87fa38aba6d1-228197773ae00024%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MYckMmVo2Vfswn95MHPiBhd5UjiAQ&#038;gpic=UID%3D00000c68629dfc2c%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MZDFyoF212apRPpMbleAC7ctF2XXA&#038;eo_id_str=ID%3D3a28f95a7d6a69b8%3AT%3D1706630356%3ART%3D1715073177%3AS%3DAA-Afjb1UvVEMQvUXZIfIVO0mC3X&#038;prev_fmts=752&#215;280%2C314x250%2C0x0&#038;nras=2&#038;correlator=4371709292074&#038;frm=20&#038;pv=1&#038;ga_vid=525080555.1715073357&#038;ga_sid=1715073357&#038;ga_hid=1254373077&#038;ga_fc=0&#038;u_tz=120&#038;u_his=1&#038;u_h=768&#038;u_w=1366&#038;u_ah=728&#038;u_aw=1366&#038;u_cd=24&#038;u_sd=1&#038;dmc=4&#038;adx=142&#038;ady=1256&#038;biw=1349&#038;bih=607&#038;scr_x=0&#038;scr_y=0&#038;eid=44759876%2C44759927%2C44759842%2C95331982%2C95329829%2C95331042%2C31078663%2C31078665%2C31078668%2C31078670&#038;oid=2&#038;pvsid=3085043427578308&#038;tmod=3008561&#038;uas=0&#038;nvt=1&#038;ref=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F23163%2Favis-de-recrutement-11-postes-disponibles-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fc=384&#038;brdim=0%2C0%2C0%2C0%2C1366%2C0%2C1366%2C728%2C1366%2C607&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1&#038;td=1&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;ifi=5&#038;uci=a!5&#038;btvi=2&#038;fsb=1&#038;dtd=911<\/p>\n\n\n\n<p>Manager les \u00e9quipes en visant un haut niveau de professionnalisme, la meilleure satisfaction clients et l\u2019\u00e9panouissement des collaborateurs ;<\/p>\n\n\n\n<p>Animer et organiser la vie commerciale des rayons concern\u00e9s;<\/p>\n\n\n\n<p>Assurer la qualit\u00e9 et la conformit\u00e9 des produits mis en vente, la bonne ma\u00eetrise des marges commerciales et de l\u2019ensemble des co\u00fbts d\u2019exploitation de son secteur;<\/p>\n\n\n\n<p>Conseiller, assister, contr\u00f4ler et faire \u00e9voluer les managers m\u00e9tiers des rayons concern\u00e9s;<\/p>\n\n\n\n<p>Contribuer au respect des r\u00e8gles sociales et soci\u00e9tales de l\u2019environnement du supermarch\u00e9 et assurer l\u2019image de l\u2019enseigne;<\/p>\n\n\n\n<p>Repr\u00e9senter le Directeur de l\u2019hypermarch\u00e9 en son absence et assurer le suivi du secteur PGC et Non alimentaire en l\u2019absence de son coll\u00e8gue Responsable de ce secteur.<\/p>\n\n\n\n<p><strong>&nbsp;Activit\u00e9s du poste:<\/strong><\/p>\n\n\n\n<p>Satisfaction client (Assurer le service et la satisfaction du client est une priorit\u00e9)<\/p>\n\n\n\n<p>Assurer la qualit\u00e9 des produits, le service et la satisfaction du client est une priorit\u00e9<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&#038;client=ca-pub-8127528471213975&#038;output=html&#038;h=280&#038;adk=2276785327&#038;adf=224688394&#038;pi=t.aa~a.4269927312~i.55~rp.1&#038;w=722&#038;abgtt=3&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1715073358&#038;num_ads=1&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=1921297977&#038;ad_type=text_image&#038;format=722&#215;280&#038;url=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F27491%2Favis-de-recrutement-responsable-de-secteur-produits-frais-hf-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fwr=0&#038;pra=3&#038;rh=181&#038;rw=722&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiOC4wLjAiLCJ4ODYiLCIiLCIxMjQuMC42MzY3LjExOSIsbnVsbCwwLG51bGwsIjY0IixbWyJDaHJvbWl1bSIsIjEyNC4wLjYzNjcuMTE5Il0sWyJHb29nbGUgQ2hyb21lIiwiMTI0LjAuNjM2Ny4xMTkiXSxbIk5vdC1BLkJyYW5kIiwiOTkuMC4wLjAiXV0sMF0.&#038;dt=1715073357871&#038;bpp=3&#038;bdt=1369&#038;idt=3&#038;shv=r20240502&#038;mjsv=m202405020101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3Da5aa87fa38aba6d1-228197773ae00024%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MYckMmVo2Vfswn95MHPiBhd5UjiAQ&#038;gpic=UID%3D00000c68629dfc2c%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MZDFyoF212apRPpMbleAC7ctF2XXA&#038;eo_id_str=ID%3D3a28f95a7d6a69b8%3AT%3D1706630356%3ART%3D1715073177%3AS%3DAA-Afjb1UvVEMQvUXZIfIVO0mC3X&#038;prev_fmts=752&#215;280%2C314x250%2C0x0%2C722x280&#038;nras=3&#038;correlator=4371709292074&#038;frm=20&#038;pv=1&#038;ga_vid=525080555.1715073357&#038;ga_sid=1715073357&#038;ga_hid=1254373077&#038;ga_fc=0&#038;u_tz=120&#038;u_his=1&#038;u_h=768&#038;u_w=1366&#038;u_ah=728&#038;u_aw=1366&#038;u_cd=24&#038;u_sd=1&#038;dmc=4&#038;adx=142&#038;ady=2130&#038;biw=1349&#038;bih=607&#038;scr_x=0&#038;scr_y=0&#038;eid=44759876%2C44759927%2C44759842%2C95331982%2C95329829%2C95331042%2C31078663%2C31078665%2C31078668%2C31078670&#038;oid=2&#038;pvsid=3085043427578308&#038;tmod=3008561&#038;uas=0&#038;nvt=1&#038;ref=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F23163%2Favis-de-recrutement-11-postes-disponibles-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fc=384&#038;brdim=0%2C0%2C0%2C0%2C1366%2C0%2C1366%2C728%2C1366%2C607&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1&#038;td=1&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;ifi=6&#038;uci=a!6&#038;btvi=3&#038;fsb=1&#038;dtd=932<\/p>\n\n\n\n<p>Diffuser et expliquer les politiques commerciales en les adaptant \u00e0 son secteur et s&rsquo;assurer de leur appropriation par les Managers m\u00e9tier : plan de fabrication, implantation, assortiment, promotion, positionnement prix\u2026<\/p>\n\n\n\n<p>En collaboration avec les Managers m\u00e9tiers et son Directeur, faire \u00e9voluer l&rsquo;assortiment en fonction du march\u00e9, de la saisonnalit\u00e9, de la concurrence, de la demande de la client\u00e8le dans le respect des pr\u00e9conisations nationales ou du groupe<\/p>\n\n\n\n<p>Avoir un secteur qui relaie la politique qualit\u00e9, prix et promotionnelle de l&rsquo;enseigne;<\/p>\n\n\n\n<p>Inciter les Managers m\u00e9tier \u00e0 conna\u00eetre la client\u00e8le, la concurrence (suggestions clients, table ronde, parcours client, diagnostic marketing, \u2026) ;<\/p>\n\n\n\n<p>R\u00e9pondre aux attentes des clients en facilitant leur parcours dans le magasin<\/p>\n\n\n\n<p>Efficacit\u00e9 dans l\u2019organisation<\/p>\n\n\n\n<p>Expliquer, piloter et suivre les changements d&rsquo;organisation relatifs aux flux marchandises, flux d&rsquo;information et administratifs, \u2026. Proposer des adaptations si besoin et en assurer la p\u00e9rennit\u00e9.<\/p>\n\n\n\n<p>S&rsquo;assurer de l&rsquo;ad\u00e9quation des ressources (humaines et mat\u00e9rielles) par rapport au flux clients et aux besoins de l&rsquo;activit\u00e9 du secteur et veiller \u00e0 la bonne productivit\u00e9;<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&#038;client=ca-pub-8127528471213975&#038;output=html&#038;h=280&#038;adk=2276785327&#038;adf=2937891334&#038;pi=t.aa~a.4269927312~i.79~rp.1&#038;w=722&#038;abgtt=3&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1715073363&#038;num_ads=1&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=1921297977&#038;ad_type=text_image&#038;format=722&#215;280&#038;url=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F27491%2Favis-de-recrutement-responsable-de-secteur-produits-frais-hf-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fwr=0&#038;pra=3&#038;rh=181&#038;rw=722&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiOC4wLjAiLCJ4ODYiLCIiLCIxMjQuMC42MzY3LjExOSIsbnVsbCwwLG51bGwsIjY0IixbWyJDaHJvbWl1bSIsIjEyNC4wLjYzNjcuMTE5Il0sWyJHb29nbGUgQ2hyb21lIiwiMTI0LjAuNjM2Ny4xMTkiXSxbIk5vdC1BLkJyYW5kIiwiOTkuMC4wLjAiXV0sMF0.&#038;dt=1715073357888&#038;bpp=4&#038;bdt=1386&#038;idt=4&#038;shv=r20240502&#038;mjsv=m202405020101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3Da5aa87fa38aba6d1-228197773ae00024%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MYckMmVo2Vfswn95MHPiBhd5UjiAQ&#038;gpic=UID%3D00000c68629dfc2c%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MZDFyoF212apRPpMbleAC7ctF2XXA&#038;eo_id_str=ID%3D3a28f95a7d6a69b8%3AT%3D1706630356%3ART%3D1715073177%3AS%3DAA-Afjb1UvVEMQvUXZIfIVO0mC3X&#038;prev_fmts=752&#215;280%2C314x250%2C0x0%2C722x280%2C722x280&#038;nras=4&#038;correlator=4371709292074&#038;frm=20&#038;pv=1&#038;ga_vid=525080555.1715073357&#038;ga_sid=1715073357&#038;ga_hid=1254373077&#038;ga_fc=0&#038;u_tz=120&#038;u_his=1&#038;u_h=768&#038;u_w=1366&#038;u_ah=728&#038;u_aw=1366&#038;u_cd=24&#038;u_sd=1&#038;dmc=4&#038;adx=142&#038;ady=2470&#038;biw=1349&#038;bih=607&#038;scr_x=0&#038;scr_y=55&#038;eid=44759876%2C44759927%2C44759842%2C95331982%2C95329829%2C95331042%2C31078663%2C31078665%2C31078668%2C31078670&#038;oid=2&#038;psts=AOrYGslBAERCKvVjv3rFO73SDCkFVgcqbfgO3MGiAIIqxDWIRGF8h8mT8Wm1TMxFyvdAGsWa651TpVbLN_ZNI1bHixbSw5Q&#038;pvsid=3085043427578308&#038;tmod=3008561&#038;uas=0&#038;nvt=1&#038;ref=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F23163%2Favis-de-recrutement-11-postes-disponibles-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fc=384&#038;brdim=0%2C0%2C0%2C0%2C1366%2C0%2C1366%2C728%2C1366%2C607&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1&#038;td=1&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;ifi=7&#038;uci=a!7&#038;btvi=4&#038;fsb=1&#038;dtd=5925<\/p>\n\n\n\n<p>Savoir accompagner les managers m\u00e9tiers dans leurs propositions et solliciter l\u2019aide d\u2019experts si n\u00e9cessaire;<\/p>\n\n\n\n<p>Inciter les Managers m\u00e9tier \u00e0 rep\u00e9rer et partager les exp\u00e9riences r\u00e9ussies et les promouvoir;<\/p>\n\n\n\n<p>Organiser et animer avec les Managers m\u00e9tier des r\u00e9unions pr\u00e9paratoires et de suivi des temps forts de l&rsquo;activit\u00e9 des rayons (implantation, inventaire, saisonnalit\u00e9s, \u2026);<\/p>\n\n\n\n<p>Respecter rigoureusement les r\u00e8gles d\u2019hygi\u00e8ne personnelle (corporelles) et professionnelle (propret\u00e9 des locaux, du mat\u00e9riel et des produits, respect strict des mesures d\u2019hygi\u00e8ne, \u2026)<\/p>\n\n\n\n<p>Management<\/p>\n\n\n\n<p>Respecter et faire respecter la politique ressources humaines de l\u2019entreprise, ainsi que les politiques Anzen et Kaizen;<\/p>\n\n\n\n<p>Mettre en place et appliquer les actions en mati\u00e8re de Ressources Humaines : recrutement, formation, \u00e9valuation, relations sociales;<\/p>\n\n\n\n<p>Organiser, r\u00e9aliser le recrutement et l\u2019int\u00e9gration des nouveaux employ\u00e9s du secteur en accord avec les politiques RH.<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&#038;client=ca-pub-8127528471213975&#038;output=html&#038;h=280&#038;adk=2276785327&#038;adf=778542425&#038;pi=t.aa~a.4269927312~i.103~rp.1&#038;w=722&#038;abgtt=3&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1715073400&#038;num_ads=1&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=1921297977&#038;ad_type=text_image&#038;format=722&#215;280&#038;url=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F27491%2Favis-de-recrutement-responsable-de-secteur-produits-frais-hf-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fwr=0&#038;pra=3&#038;rh=181&#038;rw=722&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiOC4wLjAiLCJ4ODYiLCIiLCIxMjQuMC42MzY3LjExOSIsbnVsbCwwLG51bGwsIjY0IixbWyJDaHJvbWl1bSIsIjEyNC4wLjYzNjcuMTE5Il0sWyJHb29nbGUgQ2hyb21lIiwiMTI0LjAuNjM2Ny4xMTkiXSxbIk5vdC1BLkJyYW5kIiwiOTkuMC4wLjAiXV0sMF0.&#038;dt=1715073357906&#038;bpp=3&#038;bdt=1404&#038;idt=3&#038;shv=r20240502&#038;mjsv=m202405020101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3Da5aa87fa38aba6d1-228197773ae00024%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MYckMmVo2Vfswn95MHPiBhd5UjiAQ&#038;gpic=UID%3D00000c68629dfc2c%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MZDFyoF212apRPpMbleAC7ctF2XXA&#038;eo_id_str=ID%3D3a28f95a7d6a69b8%3AT%3D1706630356%3ART%3D1715073177%3AS%3DAA-Afjb1UvVEMQvUXZIfIVO0mC3X&#038;prev_fmts=752&#215;280%2C314x250%2C0x0%2C722x280%2C722x280%2C722x280&#038;nras=5&#038;correlator=4371709292074&#038;frm=20&#038;pv=1&#038;ga_vid=525080555.1715073357&#038;ga_sid=1715073357&#038;ga_hid=1254373077&#038;ga_fc=0&#038;u_tz=120&#038;u_his=1&#038;u_h=768&#038;u_w=1366&#038;u_ah=728&#038;u_aw=1366&#038;u_cd=24&#038;u_sd=1&#038;dmc=4&#038;adx=142&#038;ady=3038&#038;biw=1349&#038;bih=607&#038;scr_x=0&#038;scr_y=623&#038;eid=44759876%2C44759927%2C44759842%2C95331982%2C95329829%2C95331042%2C31078663%2C31078665%2C31078668%2C31078670&#038;oid=2&#038;psts=AOrYGslBAERCKvVjv3rFO73SDCkFVgcqbfgO3MGiAIIqxDWIRGF8h8mT8Wm1TMxFyvdAGsWa651TpVbLN_ZNI1bHixbSw5Q&#038;pvsid=3085043427578308&#038;tmod=3008561&#038;uas=3&#038;nvt=1&#038;ref=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F23163%2Favis-de-recrutement-11-postes-disponibles-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fc=384&#038;brdim=0%2C0%2C0%2C0%2C1366%2C0%2C1366%2C728%2C1366%2C607&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1&#038;td=1&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;ifi=8&#038;uci=a!8&#038;btvi=5&#038;fsb=1&#038;dtd=42981<\/p>\n\n\n\n<p>R\u00e9aliser le suivi et l\u2019\u00e9valuation de son \u00e9quipe. D\u00e9tecter les \u00e9volutifs dans le respect de la charte de gestion des carri\u00e8res.<\/p>\n\n\n\n<p>Pr\u00e9voir les formations en fonction des besoins et des priorit\u00e9s de l\u2019entit\u00e9. S\u2019assurer de leur mise en \u0153uvre dans le respect des principes d\u2019entreprise.<\/p>\n\n\n\n<p>Informer en permanence l\u2019\u00e9quipe en organisant des briefings, des r\u00e9unions sur l\u2019activit\u00e9 du secteur, magasin, les r\u00e9sultats, les valeurs de l\u2019entreprise et les commentaires clients. Favoriser l\u2019expression de chacun<\/p>\n\n\n\n<p>&nbsp;Performances \u00e9conomiques<\/p>\n\n\n\n<p>Respecter le budget allou\u00e9 au secteur (frais de personnel et frais de fonctionnement);<\/p>\n\n\n\n<p>Coordonner les n\u00e9gociations avec les fournisseurs locaux de Produits Frais;<\/p>\n\n\n\n<p>R\u00e9aliser les objectifs de CA et de marges;<\/p>\n\n\n\n<p>Contr\u00f4ler et r\u00e9duire la d\u00e9marque connue et inconnue;<\/p>\n\n\n\n<p>Suivre et analyser le tableau de bord, les diff\u00e9rents indicateurs de gestion (chiffres d\u2019affaires, marge, stocks, frais de personnel, frais g\u00e9n\u00e9raux, \u2026).<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?gdpr=0&#038;client=ca-pub-8127528471213975&#038;output=html&#038;h=280&#038;adk=2276785327&#038;adf=2514487184&#038;pi=t.aa~a.4269927312~i.130~rp.1&#038;w=722&#038;abgtt=3&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1715073401&#038;num_ads=1&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=1921297977&#038;ad_type=text_image&#038;format=722&#215;280&#038;url=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F27491%2Favis-de-recrutement-responsable-de-secteur-produits-frais-hf-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fwr=0&#038;pra=3&#038;rh=181&#038;rw=722&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiOC4wLjAiLCJ4ODYiLCIiLCIxMjQuMC42MzY3LjExOSIsbnVsbCwwLG51bGwsIjY0IixbWyJDaHJvbWl1bSIsIjEyNC4wLjYzNjcuMTE5Il0sWyJHb29nbGUgQ2hyb21lIiwiMTI0LjAuNjM2Ny4xMTkiXSxbIk5vdC1BLkJyYW5kIiwiOTkuMC4wLjAiXV0sMF0.&#038;dt=1715073357931&#038;bpp=5&#038;bdt=1429&#038;idt=5&#038;shv=r20240502&#038;mjsv=m202405020101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3Da5aa87fa38aba6d1-228197773ae00024%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MYckMmVo2Vfswn95MHPiBhd5UjiAQ&#038;gpic=UID%3D00000c68629dfc2c%3AT%3D1689062877%3ART%3D1715073177%3AS%3DALNI_MZDFyoF212apRPpMbleAC7ctF2XXA&#038;eo_id_str=ID%3D3a28f95a7d6a69b8%3AT%3D1706630356%3ART%3D1715073177%3AS%3DAA-Afjb1UvVEMQvUXZIfIVO0mC3X&#038;prev_fmts=752&#215;280%2C314x250%2C0x0%2C722x280%2C722x280%2C722x280%2C722x280&#038;nras=6&#038;correlator=4371709292074&#038;frm=20&#038;pv=1&#038;ga_vid=525080555.1715073357&#038;ga_sid=1715073357&#038;ga_hid=1254373077&#038;ga_fc=0&#038;u_tz=120&#038;u_his=1&#038;u_h=768&#038;u_w=1366&#038;u_ah=728&#038;u_aw=1366&#038;u_cd=24&#038;u_sd=1&#038;dmc=4&#038;adx=142&#038;ady=3632&#038;biw=1349&#038;bih=607&#038;scr_x=0&#038;scr_y=1210&#038;eid=44759876%2C44759927%2C44759842%2C95331982%2C95329829%2C95331042%2C31078663%2C31078665%2C31078668%2C31078670&#038;oid=2&#038;psts=AOrYGslBAERCKvVjv3rFO73SDCkFVgcqbfgO3MGiAIIqxDWIRGF8h8mT8Wm1TMxFyvdAGsWa651TpVbLN_ZNI1bHixbSw5Q&#038;pvsid=3085043427578308&#038;tmod=3008561&#038;uas=3&#038;nvt=1&#038;ref=https%3A%2F%2Fcameroun.minajobs.net%2Femplois-stage-recrutement%2F23163%2Favis-de-recrutement-11-postes-disponibles-at-hsd-melt-group-africa-consultants-rh-et-recrutement&#038;fc=384&#038;brdim=0%2C0%2C0%2C0%2C1366%2C0%2C1366%2C728%2C1366%2C607&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1&#038;td=1&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;ifi=9&#038;uci=a!9&#038;btvi=6&#038;fsb=1&#038;dtd=43834<\/p>\n\n\n\n<p>Analyser les performances du secteur, rayon par rayon (CA, marge, frais personnels,)<\/p>\n\n\n\n<p>Pr\u00e9senter un point complet sur la situation de son secteur lors d\u2019une revue de performance. D\u00e9finir les plans d\u2019action si n\u00e9cessaire.<\/p>\n\n\n\n<p>D\u00e9finir les priorit\u00e9s op\u00e9rationnelles et affecter les moyens humains, techniques n\u00e9cessaires.<\/p>\n\n\n\n<p>Appliquer et faire appliquer les proc\u00e9dures flux argent et flux marchandises pour \u00e9viter les pertes et r\u00e9duire la d\u00e9marque.<\/p>\n\n\n\n<p>Faire des pr\u00e9visions de ventes et de r\u00e9sultats en collaboration avec les Managers m\u00e9tiers et d\u00e9terminer les moyens de mise en \u0153uvre ;<\/p>\n\n\n\n<p>Faire des suggestions d\u2019am\u00e9lioration des performances \u00e9conomiques<\/p>\n\n\n\n<p>Exigences scolaires<\/p>\n\n\n\n<p>Bac + 4 en commerce ou gestion ou exp\u00e9rience \u00e9quivalente<\/p>\n\n\n\n<p>Exp\u00e9rience requise<\/p>\n\n\n\n<p>Exp\u00e9rience confirm\u00e9e dans le B to C (5 ans minimum)<\/p>\n\n\n\n<p>Exp\u00e9rience dans la gestion d\u2019\u00e9quipe (30 personnes minimum) &nbsp;<\/p>\n\n\n\n<p>Exigences suppl\u00e9mentaires<\/p>\n\n\n\n<p>Comp\u00e9tences techniques<\/p>\n\n\n\n<p>Gestion de la client\u00e8le<\/p>\n\n\n\n<p>Gestion financi\u00e8re<\/p>\n\n\n\n<p>Management d\u2019\u00e9quipe<\/p>\n\n\n\n<p>Une bonne connaissance des produits frais et de la fabrication<\/p>\n\n\n\n<p>Fran\u00e7ais\/Anglais<\/p>\n\n\n\n<p>R\u00e9mun\u00e9ration et autres avantages<\/p>\n\n\n\n<p>N\u00e9gociable<\/p>\n\n\n\n<p>Lieu de travail<\/p>\n\n\n\n<p>Douala<\/p>\n\n\n\n<p><strong>COMMENT POSTULER ?<\/strong><\/p>\n\n\n\n<p>Les candidat int\u00e9ress\u00e9s peuvent postuler via Cameroon.office@hsd-melt.com ou<br><a href=\"https:\/\/mhd.hsd-melt.com\/public-search?keyword=&amp;country_id=3\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/mhd.hsd-melt.com<\/a>&nbsp;, sp\u00e9cifier en objet \u00ab\u00a0le titre de l&rsquo;offre\u00a0\u00bb<\/p>\n\n\n\n<p>Date limite : 31 Mai 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via Cameroon.office@hsd-melt.com ou<br \/>\nhttps:\/\/mhd.hsd-melt.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[],"villes":[135],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"RESPONSABLE DE SECTEUR Produits Frais H\/F","emplois_employeur":4816,"emplois_date_publication":"2024-05-07","emplois_heure_publication":"10:18","emplois_date_cloture":"2024-05-31","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":"Cameroon.office@hsd-melt.com ou https:\/\/mhd.hsd-melt.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47558"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=47558"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/13905"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=47558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=47558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=47558"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=47558"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=47558"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=47558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}