{"id":47536,"date":"2024-05-06T11:27:28","date_gmt":"2024-05-06T09:27:28","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=47536"},"modified":"2024-05-06T11:27:32","modified_gmt":"2024-05-06T09:27:32","slug":"charge-e-de-gestion-versement","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/charge-e-de-gestion-versement\/","title":{"rendered":"CHARGE.E DE GESTION VERSEMENT"},"content":{"rendered":"\n<p><strong>Quel sera votre r\u00f4le ?<\/strong><br><br>Vous serez principalement charg\u00e9(e) de la gestion<br>des Versements du portefeuille de l\u2019Agence de Bangui et de certains dossiers<br>C2D de l\u2019Agence de Yaound\u00e9.<\/p>\n\n\n\n<p> D\u2019autres dossiers hors C2D pourraient \u00eatre ajout\u00e9s<br>\u00e0 votre portefeuille le cas \u00e9ch\u00e9ant. Vous devrez vous adapter au fait que le<\/p>\n\n\n\n<p><br>lieu des op\u00e9rations de Bangui soit distinct du site de versement \u00e0 Yaound\u00e9.<\/p>\n\n\n\n<p>De plus, vous assurerez l\u2019int\u00e9rim du charg\u00e9 des<br>Versements pour Yaound\u00e9 en cas d\u2019absence de celui-ci.<\/p>\n\n\n\n<p>De mani\u00e8re sp\u00e9cifique, vos t\u00e2ches seront les suivantes :<\/p>\n\n\n\n<p><strong>1. Gestion des Versements<\/strong><br>&#8211; V\u00e9rifier les donn\u00e9es issues du syst\u00e8me d&rsquo;informations ;<br>&#8211; Contr\u00f4ler la r\u00e9gularit\u00e9 et la conformit\u00e9 des dossiers de versement ;<br>&#8211; Contr\u00f4ler la validit\u00e9 des signatures des ordonnateurs ;<br>&#8211; Contr\u00f4ler les justificatifs (factures et d\u00e9comptes) avec une attention particuli\u00e8re sur les imp\u00f4ts et taxes ;<br>&#8211; Etablir en interne, les demandes de fixation de taux le cas \u00e9ch\u00e9ant ;<br>\u00a0Renseigner la fiche de contr\u00f4le de versement ;<br>&#8211; Saisir les donn\u00e9es dans le logiciel Versement (convention, documents contractuels, demande de versement) avec \u00e9dition de la demande de r\u00e8glement ;<br>&#8211; Etablir les ordres de virements bancaires le cas \u00e9ch\u00e9ant et adresser les lettres de confirmations de r\u00e8glement aux ordonnateurs ;<br>&#8211; Envoyer les dossiers trait\u00e9s au si\u00e8ge de l\u2019AFD \u00e0 Paris apr\u00e8s scan et enregistrement ;<br>&#8211; Classer les dossiers sous forme d\u00e9mat\u00e9rialis\u00e9e dans l\u2019arborescence de l\u2019Agence ;<br>&#8211; G\u00e9rer les rejets pour les dossiers non conformes ;<br>&#8211; R\u00e9gulariser les anomalies relev\u00e9es par le contr\u00f4le de second niveau ;<br>&#8211; Traiter les restes \u00e0 justifier et annuler les restes \u00e0 verser dans le logiciel ;<br>&#8211; Travailler en collaboration avec les diff\u00e9rents services impliqu\u00e9s dans le suivi back office des concours.<\/p>\n\n\n\n<p>2. Gestion des concours financiers<br>&#8211; Contr\u00f4ler et pr\u00e9parer les lettres de transmission des relev\u00e9s de compte aux contreparties ;<br>&#8211; Etablir les Comptes Rendus Hebdomadaires.<\/p>\n\n\n\n<p>3. Relation avec le Middle office<br>&#8211; Assurer le traitement des Restes \u00e0 Verser des projets en subvention \u00e0 Bangui.<\/p>\n\n\n\n<p><strong>4. R\u00e9alisation de l&rsquo;enqu\u00eate March\u00e9s \/<\/strong><br><strong>Empreinte France<\/strong><\/p>\n\n\n\n<p>En cas d\u2019int\u00e9rim :<br>&#8211; Contr\u00f4ler et transmettre les appels d\u2019\u00e9ch\u00e9ance aux contreparties ;<br>&#8211; Tenir et mettre \u00e0 jour le tableau de suivi des impay\u00e9s ;<br>&#8211; Relancer les contreparties sur les impay\u00e9s ;<br>&#8211; Faire office de Front Office pour r\u00e9soudre les probl\u00e8mes li\u00e9s aux impay\u00e9s des \u00e9ch\u00e9ances ;<br>&#8211; Fournir les informations n\u00e9cessaires pour l\u2019alimentation des tableaux de bord.<\/p>\n\n\n\n<p><strong>Qui recherchons nous ?<\/strong><\/p>\n\n\n\n<p><strong>1. Comp\u00e9tences<\/strong><br>recherch\u00e9es :<br>&#8211; Ma\u00eetriser l&rsquo;ensemble du processus comptable et des autres fonctions annexes<br>&#8211; Avoir une excellente maitrise des outils informatiques et d\u2019Excel en particulier.<\/p>\n\n\n\n<p><strong>2. Qualit\u00e9s humaines \/<\/strong><br><strong>relationnelles :<\/strong><br>&#8211; Aimer travailler en \u00e9quipe.<br>&#8211; Faire preuve d&rsquo;organisation, de rigueur, de polyvalence et d&rsquo;adaptabilit\u00e9.<br>&#8211; \u00catre capable de travailler dans des situations d\u2019urgence.<br>&#8211; \u00catre en capacit\u00e9 de suivre la mise \u00e0 jour de nouvelles proc\u00e9dures.<\/p>\n\n\n\n<p><strong>3. Niveau d\u2019\u00e9tudes et<\/strong><br><strong>d\u2019exp\u00e9rience :<\/strong><br>&#8211; Master II en comptabilit\u00e9 et Finances<br>&#8211; Avoir au minimum trois ann\u00e9es d\u2019exp\u00e9rience professionnelle en comptabilit\u00e9 et\/ou audit.<\/p>\n\n\n\n<p><strong>4. Langues<\/strong><br><strong>&#8211; Avoir un niveau d\u2019anglais op\u00e9rationnel.<\/strong><\/p>\n\n\n\n<p>Quelle \u00e9quipe allez-vous rejoindre ?<br>L\u2019Agence Fran\u00e7aise de D\u00e9veloppement (AFD) est un \u00e9tablissement public fran\u00e7ais qui contribue, depuis 80 ans, au d\u00e9veloppement \u00e9conomique et social, durable et partag\u00e9, des pays dans lesquels elle intervient. L\u2019AFD a un r\u00e9seau de 85 agences \u00e0 l\u2019\u00e9tranger et couvrant plus de 100 pays. Chacune de ces agences est rattach\u00e9e localement \u00e0 une Direction R\u00e9gionale ainsi qu\u2019\u00e0 un D\u00e9partement g\u00e9ographique au si\u00e8ge, charg\u00e9 de coordonner les diff\u00e9rentes \u00e9quipes d\u2019experts de Paris.<br>Vous allez rejoindre l\u2019\u00e9quipe Versement de l&rsquo;Agence AFD du Cameroun bas\u00e9e \u00e0 Yaound\u00e9 qui assure le suivi comptable des financements (pr\u00eats et subventions) octroy\u00e9s au Cameroun et \u00e0 la Centrafrique \u00e0 travers des applications qui lui sont propres.<\/p>\n\n\n\n<p><strong>Pourquoi<\/strong><br><strong>rejoindre l\u2019Agence Fran\u00e7aise de D\u00e9veloppement ?<\/strong><br>Rejoindre<br>l\u2019AFD, c\u2019est contribuer \u00e0 la construction d\u2019un monde en commun, c\u2019est la<br>mission de notre Groupe. Un monde en commun, c\u2019est un monde qui pr\u00e9serve et<br>d\u00e9fend ces cinq grands biens communs que sont la plan\u00e8te, le lien social, la<br>paix, les partenariats et la prosp\u00e9rit\u00e9 \u00e9conomique<\/p>\n\n\n\n<p><a href=\"https:\/\/afd.csod.com\/ux\/ats\/careersite\/5\/requisition\/7833\/application?c=afd&amp;8fhryptf=&amp;m=-5&amp;u=675&amp;jobboardid=0#1\" target=\"_blank\" rel=\"noreferrer noopener\">LA SOUMISSION DES DOSSIERS DE CANDIDATURES SE FAIT UNIQUEMENT SUR LE SITE WEB&nbsp;:&nbsp;<\/a><a href=\"https:\/\/afd.csod.com\/ux\/ats\/careersite\/5\/home\/requisition\/7895?c=afd\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/afd.csod.com\/ux\/ats\/careersite\/5\/home\/requisition\/7895?c=afd<\/a><\/p>\n\n\n\n<p><strong><u>Avant le 8 mai 2024.<\/u><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/afd.csod.com\/ux\/ats\/careersite\/5\/home\/requisition\/7895?c=afd<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[282,23],"tags":[],"villes":[136],"contrats":[236],"diplomes":[159],"louma_meta":{"emploi_title":"CHARGE.E DE GESTION VERSEMENT ","emplois_employeur":6721,"emplois_date_publication":"2024-05-06","emplois_heure_publication":"10:27","emplois_date_cloture":"2024-05-07","emplois_heure_cloture":"17:00","emplois_experience_min":"3","emplois_experience_max":"","emploi_email":"https:\/\/afd.csod.com\/ux\/ats\/careersite\/5\/home\/requisition\/7895?c=afd"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47536"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=47536"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/47536\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6722"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=47536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=47536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=47536"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=47536"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=47536"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=47536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}