{"id":46853,"date":"2024-03-07T10:34:18","date_gmt":"2024-03-07T09:34:18","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46853"},"modified":"2024-03-07T10:34:22","modified_gmt":"2024-03-07T09:34:22","slug":"responsable-communication","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/responsable-communication\/","title":{"rendered":"RESPONSABLE COMMUNICATION"},"content":{"rendered":"\n<p><strong>Fiche de poste<\/strong><\/p>\n\n\n\n<p><strong>\u00a0<\/strong>du Responsable de la Communication BVMAC<br>\u00a0Pilotage de la strat\u00e9gie de communication de la BVMAC;<br>\u00a0Elaboration, mise en \u0153uvre et suivi des plans d&rsquo;action des projets relatifs \u00e0 la communication de la Direction de D\u00e9veloppement;<br>\u00a0Proposition d&rsquo;une communication et des plans de communication innovants, coh\u00e9rents et align\u00e9s sur les objectifs de la Direction de D\u00e9veloppement;<br>\u00a0Cr\u00e9ation de contenus pour diff\u00e9rents canaux de communication (site web et r\u00e9seaux sociaux), mettre en place les newsletters p\u00e9riodiques;<br>\u00a0Aide \u00e0 la cr\u00e9ation de supports visuels, affiches, infographies etc.;<br>\u00a0Participation \u00e0 la production de vid\u00e9os r\u00e9capitulatives d&rsquo;\u00e9v\u00e9nements, de sensibilisation \u00e0 la culture boursi\u00e8re etc.;<br>\u00a0D\u00e9veloppement de la visibilit\u00e9 de la BVMAC dans la sous-r\u00e9gion CEMAC et \u00e0 l&rsquo;international R\u00e9daction des discours du Directeur G\u00e9n\u00e9ral et de mani\u00e8re g\u00e9n\u00e9rale ceux \u00e0 destination du public et des parties prenantes;<\/p>\n\n\n\n<p>&nbsp;Organisation des passages dans les m\u00e9dias (r\u00e9servation des espaces, r\u00e9daction des protocoles d&rsquo;interview, media training&#8230;);<br>&nbsp;Analyse des sollicitations m\u00e9diatiques de la Direction par les journalistes et proposition de recommandations et \u00e9l\u00e9ments de langage le cas \u00e9ch\u00e9ant;<br>&nbsp;Veille au respect de la charte graphique de la BVMAC sur tous les supports de communication;<br>&nbsp;Gestion de la relation avec les agences de communication;<br>&nbsp;Analyse des performances: suivi des performances des campagnes de communication et production de rapports sur les r\u00e9sultats.<br>&nbsp;Pr\u00e9paration d&rsquo;\u00e9v\u00e9nements en ligne et\/ou en pr\u00e9sentiel (retro planning, coordination intervenants, gestion des invitations, inscriptions, goodies etc.);<br>&nbsp;Plan de communication de l&rsquo;\u00e9v\u00e8nement (supports de communication, relais m\u00e9dias sociaux interne et\/ou externe);<br>&nbsp;Contr\u00f4le des pr\u00e9paratifs, mise en place et suivi du bon d\u00e9roulement des \u00e9v\u00e9nements; G\u00e9rer le retour d&rsquo;exp\u00e9rience sur mesure de la satisfaction;<br>&nbsp;Animation\/mod\u00e9ration des \u00e9v\u00e9nements (c\u00e9r\u00e9monies de premi\u00e8res cotation, panels etc.); Supervision des activit\u00e9s du community management et suivi du planning des publications; Suivi et accroissement de l&rsquo;engagement, recrutement, l&rsquo;animation et la fid\u00e9lisation de la communaut\u00e9 ;<br>Veille concurrentielle ;<br>Reporting des actions men\u00e9es;<br>&nbsp;Et encadrement des \u00e9quipes en charge de la communication.<\/p>\n\n\n\n<p><strong>Profil et comp\u00e9tences recherch\u00e9s:<\/strong><br>&nbsp;\u00catre ressortissant d&rsquo;un pays membre de la CEMAC;<br>&nbsp;Bac+4\/5 en \u00e9cole de commerce ou universit\u00e9 avec une sp\u00e9cialit\u00e9 en Communication d&rsquo;entreprise, \u00e9v\u00e9nementielle, Community management etc.;<br>&nbsp;Bonne connaissance des march\u00e9s financiers;<br>&nbsp;Ma\u00eetrise des codes et techniques du digital et des r\u00e9seaux sociaux ; Excellente communication \u00e0 l&rsquo;oral;<br>&nbsp;Capacit\u00e9 \u00e0 r\u00e9diger et relire dans un univers orient\u00e9 march\u00e9s financiers;<br>Bon esprit d&rsquo;analyse et de synth\u00e8se ;<br>Comment postuler ?<br>&nbsp; Envoyez vos CV \u00e0 l&rsquo;adresse: rh.recrutement@bvmac.cm&nbsp;Date limite: 12 mars 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via rh.recrutement@bvmac.cm<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25,24],"tags":[],"villes":[135],"contrats":[236],"diplomes":[159],"louma_meta":{"emploi_title":"RESPONSABLE COMMUNICATION","emplois_employeur":43105,"emplois_date_publication":"2024-03-07","emplois_heure_publication":"10:33","emplois_date_cloture":"2024-03-12","emplois_heure_cloture":"17:00","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"rh.recrutement@bvmac.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46853"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46853"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/43106"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46853"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46853"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46853"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}