{"id":46808,"date":"2024-03-04T16:47:05","date_gmt":"2024-03-04T15:47:05","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46808"},"modified":"2024-03-04T16:47:09","modified_gmt":"2024-03-04T15:47:09","slug":"analyste-risques-credit","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/analyste-risques-credit\/","title":{"rendered":"ANALYSTE RISQUES CREDIT"},"content":{"rendered":"\n<p>Position&nbsp;&nbsp;&nbsp; Collaborateur<br><strong>MISSION DU POSTE<\/strong><br>Participer \u00e0 la ma\u00eetrise des risques de cr\u00e9dit li\u00e9s aux financements sollicit\u00e9s par les clients de la Banque dans le respect des obligations l\u00e9gales et des int\u00e9r\u00eats de la Banque.<br><strong>ACTIVITES DU POSTE<\/strong><br>\u2022&nbsp;&nbsp;&nbsp; Effectuer la contre analyse des dossiers de cr\u00e9dits selon le sch\u00e9ma d\u00e9l\u00e9gataire en vigueur ;<br>Analyser les risques de cr\u00e9dit des clients et quantifier le risque de cr\u00e9dit (m\u00e9thodes de rating, scoring, &#8230;) ,<br>Proc\u00e9der \u00e0 la notation des entreprises \u00e0 l&rsquo;aide de l&rsquo;outil de notation groupe ;<br>\u2022&nbsp;&nbsp;&nbsp; Pr\u00e9senter la contre analyse des dossiers au comit\u00e9 des engagements de la banque ;<br>Contr\u00f4ler la compl\u00e9tude du dossier r\u00e9glementaire client ou dossier cr\u00e9dit pr\u00e9sent\u00e9 au comit\u00e9 des engagements dans le respect des d\u00e9lais de contre analyse ,<br>Mettre en forme les dossiers de cr\u00e9dits en d\u00e9l\u00e9gation Groupe et r\u00e9pondre aux compl\u00e9ments d&rsquo;informations ;<br>Analyser le contexte sectoriel et concurrentiel, les donn\u00e9es financi\u00e8res des entreprises \u00e0 l&rsquo;aide des bilans et comptes d&rsquo;exploitation<br>Rechercher toutes informations susceptibles d&rsquo;\u00e9clairer l&rsquo;\u00e9ventuel risque pris par l&rsquo; \u00e9tablissement ;<br>Contr\u00f4ler le respect des limites en vigueur (de contrepartie, sectorielle&#8230;) ,<br>Contr\u00f4ler la compl\u00e9tude des dossiers pr\u00e9sent\u00e9s au comit\u00e9 des engagements de la banque ;<br>R\u00e9aliser les contre analyses cr\u00e9dit sur la base des analyses r\u00e9alis\u00e9es par la ligne commerciale et \u00e9mettre des avis sur la validit\u00e9 des montages et des garanties.<br><strong>PROFIL DU TITULAIRE<\/strong><br>Dipl\u00f4me de l&rsquo;enseignement sup\u00e9rieur (BACC +4 minimum) ou dipl\u00f4me bancaire (ITB) , Une exp\u00e9rience de 03 ans minimum dans la fili\u00e8re Engagements serait un atout.<br><strong>Connaissances<\/strong><br>&nbsp;&nbsp;&nbsp;&nbsp; Connaissance des techniques d&rsquo;analyse financi\u00e8re, des ratios financiers, des soldes interm\u00e9diaires de gestion (SIG) , Connaissances g\u00e9n\u00e9rales sur l&rsquo;activit\u00e9 bancaire, les structures et les circuits de traitement, les proc\u00e9dures et la r\u00e9glementation ;<br>&nbsp;&nbsp;&nbsp;&nbsp; Connaissance de la comptabilit\u00e9 bancaire, des normes et proc\u00e9dures relatives aux op\u00e9rations de banque ; Connaissance de la gamme de produits et services destin\u00e9s \u00e0 la client\u00e8le ;<br>Connaissances en mati\u00e8re de montage des dossiers de cr\u00e9dit et maitrise du circuit de traitement des cr\u00e9dits ; Ma\u00eetrise de l&rsquo;outil informatique (bureautique, logiciel de la banque).<br>Savoir-faire<br>Aptitude \u00e0 analyser un bilan et un compte d&rsquo;exploitation ,<br>Aptitude \u00e0 r\u00e9aliser des \u00e9tudes sectorielles et analyser les besoins en mati\u00e8re de financement ;<br>Capacit\u00e9 \u00e0 exposer et de d\u00e9fendre une position sur un dossier (comit\u00e9s, d\u00e9cideur sup\u00e9rieur, r\u00e9seau) , Capacit\u00e9 \u00e0 rechercher l&rsquo;information et actualiser ses connaissances.<br>Savoir-\u00eatre<br>Rigueur et organisation, disponibilit\u00e9 et capacit\u00e9 \u00e0 g\u00e9rer la pression ; Aptitude au travail en \u00e9quipe ;<br>&nbsp;&nbsp;&nbsp;&nbsp; Sens de la confidentialit\u00e9.<br><br><br>D\u00e9lai de recevabilit\u00e9 des candidatures : vendredi 08 Mars 2024 \u00e0 16 heures 30 minutes<br>Canal : par mail \u00e0 l&rsquo;adresse recrutement@bicec.com avec en objet \u00ab CANDIDATURE&nbsp;ANALYSTE RISQUES CREDIT&nbsp;<em>\u00bb.<\/em><\/p>\n\n\n\n<p><em>Seuls les candidats s\u00e9lectionn\u00e9s seront contact\u00e9s pour la suite du processus de recrutement.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement@bicec.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3636],"tags":[],"villes":[135],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"ANALYSTE RISQUES CREDIT","emplois_employeur":9679,"emplois_date_publication":"2024-03-04","emplois_heure_publication":"16:46","emplois_date_cloture":"2024-03-08","emplois_heure_cloture":"16:30","emplois_experience_min":"3","emplois_experience_max":"","emploi_email":"recrutement@bicec.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46808"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46808"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/37715"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46808"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46808"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46808"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}