{"id":46648,"date":"2024-02-22T10:19:34","date_gmt":"2024-02-22T09:19:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46648"},"modified":"2024-02-22T10:19:38","modified_gmt":"2024-02-22T09:19:38","slug":"charge-de-la-clientele-corporate-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/charge-de-la-clientele-corporate-2\/","title":{"rendered":"CHARGE DE LA CLIENTELE CORPORATE"},"content":{"rendered":"\n<p>Il est ouvert au sein de la Direction des&nbsp; Grandes Entreprises du Cr\u00e9dit Communautaire d\u2019Afrique Bank SA, le&nbsp;<strong>poste de Charg\u00e9 de la Client\u00e8le Corporate.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mission<\/h3>\n\n\n\n<p>Sous la supervision du Directeur des Grandes Entreprises, le titulaire du poste aura pour mission : De d\u00e9velopper le portefeuille clients des grandes entreprises en fonction des orientations strat\u00e9giques d\u00e9clin\u00e9s par la Direction G\u00e9n\u00e9rale, conseiller, g\u00e9rer et fid\u00e9liser celui-ci ; maximiser les profits en commercialisant les produits, services bancaires et\/ou financiers.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Profil<\/h3>\n\n\n\n<ul>\n<li>\u00catre titulaire d\u2019un Master 1\/2 et\/ou minimum Licence en Banque et Finance, Commerce, Droit priv\u00e9, Marketing, etc\u2026..<\/li>\n\n\n\n<li>Avoir une exp\u00e9rience professionnelle d\u2019au moins 04 ans dans le domaine de la banque \u00e0 un poste de Charg\u00e9 de la Client\u00e8le, Analyste de Cr\u00e9dit ou de risques ;<\/li>\n\n\n\n<li>\u00catre parfaitement bilingue.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Il\/Elle doit avoir<\/h3>\n\n\n\n<p><strong>Comp\u00e9tences techniques<\/strong><\/p>\n\n\n\n<ul>\n<li>Des connaissances en n\u00e9gociation commerciale et principes comptables ;<\/li>\n\n\n\n<li>Des connaissances en analyse financi\u00e8re ;<\/li>\n\n\n\n<li>Des connaissances en techniques bancaires et proc\u00e9dures administratives ;<\/li>\n\n\n\n<li>Des connaissances en r\u00e9glementation du change ;<\/li>\n\n\n\n<li>Des capacit\u00e9s \u00e0 appr\u00e9cier et analyser les risques (aspects juridiques, fiscaux etc.) ;<\/li>\n\n\n\n<li>De capacit\u00e9s communicationnelles et r\u00e9dactionnelles.<\/li>\n<\/ul>\n\n\n\n<p><strong>Comp\u00e9tences comportementales<\/strong><\/p>\n\n\n\n<ul>\n<li>Avoir un sens ais\u00e9 de la communication ;<\/li>\n\n\n\n<li>Organisation, planification, autonomie ;<\/li>\n\n\n\n<li>Etre capable de travailler en \u00e9quipe ;<\/li>\n\n\n\n<li>Esprit d\u2019analyse, sens du d\u00e9tail ;<\/li>\n\n\n\n<li>Sens de l\u2019\u00e9thique et discr\u00e9tion ;<\/li>\n\n\n\n<li>Avoir des capacit\u00e9s de prise de parole en public et d\u2019animation ;<\/li>\n\n\n\n<li>Go\u00fbt pour les chiffres ;<\/li>\n\n\n\n<li>Force de proposition et de conviction ;<\/li>\n\n\n\n<li>Rigueur dans le recueil et le traitement des donn\u00e9es ;<\/li>\n\n\n\n<li>Sens de la maitrise du risque et souci de la rentabilit\u00e9.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Principales Responsabilit\u00e9s<\/h3>\n\n\n\n<ul>\n<li>D\u00e9tecter les caract\u00e9ristiques et les opportunit\u00e9s du portefeuille des grandes entreprises ;<\/li>\n\n\n\n<li>D\u00e9velopper les relations commerciales en effectuant des visites selon le planning de la hi\u00e9rarchie ;<\/li>\n\n\n\n<li>Faire le suivi et le d\u00e9veloppement des relations avec les clients ;<\/li>\n\n\n\n<li>Monter les dossiers de cr\u00e9dit des clients \u00e0 transf\u00e9rer au comit\u00e9 de cr\u00e9dit ;<\/li>\n\n\n\n<li>Prendre les garanties et suivre leurs enregistrements, les \u00e9valuer annuellement et suivre les mises en place de cr\u00e9dit ;<\/li>\n\n\n\n<li>Maintenir un niveau de qualit\u00e9 de service \u00e9lev\u00e9 pour le portefeuille existant gr\u00e2ce \u00e0 une connaissance approfondie de leurs activit\u00e9s ;<\/li>\n\n\n\n<li>Effectuer le suivi et la ma\u00eetrise des risques sur les engagements de son portefeuille ;<\/li>\n\n\n\n<li>Proc\u00e9der \u00e0 l\u2019ouverture des grands comptes ;<\/li>\n\n\n\n<li>R\u00e9diger les comptes rendus de visite\/entretiens\/ prospection\/ \u00e9valuation ;<\/li>\n<\/ul>\n\n\n\n<p><strong>Poste bas\u00e9 \u00e0<\/strong>&nbsp;: Douala<\/p>\n\n\n\n<p><strong>D\u00e9lai de d\u00e9p\u00f4t des candidatures :<\/strong>&nbsp;au plus tard le 29 f\u00e9vrier \u00e0 17h00<br>Les CVs (version PDF) sont recevables uniquement via l\u2019adresse&nbsp;<strong><a href=\"mailto:recrutement@cca-bank.com\">recrutement@cca-bank.com<\/a><\/strong>&nbsp;avec pour objet : \u00ab&nbsp;<strong>VOTRE NOM_CHARG CORP_FEVRIER_2024<\/strong>&nbsp;\u00bb.<\/p>\n\n\n\n<p>Seuls les candidats s\u00e9lectionn\u00e9s seront convoqu\u00e9s pour la suite du processus de recrutement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement@cca-bank.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3636,251,479,23,24],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"CHARGE DE LA CLIENTELE CORPORATE","emplois_employeur":3887,"emplois_date_publication":"2024-02-22","emplois_heure_publication":"10:19","emplois_date_cloture":"2024-02-29","emplois_heure_cloture":"17:00","emplois_experience_min":"4","emplois_experience_max":"","emploi_email":"recrutement@cca-bank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46648"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46648"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46648"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46648"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46648"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}