{"id":46529,"date":"2024-02-16T12:53:45","date_gmt":"2024-02-16T11:53:45","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46529"},"modified":"2024-02-16T12:53:48","modified_gmt":"2024-02-16T11:53:48","slug":"techniciens-de-laboratoire","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/techniciens-de-laboratoire\/","title":{"rendered":"Techniciens de Laboratoire"},"content":{"rendered":"\n<p>Le Recteur de l&rsquo;Universit\u00e9 de Dschang recrute, pour les besoins de ses services, des personnels suivants :<\/p>\n\n\n\n<p><em>Pour le poste de Techniciens de laboratoire<\/em><br><em>Le postulant doit \u00eatre capable dans l&rsquo;exercice de sa fonction :<\/em><br>&nbsp;&nbsp;&nbsp;&nbsp; D&rsquo;effectuer des analyses et des essais dans les laboratoires d&rsquo;analyses et de recherche de l&rsquo;Universit\u00e9 ;<br>&nbsp; D&rsquo;utiliser le mat\u00e9riel de laboratoire n\u00e9cessaire pour effectuer les analyses ;<br>&nbsp; D&rsquo;utiliser les m\u00e9thodes de documentation et d&rsquo;enregistrement des donn\u00e9es d&rsquo;analyse des \u00e9chantillons.<\/p>\n\n\n\n<p><strong>Dipl\u00f4me exig\u00e9 :<\/strong>&nbsp;Bacc scientifique ou tout dipl\u00f4me \u00e9quivalent et justifier d&rsquo;une exp\u00e9rience pratique dans le domaine.<\/p>\n\n\n\n<p><br><strong>COMPOSITION DU DOSSIER DE CANDIDATURE :<\/strong><br>Les dossiers de candidature, \u00e0 d\u00e9poser contre r\u00e9c\u00e9piss\u00e9 au Service du courrier, 1er \u00e9tage du B\u00e2timent du Rectorat de l&rsquo;Universit\u00e9 de Dschang, porte 103,&nbsp;au plus tard le 29 F\u00e9vrier 2024 \u00e0 15h30, devront contenir les pi\u00e8ces suivantes :<br>&nbsp;&nbsp;&nbsp;&nbsp; Une demande timbr\u00e9e adress\u00e9e au Recteur de l&rsquo;Universit\u00e9 de Dschang et qui mentionne la r\u00e9gion d&rsquo;origine ;<br>&nbsp;&nbsp; Une copie certifi\u00e9e conforme de l&rsquo;acte de naissance ;<br>&nbsp;&nbsp;&nbsp;&nbsp; Un certificat de nationalit\u00e9<br>&nbsp;&nbsp;&nbsp;&nbsp; Une copie certifi\u00e9e conforme du dipl\u00f4me exig\u00e9 ;<br>&nbsp;&nbsp;&nbsp;&nbsp; Un Curriculum Vitae ;<br>&nbsp;&nbsp;&nbsp;&nbsp; Un extrait de casier judiciaire datant de moins de trois mois;<br>&nbsp;&nbsp;&nbsp;&nbsp; Un certificat m\u00e9dical attestant des aptitudes du candidat \u00e0 exercer la fonction sollicit\u00e9e ;&nbsp;&nbsp; Une photocopie de la CNI \u2022<br>&nbsp;&nbsp;&nbsp;&nbsp; 2 photos 4&#215;4 ;<br>&nbsp; Tout document \u00e9ventuel \u00e9tablissant les connaissances, les aptitudes ou l&rsquo;exp\u00e9rience pratique du candidat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Recteur de l&rsquo;Universit\u00e9 de Dschang recrute, pour les besoins de ses services, des personnels suivants : Pour le poste de Techniciens de laboratoireLe postulant&#8230;<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[27],"tags":[],"villes":[322],"contrats":[148],"diplomes":[],"louma_meta":{"emploi_title":"Techniciens de Laboratoire","emplois_employeur":46515,"emplois_date_publication":"2024-02-16","emplois_heure_publication":"12:53","emplois_date_cloture":"2024-02-29","emplois_heure_cloture":"15:30","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46529"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46529"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/46516"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46529"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46529"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46529"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}