{"id":4641,"date":"2020-07-09T03:41:50","date_gmt":"2020-07-09T01:41:50","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=4641"},"modified":"2020-07-09T03:41:50","modified_gmt":"2020-07-09T01:41:50","slug":"avis-de-recrutement-suivi-evaluation-m-e","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/avis-de-recrutement-suivi-evaluation-m-e\/","title":{"rendered":"Avis de recrutement : SUIVI-EVALUATION (M &amp; E)"},"content":{"rendered":"<div class=\"post-header\">\n<div class=\"post-head\">\n<h1 class=\"post-title entry-title\">Avis de recrutement : SUIVI-EVALUATION (M &amp; E)<\/h1>\n<\/div>\n<div class=\"post-meta\"><\/div>\n<div class=\"ads-posting\">\n<div id=\"ads-home\" class=\"home-ad no-items section\"><\/div>\n<p><a name=\"ad-post\"><\/a><\/div>\n<\/div>\n<article>\n<div id=\"post-body-8751623182266575939\" class=\"post-body entry-content\">\n<h2>Avis de recrutement : SUIVI-EVALUATION (M &amp; E)<\/h2>\n<div class=\"separator\"><\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>OFFRE D&rsquo;EMPLOI &#8211; AVIS DE RECRUTEMENT 001-007-2020<\/div>\n<div>ASSOCIATION CAMEROUNAISE DES FEMMES M\u00c9DECINS<\/div>\n<div>ACAFEM<\/div>\n<div><\/div>\n<div>CAMEROON MEDICAL WOMEN ASSOCIATION<\/div>\n<div>CMWA<\/div>\n<div>Si\u00e8ge Social : Yaound\u00e9 Headquarters: Yaound\u00e9<\/div>\n<div>B.P 4198 P.O BOX 4198<\/div>\n<div>Tel: 22 22 50 33 \/677404751 \/ 677 70 40 06<\/div>\n<div>Phone: 22 22 50 33 1677404751 \/ 677 70 40 06<\/div>\n<div>Email: acafemcmwa@gmail.com<\/div>\n<div><\/div>\n<div>INTITULE DU POSTE : SUIVI-EVALUATION (M &amp; E)<\/div>\n<div>Dur\u00e9e de l&#8217;emploi : 03 mois renouvelable apr\u00e8s \u00e9valuation, une p\u00e9riode d&rsquo;essai d&rsquo;au moins un mois sera observ\u00e9e.<\/div>\n<div><\/div>\n<div>Objectif du poste<\/div>\n<div>Le \/ la M &amp; E devra :<\/div>\n<div>\n<ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li>Assister le DIC Manager dans la mise en application des recommandations du partenaire ; T\u00e9l\u00e9charger et analyser les donn\u00e9es hebdomadaires ;<\/li>\n<li>Participer \u00e0 l&rsquo;\u00e9valuation de la qualit\u00e9 de r\u00e9colte des donn\u00e9es ;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div class=\"google-auto-placed ap_container\"><\/div>\n<ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li>Elaborer les proc\u00e9dures d&rsquo;enregistrement et de synchronisation des donn\u00e9es<\/li>\n<li>Contr\u00f4ler la disponibilit\u00e9 des fiches des KP PREV et HTC de mani\u00e8re journali\u00e8re;<\/li>\n<li>Superviser les r\u00e9unions hebdomadaires et participer \u00e0 la validation des donn\u00e9es enregistr\u00e9es ;<\/li>\n<li>Rappel des targets et des r\u00e9alisations de mani\u00e8re journali\u00e8res de chaque pairs leaders en collaboration avec les charg\u00e9s de mobilisations communautaires et le DIC Manager afin de suivre la cascade ; Compiler et t\u00e9l\u00e9charger les donn\u00e9es hebdomadaires recueillies aux diff\u00e9rents postes,<\/li>\n<li>Intervenir dans toute activit\u00e9 ou sa comp\u00e9tence est n\u00e9cessaire ; Superviser les r\u00e9unions hebdomadaires des collectes de donn\u00e9es ;<\/li>\n<li>Edition du rapport et envoi ;<\/li>\n<li>Collaborer avec l&rsquo;\u00e9quipe de M &amp; E de CHAMP pour la coordination et l&rsquo;analyse des donn\u00e9es. Profil du candidat<\/li>\n<li>Une formation de niveau sup\u00e9rieur (au minimum bac + 3 ou bac + 2 de formation dans le domaine associatif ou en management des programmes et projets)<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div class=\"google-auto-placed ap_container\"><\/div>\n<ul>\n<li>Une exp\u00e9rience pr\u00e9alable d&rsquo;au moins deux ans dans la gestion des projets ;<\/li>\n<li>Une exp\u00e9rience pertinente dans le travail avec les ONG locales et internationales :<\/li>\n<li>Le sens de l&rsquo;organisation ;<\/li>\n<li>Une bonne moralit\u00e9 ;<\/li>\n<li>La capacit\u00e9 de travailler en \u00e9quipe ;<\/li>\n<li>Le sens de l&rsquo;initiative ;<\/li>\n<li>La capacit\u00e9 de jugement ;<\/li>\n<li>Une parfaite maitrise de la langue fran\u00e7aise et une bonne connaissance de l&rsquo;anglais ; La maitrise des logiciels tableurs et de traitement de texte ; Avoir la capacit\u00e9 de travailler sous pression.<\/li>\n<li>Etre bon communicateur, r\u00e9ceptif, conciliateur, lent \u00e0 la col\u00e8re, sens de l&rsquo;innovation, pr\u00eat \u00e0 travailler sous pression et capacit\u00e9 d&rsquo; anticipation<\/li>\n<\/ul>\n<\/div>\n<div><\/div>\n<div>\u2022 Horaire de travail : 08H-17H, avec une pause en mi-journ\u00e9e<\/div>\n<div>\u2022 Jour de travail : Lundi \u00e0 Vendredi et les Samedis selon les r\u00e9sultats \u00e0 atteindre<\/div>\n<div>NB : Les r\u00e9am\u00e9nagements de jours et heures de travail sont r\u00e9guliers, et en fonction du poste.<\/div>\n<div><\/div>\n<div>COMPOSITION DU DOSSIER DE CANDIDATURE<\/div>\n<div>\u2022 Une lettre de motivation sign\u00e9e et adress\u00e9e \u00e0 la Pr\u00e9sidente Nationale ACAFEM<\/div>\n<div>\u2022 Un CV d\u00e9taill\u00e9 sign\u00e9<\/div>\n<div>\u2022 Une photocopie du dernier dipl\u00f4me, attestation ou tout autre document probant<\/div>\n<div>\u2022 Une photocopie de la CNI<\/div>\n<div><\/div>\n<div><\/div>\n<div>Date limite de d\u00e9p\u00f4t des dossiers le 09 Juillet \u00e0 15 heures pr\u00e9cises par voie \u00e9lectronique \u00e0 acafemcmwa@gmail.com|<\/div>\n<div><\/div>\n<div><b>COMMENT POSTULER<\/b><\/div>\n<div>\n<h2>Avis de recrutement : SUIVI-EVALUATION (M &amp; E)<\/h2>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Avis de recrutement : SUIVI-EVALUATION (M &amp; E) Avis de recrutement : SUIVI-EVALUATION (M &amp; E) OFFRE D&rsquo;EMPLOI &#8211; AVIS DE RECRUTEMENT 001-007-2020 ASSOCIATION CAMEROUNAISE&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[27],"tags":[450],"villes":[136],"contrats":[234],"diplomes":[278,160,212],"louma_meta":{"emploi_title":"Avis de recrutement : SUIVI-EVALUATION (M & E)","emplois_employeur":4634,"emplois_date_publication":"2020-07-09","emplois_heure_publication":"","emplois_date_cloture":"2020-07-09","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"Avis de recrutement : SUIVI-EVALUATION (M & E)"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4641"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=4641"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4635"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=4641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=4641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=4641"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=4641"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=4641"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=4641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}