{"id":46380,"date":"2024-02-01T14:38:42","date_gmt":"2024-02-01T13:38:42","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46380"},"modified":"2024-02-01T14:38:45","modified_gmt":"2024-02-01T13:38:45","slug":"charge-e-pshea","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/charge-e-pshea\/","title":{"rendered":"Charg\u00e9-e PSHEA"},"content":{"rendered":"\n<p><strong><u>CONTEXTE<\/u><\/strong><\/p>\n\n\n\n<p>CARE est pr\u00e9sente dans 100 pays et met en \u0153uvre plus de 1000 projets d\u2019urgence et de d\u00e9veloppement en collaboration avec les acteurs gouvernementaux et les acteurs locaux du d\u00e9veloppement. Notre objectif est de lutter contre toutes formes de pauvret\u00e9, de d\u00e9fendre l&rsquo;acc\u00e8s aux droits fondamentaux, de combattre les injustices sociales.&nbsp;&nbsp;Au Cameroun depuis 1978, les interventions en cours sont structur\u00e9es autour de 3 programmes d\u2019actions (d\u00e9compos\u00e9s en plusieurs projets) :&nbsp;<strong><em>Le programme Sant\u00e9, Le programme de justice \u00e9conomique et climatique et Le programme de justice genre.<\/em><\/strong><\/p>\n\n\n\n<p>Les op\u00e9rations sont coordonn\u00e9es \u00e0 Yaound\u00e9 et mises en \u0153uvre \u00e0 partir de six (06) bureaux dont trois (03) sp\u00e9cialement pour le programme Fond mondial (Garoua, Douala et Yaound\u00e9) et trois (03) pour les autres programmes (Maroua, Bafoussam et Batouri).&nbsp;Au regard de la dimension communautaire de nos interventions, nous devons nous assurer que notre staff ainsi que les staffs de nos partenaires sont outill\u00e9s aux m\u00e9canismes de protection du Fonds Mondial en g\u00e9n\u00e9rale et particuli\u00e8rement \u00e0 la politique contre l\u2019exploitation, les abus sexuels et le harc\u00e8lement. A ce titre, CARE International Cameroun, recherche&nbsp;:&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Poste<\/strong>&nbsp;: Un-e Charg\u00e9-e PSHEA<\/p>\n\n\n\n<p><strong>P\u00f4le :&nbsp;<\/strong>Programme<\/p>\n\n\n\n<p><strong>Forme contrat :&nbsp;<\/strong>CDD d\u2019un an<\/p>\n\n\n\n<p><strong>Temps de travail&nbsp;:&nbsp;<\/strong>40 heures par semaine (Temps plein)<\/p>\n\n\n\n<p><strong>Rattachement hi\u00e9rarchique&nbsp;:&nbsp;<\/strong>Coordinateur UGP<\/p>\n\n\n\n<p><strong>Lieu du poste :&nbsp;<\/strong>Yaound\u00e9<\/p>\n\n\n\n<p><strong><u>Mission<\/u><\/strong><strong>&nbsp;:<\/strong><\/p>\n\n\n\n<p>Sous la responsabilit\u00e9 directe du Coordinateur de l\u2019unit\u00e9 de Gestion du projet et la supervision fonctionnelle du Coordinateur Ressources Humaines, le Charg\u00e9 PSHEA&nbsp;<strong><em>(Prevention of Sexual Harassment, Exploitation, and Abuse)<\/em><\/strong>&nbsp;est responsable de l\u2019\u00e9laboration et du d\u00e9veloppement des activit\u00e9s de PSHEA au niveau du PR, des SRs et SSRs dans le cadre du projet Fond Mondial GC7.<\/p>\n\n\n\n<p>A ce titre, il participe \u00e0, l\u2019accompagnement des collaborateurs de l\u2019Unit\u00e9 de Gestion et des Sous R\u00e9cipiendaires, Sous &#8211; sous R\u00e9cipiendaires et des partenaires dans la compr\u00e9hension et la mise en \u0153uvre des activit\u00e9s en mati\u00e8re de PSHEA.<\/p>\n\n\n\n<p><strong><u>PRINCIPALES RESPONSABILITES<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>Responsabilit\u00e9 1<\/u><\/strong><strong>&nbsp;:&nbsp;<\/strong><em>Appuyer la Mission de CARE International au Cameroun notamment l\u2019Unit\u00e9 de gestion du Projet Fonds Mondial (GC7) dans la diffusion et la mise en \u0153uvre du plan d\u2019action de la PSHEA avec le soutien de l\u2019\u00e9quipe de la coordination RH.<\/em><em><\/em><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Participer \u00e0 l\u2019\u00e9laboration et la mise \u00e0 jour du plan d\u2019action avec les acteurs concern\u00e9s&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Assurer la mise \u00e0 disposition des politiques de PSHEA, du Code de conduite de CARE ainsi que les \u00e9l\u00e9ments appropri\u00e9s de la bo\u00eete \u00e0 outils \u00e0 toutes les personnes collaborant avec CARE dans le cadre du projet ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Soutenir les \u00e9quipes op\u00e9rationnelles dans la mise en \u0153uvre des standards PSHEA dans les projets (ex : accompagner les coll\u00e8gues dans leurs activit\u00e9s d&rsquo;\u00e9valuation du risque ; proposer des mesures de r\u00e9duction du risque, int\u00e9gration des questions sp\u00e9cifiques lors des entretiens, dans la prise de r\u00e9f\u00e9rences etc.) ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Assurer le suivi la formation initiale et recyclage annuelle sur la PSHEA par tous les staffs du bureau pays&nbsp;et envoyer des rappels r\u00e9guliers ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Assurer le suivi des progr\u00e8s de mise en \u0153uvre avec des rapports r\u00e9guliers \u00e0 son manager et le suivi du rapport de monitoring annuel<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Participer aux hubs, clusters et autres r\u00e9unions PSHEA au niveau national et aux diff\u00e9rents groupes de travail.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Collaborer avec les sp\u00e9cialistes techniques Protection, PSHEA et Inclusion afin de favoriser la promotion de la protection transversale dans le programme :&nbsp;&nbsp;mise en commun d\u2019outils et de bonnes pratiques en mati\u00e8re de pr\u00e9vention et de prise en charge des violences et abus (ex : syst\u00e8me de remont\u00e9 de plaintes inclusif, service de r\u00e9f\u00e9rencement, analyse des risques de protection, communication avec les personnes handicap\u00e9es etc.)<\/p>\n\n\n\n<p><strong><u>Responsabilit\u00e9 2<\/u><\/strong><strong>&nbsp;:&nbsp;&nbsp;<\/strong><em>Contribuer au d\u00e9veloppement d\u2019outils de formation et sensibilisation<\/em><strong><\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;En fonction des besoins et des demandes, am\u00e9liorer et\/ou d\u00e9velopper des outils de sensibilisation (affiches, pr\u00e9sentation, modules de formation etc)<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Veiller \u00e0 la disponibilit\u00e9 des outils de sensibilisation dans tous les sous bureaux de CARE et partenaires de mise en \u0153uvre et prestataires&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Organiser les sessions de formation &amp; de sensibilisation approfondies et adapt\u00e9es pour l&rsquo;ensemble du personnel, l&rsquo;encadrement, et pour les partenaires ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Contribuer au renforcement de capacit\u00e9 des partenaires de mise en \u0153uvre sur l\u2019accueil des plaintes et la sensibilisation&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Veiller \u00e0 ce que la mission CARE Cameroun et chaque projet organise au minimum une s\u00e9ance de formation \u00e0 destination du personnel, des partenaires et des b\u00e9n\u00e9ficiaires\/communaut\u00e9s.<\/p>\n\n\n\n<p><strong><u>Responsabilit\u00e9 3<\/u><\/strong><strong>&nbsp;:&nbsp;&nbsp;<\/strong><em>Contribuer au d\u00e9ploiement des syst\u00e8mes de gestion des remont\u00e9es &amp; plaintes aupr\u00e8s des partenaires et des b\u00e9n\u00e9ficiaires :<\/em><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Contribuer aux SoP des m\u00e9canismes de gestion des remont\u00e9es &amp; plaintes \u00e9labor\u00e9s par les \u00e9quipes MEAL, genre, audit et de l\u2019Instance de Coordination Nationale pour la partie&nbsp;(d\u00e9velopper un outil d\u2019information, documentation et suivi des plaintes&nbsp;; d\u00e9velopper un guide d\u2019assistance aux investigations etc)<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;\u00c9laborer et mettre \u00e0 jour une liste de contacts PSHEA des Partenaires (Sous R\u00e9cipiendaires et Organisations \u00e0 base communautaires) et au sein des groupes cibles ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Communiquer sur le m\u00e9canisme d\u2019alerte professionnelle aupr\u00e8s des collaborateurs de CARE International et suit la diffusion des informations au niveau des b\u00e9n\u00e9ficiaires.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Sur d\u00e9cision du Fonds Mondial, il est le point de r\u00e9ception des canaux de retours et plaintes au sein des communaut\u00e9s et assure le 1er niveau de triage.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Assurer la formation des Points Focaux PSHEA des partenaires, sur les enjeux d\u2019accueils des plaintes &amp; de promotion de la culture de PSHEA en interne ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Appuyer les points focaux au niveau site pour sensibiliser les populations aux politiques de protection et au code de conduite ainsi qu\u2019au fonctionnement des m\u00e9canismes de gestion des retours et plaintes<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Suivre les statistiques sur le nombre de plaintes re\u00e7ues ainsi que les enqu\u00eates men\u00e9es et faire r\u00e9guli\u00e8rement le point au comit\u00e9 de direction<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Garantir la s\u00e9curisation des r\u00e9ceptions de plainte en coordination avec l\u2019ICN et DN\/ MO et la mise en place de la protection de la victime et du lanceur d\u2019alerte.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Participer aux \u00e9valuations initiales des cas et sur nomination \u2013 \u00e0 la cellule d\u2019enqu\u00eate<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Garder un contact r\u00e9gulier avec le r\u00e9f\u00e9rent PSHEA Fonds Mondial et le Coordinateur RH du si\u00e8ge pour les signalements, le partage d&rsquo;informations et le retour d\u2019exp\u00e9rience sur les questions de PSHEA<\/p>\n\n\n\n<p><strong><u>COMPETENCES ET QUALIFICATIONS REQUISES AU POSTE<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>SAVOIR<\/u><\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;BAC + 3 en Sciences sociales ou Politiques, D\u00e9veloppement ou Sant\u00e9, Droits de l\u2019Homme<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Exp\u00e9rience professionnelle d\u2019au moins 2 ans dans le secteur humanitaire ou de d\u00e9veloppement et dans la mise en place des Outils PSHEA<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Connaissances des r\u00e8gles internationales en Droits de l\u2019Homme (enfance, femmes, handicap) et les cadres humanitaires (Protection\/Conventions).<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Sensibilit\u00e9 et connaissance d\u00e9montr\u00e9es du contexte en mati\u00e8re de genre, normes culturelles, et cadre l\u00e9gal<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Exp\u00e9rience dans l\u2019animation et formation des adultes<\/p>\n\n\n\n<p><strong><u>SAVOIR-FAIRE (Est capable de : \u2026)<\/u><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;(1)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;A : D\u00e9butant&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;B : Semi \u2013 autonome&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;C : Autonome&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;D : Expert<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Une exp\u00e9rience dans la prise en charge de survivant de violences&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Compr\u00e9hension des principes de travail avec les survivants de VBG&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Comp\u00e9tences en mati\u00e8re de pr\u00e9sentation et de communication publique&nbsp;<strong>\u2013 D&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Excellente capacit\u00e9 de d\u00e9veloppement d\u2019outils de formation (pr\u00e9sentations, modules, tests de connaissances)&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Bonne compr\u00e9hension de la programmation des activit\u00e9s des projets (Ex : VIH\/SIDA) et des questions de plaidoyer concernant les populations cl\u00e9s, y compris la s\u00e9curit\u00e9, la pr\u00e9vention, les soins et le traitement, la stigmatisation&nbsp;&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Parler\/\u00e9crire l\u2019anglais ou le fran\u00e7ais&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;&nbsp;Excellentes comp\u00e9tences en communication, en particulier l&rsquo;\u00e9coute active et la transmission des messages de mani\u00e8re appropri\u00e9e et claire \u00e0 une vari\u00e9t\u00e9 de publics&nbsp;<strong>\u2013 C<\/strong><\/p>\n\n\n\n<p><strong><u>SAVOIR-ETRE<\/u><\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Engagement pour l\u2019\u00e9galit\u00e9 de genre et la lutte contre la discrimination<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Engagement vers les valeurs de CARE \u2013 Respect, Int\u00e9grit\u00e9, Engagement, Excellence, Transformation<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Sens de l\u2019organisation, Travail en Equipe, Int\u00e9grit\u00e9<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Capacit\u00e9s \u00e0 g\u00e9rer plusieurs t\u00e2ches, Sens de l\u2019anticipation<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Sens de confidentialit\u00e9 et discr\u00e9tion, Esprit de synth\u00e8se et d\u2019analyse<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Orientation r\u00e9sultats, Flexibilit\u00e9 et capacit\u00e9 d&rsquo;adaptation<\/p>\n\n\n\n<p><strong><u>CONDITIONS ET MODALIT\u00c9S DE CANDIDATURE<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>IMPORTANT &#8211; COMMENT POSTULER (Suivre les instructions SVP)<\/u><\/strong><\/p>\n\n\n\n<p>1-\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Les personnes int\u00e9ress\u00e9es par cette offre sont pri\u00e9es de bien vouloir remplir le formulaire pr\u00e9vu \u00e0 cet effet en suivant le lien ci-dessous\u00a0: <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUOUlFN1k4NVY4OUxPMlRJTVlFNjU2TDEwNy4u\">https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUOUlFN1k4NVY4OUxPMlRJTVlFNjU2TDEwNy4u<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUOUlFN1k4NVY4OUxPMlRJTVlFNjU2TDEwNy4u\n<\/div><\/figure>\n\n\n\n<p><strong><em>2-&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/strong>A la fin du formulaire, il vous sera indiqu\u00e9 un autre lien par lequel vous transmettrez&nbsp;<strong><u>UNIQUEMENT<\/u><\/strong>&nbsp;votre&nbsp;<strong><em><u>CV et lettre de motivation<\/u><\/em><\/strong><\/p>\n\n\n\n<p><strong><u>NB<\/u><\/strong>&nbsp;:<\/p>\n\n\n\n<p>1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Les candidatures f\u00e9minines sont vivement encourag\u00e9es&nbsp;;<\/p>\n\n\n\n<p>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Toute candidature transmise par un autre canal que celui indiqu\u00e9 plus haut, ne sera pas prise en compte&nbsp;;<\/p>\n\n\n\n<p>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s personnellement&nbsp;;<\/p>\n\n\n\n<p>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Dans le cadre de ce processus de recrutement, les candidatures seront trait\u00e9es au fur et \u00e0 mesure. CARE International au Cameroun se r\u00e9serve le droit de cl\u00f4turer le processus avant le terme.<\/p>\n\n\n\n<p>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Date de cl\u00f4ture de l\u2019offre&nbsp;:&nbsp;<strong><u>13 f\u00e9vrier 2024 \u00e0 17 heures pr\u00e9cises<\/u><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUOUlFN1k4NVY4OUxPMlRJTVlFNjU2TDEwNy4u<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2554],"tags":[],"villes":[136],"contrats":[148],"diplomes":[212],"louma_meta":{"emploi_title":"Charg\u00e9-e PSHEA","emplois_employeur":2916,"emplois_date_publication":"2024-02-01","emplois_heure_publication":"14:38","emplois_date_cloture":"2024-02-13","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUOUlFN1k4NVY4OUxPMlRJTVlFNjU2TDEwNy4u"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46380"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46380"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2917"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46380"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46380"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46380"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}