{"id":46324,"date":"2024-01-29T10:08:29","date_gmt":"2024-01-29T09:08:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46324"},"modified":"2024-01-29T10:08:30","modified_gmt":"2024-01-29T09:08:30","slug":"conseillers-clients-h-f-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/conseillers-clients-h-f-2\/","title":{"rendered":"CONSEILLERS CLIENTS (H\/F)"},"content":{"rendered":"\n<p><strong><u>PROFIL<\/u><\/strong>&nbsp;<\/p>\n\n\n\n<p>Vous \u00eates,<\/p>\n\n\n\n<ul>\n<li>Un Homme ou une Femme;<\/li>\n\n\n\n<li>\u00c2g\u00e9 (\u00e9) de 23 ans minimum;<\/li>\n\n\n\n<li>Dipl\u00f4m\u00e9 (e) de l&rsquo;Enseignement Sup\u00e9rieur.<\/li>\n<\/ul>\n\n\n\n<p><strong>Vous \u00eates,<\/strong>&nbsp;<\/p>\n\n\n\n<ul>\n<li>Orient\u00e9 (e) r\u00e9sultats<\/li>\n\n\n\n<li>Ambitieux (se).<\/li>\n\n\n\n<li>Vous avez le sens de l&rsquo;\u00e9coute,<\/li>\n\n\n\n<li>Vous justifiez d&rsquo;une exp\u00e9rience \u00e0 un poste similaire.<\/li>\n<\/ul>\n\n\n\n<p><strong><u>Rejoignez nous&nbsp;<\/u><\/strong>!<\/p>\n\n\n\n<p>Envoyez votre CV via notre compte WhatsApp Business au&nbsp;<strong>658 138 577<\/strong>&nbsp;ou par mail \u00e0&nbsp;<a href=\"mailto:recrutementcm@groupensia.com\">recrutementcm@groupensia.com<\/a><\/p>\n\n\n\n<p><strong><u>CONTACT<\/u><\/strong>:<\/p>\n\n\n\n<p>&nbsp;(237) 677 11 58 28\/696 57 52 07<br>&nbsp;&nbsp;&nbsp; (237) 233 50 27 00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via \u00a0recrutementcm@groupensia.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[343,25,24,1273],"tags":[],"villes":[2714],"contrats":[148],"diplomes":[278],"louma_meta":{"emploi_title":"CONSEILLERS CLIENTS (H\/F)","emplois_employeur":9114,"emplois_date_publication":"2024-01-29","emplois_heure_publication":"10:01","emplois_date_cloture":"2024-02-02","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"\u00a0recrutementcm@groupensia.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46324"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46324"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9115"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46324"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46324"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46324"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}