{"id":46183,"date":"2024-01-24T10:47:18","date_gmt":"2024-01-24T09:47:18","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=46183"},"modified":"2024-01-24T10:47:19","modified_gmt":"2024-01-24T09:47:19","slug":"stage-academique-en-marketing-et-commercial","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2024\/stage-academique-en-marketing-et-commercial\/","title":{"rendered":"STAGE ACAD\u00c9MIQUE EN MARKETING ET COMMERCIAL"},"content":{"rendered":"\n<p>Africa Up Horizon est un programme d\u00e9di\u00e9 \u00e0 la formation des jeunes dans les m\u00e9tiers de la communication en Afrique.<\/p>\n\n\n\n<p>Nous nous engageons \u00e0 d\u00e9velopper les comp\u00e9tences et les talents des jeunes pour les pr\u00e9parer \u00e0 exceller dans l&rsquo;industrie dynamique de la communication.<\/p>\n\n\n\n<p>Position : Stage Acad\u00e9mique &#8211; Marketing et Commercial niveau Licence ou Master (Dur\u00e9e : 2 mois)<\/p>\n\n\n\n<p>Lieu : Mont\u00e9e Avenue germaine, Essos<\/p>\n\n\n\n<p>1- Description du poste : En tant que stagiaire en marketing et commercial chez Africa Up Horizon, vous serez int\u00e9gr\u00e9(e) \u00e0 notre \u00e9quipe dynamique et contribuerez activement au d\u00e9veloppement de strat\u00e9gies de marketing et de vente.<\/p>\n\n\n\n<p>Vous aurez l&rsquo;opportunit\u00e9 d&rsquo;acqu\u00e9rir une exp\u00e9rience pratique dans les domaines du marketing digital, de la gestion de la relation client et des techniques de vente.<\/p>\n\n\n\n<p>2- Responsabilit\u00e9s :<\/p>\n\n\n\n<p>Participer \u00e0 l&rsquo;\u00e9laboration de strat\u00e9gies de marketing visant \u00e0 promouvoir nos programmes de formation.<\/p>\n\n\n\n<p>Contribuer \u00e0 la cr\u00e9ation de contenus marketing attractifs pour diff\u00e9rents canaux.<\/p>\n\n\n\n<p>Assister dans la prospection et la gestion des relations avec les clients potentiels.<\/p>\n\n\n\n<p>Collaborer avec l&rsquo;\u00e9quipe pour mettre en \u0153uvre des actions commerciales efficaces.<\/p>\n\n\n\n<p>3- Exigences :<\/p>\n\n\n\n<p>\u00c9tudiant(e) en marketing, commerce, communication ou domaine similaire.<\/p>\n\n\n\n<p>Compr\u00e9hension des principes de base du marketing et des ventes.<\/p>\n\n\n\n<p>Capacit\u00e9 \u00e0 travailler de mani\u00e8re autonome et en \u00e9quipe.<\/p>\n\n\n\n<p>Comp\u00e9tences en communication et en n\u00e9gociation.<\/p>\n\n\n\n<p>Ma\u00eetrise des outils informatiques et des plateformes de m\u00e9dias sociaux.<\/p>\n\n\n\n<p>4- Avantages du stage :<\/p>\n\n\n\n<p>Encadrement professionnel et mentorat.<\/p>\n\n\n\n<p>Possibilit\u00e9 d&rsquo;acqu\u00e9rir une exp\u00e9rience pratique dans un environnement de travail stimulant.<\/p>\n\n\n\n<p>Participation active \u00e0 la conception et \u00e0 la mise en \u0153uvre de strat\u00e9gies de communication et de marketing.<\/p>\n\n\n\n<p>Possibilit\u00e9s d\u2019apprendre dans de nombreux domaines parall\u00e8les autour de la communication.<\/p>\n\n\n\n<p>Possibilit\u00e9s de gagner des commissions, des avantages en nature et des primes de rendement pendant votre stage<\/p>\n\n\n\n<p>Comment postuler : Envoyez votre CV et une lettre de motivation \u00e0 africauphorizon@gmail.com<\/p>\n\n\n\n<p>Indiquez \u00ab\u00a0Candidature &#8211; Stage Marketing et Commercial\u00a0\u00bb dans l&rsquo;objet du courriel.<\/p>\n\n\n\n<p>Date limite de candidature : 27 janvier 2024<\/p>\n\n\n\n<p>Nous sommes impatients de recevoir votre candidature et d&rsquo;explorer ensemble les belles opportunit\u00e9s qui vous attendent chez Africa Up Horizon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  africauphorizon@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[4067,24],"tags":[],"villes":[2714],"contrats":[152],"diplomes":[212,159],"louma_meta":{"emploi_title":"STAGE ACAD\u00c9MIQUE EN MARKETING ET COMMERCIAL","emplois_employeur":3046,"emplois_date_publication":"2024-01-24","emplois_heure_publication":"10:47","emplois_date_cloture":"2024-01-27","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":" africauphorizon@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46183"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=46183"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/46183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=46183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=46183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=46183"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=46183"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=46183"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=46183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}