{"id":45705,"date":"2023-12-27T15:02:04","date_gmt":"2023-12-27T14:02:04","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=45705"},"modified":"2023-12-27T15:02:05","modified_gmt":"2023-12-27T14:02:05","slug":"chargee-de-projet-programmes-a-haut-impact","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/chargee-de-projet-programmes-a-haut-impact\/","title":{"rendered":"Charg\u00e9e de Projet &#8211; Programmes \u00e0 haut impact"},"content":{"rendered":"\n<p>Impact Sant\u00e9 Afrique (ISA), NC : M031912772718P ; RC : 0249\/RDA\/JO6\/A2\/SAAJP\/BAPP<br>Street 1798, next to the Nigeria Ambassador Residency, Bastos<br>E-mail: contact@impactsante.org | Website: www.impactsante.org<br>BP: 35562 Yaound\u00e9 \u2013 Cameroun | Tel: (+237) 699 038 004<\/p>\n\n\n\n<p><br>APPEL A CANDIDATURES<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">Titre : Charg\u00e9e de Projet &#8211; Plaidoyer<br>Section : Programmes \u00e0 haut impact<br>Localisation de ce poste : Yaound\u00e9, Cameroun<br>R\u00e9mun\u00e9ration : Comp\u00e9titive<\/h1>\n\n\n\n<p><br><strong>Contexte<\/strong><br>Impact Sant\u00e9 Afrique (ISA) est une organisation non gouvernementale bas\u00e9e au Cameroun<br>dont le principal objectif est de contribuer \u00e0 l\u2019am\u00e9lioration de la sant\u00e9 des populations en<br>mettant en place des programmes transformateurs et durables (pour plus d\u2019informations,<br>visitez www.impactsante.org). ISA recherche un Charg\u00e9 de Projet &#8211; plaidoyer dans le cadre<br>du projet \u00ab \u00c9quit\u00e9 Acc\u00e8s Palu \u00bb financ\u00e9 par l\u2019Initiative sur une p\u00e9riode de 3 ans (06<br>Novembre 2023 \u2013 31 Octobre 2026) renouvelable. Ce projet vise \u00e0 renforcer l\u2019engagement<br>communautaire dans la lutte contre le paludisme.<br>Principales Missions :<br>Le charg\u00e9 de projet &#8211; Plaidoyer, aura pour principal mission l&rsquo;\u00e9laboration et la mise en<br>\u0153uvre des plans de plaidoyer de ce projet. Il ou elle dirigera la mise en \u0153uvre d&rsquo;initiatives<br>int\u00e9gr\u00e9es en mati\u00e8re d&rsquo;analyse et de participation des politiques de plaidoyer, des<br>campagnes et d&rsquo;influence sur le travail au niveau des districts afin d&rsquo;obtenir un impact<br>significatif et ainsi renforcer les objectifs du projet.<br>Responsabilit\u00e9s : Plaidoyer, conception et mise en \u0153uvre du programme<br>Sous la supervision du Coordonnateur du projet, il sera charg\u00e9 de :<br>\u25cf Assurer la mise en \u0153uvre des activit\u00e9s de plaidoyer du projet ;<br>\u25cf Assurer l\u2019organisation des r\u00e9unions et ateliers ;<br>\u25cf Assurer la production des documents de plaidoyer en prenant en compte les objectifs<br>du projet ;<br>\u25cf Assurer le plaidoyer pour la mobilisation des associations locales, des dirigeants<br>locaux des communaut\u00e9s et l&rsquo;engagement sp\u00e9cifique des groupes vuln\u00e9rables<br>principalement dans les 4 districts (Mokolo, Doume, Bafoussam et Maroua) ;<br>\u25cf Mettre en \u0153uvre les activit\u00e9s li\u00e9es au plaidoyer en faveur de la lutte contre le<br>paludisme ;<br>\u25cf Soutenir l\u2019\u00e9quipe plaidoyer dans le d\u00e9veloppement de leurs capacit\u00e9s dans le<br>plaidoyer, la planification et la gestion de programme\/projet, le suivi et la<br>redevabilit\u00e9.<br>\u25cf D\u00e9velopper les notes techniques de plaidoyer et contenus des autres outils de<br>plaidoyer ;<br>\u25cf Pr\u00e9parer des pr\u00e9sentations Power Point et autres documents cl\u00e9s \u00e0 destination des<br>leaders.<br>\u25cf Participer aux r\u00e9unions strat\u00e9giques et de suivi ;<br>\u25cf R\u00e9diger ses rapports d\u2019activit\u00e9s hebdomadaires, mensuels, annuels ;<br>\u25cf Toute autre t\u00e2che assign\u00e9e par ISA dans le cadre de ce projet.<br>P\u00e9riode : \u00e0 partir du 08 Janvier 2024<br><br>R\u00e9f. : D468\/EFR\/2023Impact Sant\u00e9 Afrique (ISA), NC : M031912772718P ; RC : 0249\/RDA\/JO6\/A2\/SAAJP\/BAPP<br>Street 1798, next to the Nigeria Ambassador Residency, Bastos<br>E-mail: contact@impactsante.org | Website: www.impactsante.org<br>BP: 35562 Yaound\u00e9 \u2013 Cameroun | Tel: (+237) 699 038 004<br><strong>Qualifications :<\/strong><br>\u25cf Master en communication, plaidoyer, sciences sociales ou dans un domaine connexe,<br>avec au moins 2 ans d&rsquo;exp\u00e9rience.<br>\u25cf Ou une licence avec au moins 4 ans d&rsquo;exp\u00e9rience dans le domaine de la<br>communication ou du plaidoyer ;<br>\u25cf Capacit\u00e9 \u00e0 travailler dans un environnement international\/multiculturel ;<br>\u25cf Excellentes aptitudes r\u00e9dactionnelle et bonne expression orale en anglais et en<br>fran\u00e7ais ;<br>\u25cf Excellentes aptitudes \u00e0 la communication orale et \u00e9crite pour produire des<br>documents professionnels conformes aux normes internationales et participer \u00e0 des<br>discussions et d\u00e9bats ;<br>\u25cf Capacit\u00e9 \u00e0 d\u00e9velopper de solides relations de travail avec les coll\u00e8gues et les<br>diff\u00e9rentes parties prenantes telles que les partenaires, les membres de la<br>communaut\u00e9, les bailleurs de fonds, la soci\u00e9t\u00e9 civile, etc\u2026 ;<br>\u25cf Attitude positive et dynamique ;<br>\u25cf Capacit\u00e9 \u00e0 planifier, hi\u00e9rarchiser et organiser son travail et celui des autres ;<br>\u25cf Capacit\u00e9 \u00e0 travailler sous pression pour respecter les d\u00e9lais.<br><strong>Pour soumettre votre candidature :<\/strong><br><strong>Votre dossier contiendra :<\/strong><br>\u25cf La lettre de motivation<br>\u25cf Le CV du candidat<br>\u25cf Trois r\u00e9f\u00e9rences professionnelles<br>Date de publication : 1er D\u00e9cembre 2023<br>Ces \u00e9l\u00e9ments devront \u00eatre envoy\u00e9s&nbsp;au plus tard le 04 Janvier 2024 \u00e0 23h59 GMT +1&nbsp;\u00e0<br>l\u2019adresse jobsimpactsante@gmail.com.&nbsp;Les candidatures re\u00e7ues apr\u00e8s cette date ne seront<br>pas consid\u00e9r\u00e9es.<br>Objet du mail : EF_ Charg\u00e9e de Projet &#8211; plaidoyer D468\/EFR\/2023<br>Pour plus d&rsquo;informations : contact@impactsante.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via jobsimpactsante@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25,302],"tags":[],"villes":[2714,136],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"Charg\u00e9e de Projet - Programmes \u00e0 haut impact","emplois_employeur":13976,"emplois_date_publication":"2023-12-27","emplois_heure_publication":"15:01","emplois_date_cloture":"2024-01-04","emplois_heure_cloture":"23:59","emplois_experience_min":"2","emplois_experience_max":"4","emploi_email":"jobsimpactsante@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45705"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45705"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/13977"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45705"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45705"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45705"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}