{"id":45651,"date":"2023-12-27T02:40:45","date_gmt":"2023-12-27T02:40:45","guid":{"rendered":""},"modified":"2023-12-27T03:57:17","modified_gmt":"2023-12-27T02:57:17","slug":"agents-commerciaux-19","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/agents-commerciaux-19\/","title":{"rendered":"Agents commerciaux"},"content":{"rendered":"<p>Univers Groupe Sarl est une entreprise commerciale en pleine croissance et recherche pour ses besoins 20 commerciaux dans la ville de Douala afin de d&eacute;velopper son portefeuille client&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Univers Groupe Sarl est une entreprise commerciale en pleine croissance et recherche pour ses besoins 20 commerciaux dans la ville de Douala afin de d&eacute;velopper&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[4067],"tags":[],"villes":[135],"contrats":[148],"diplomes":[156],"louma_meta":{"emploi_title":"Agents commerciaux ","emplois_employeur":3046,"emplois_date_publication":"2023-12-27","emplois_heure_publication":"","emplois_date_cloture":"2024-01-01","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"atanganamanuel954@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45651"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45651"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45651"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45651"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45651"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}