{"id":45519,"date":"2023-12-16T09:29:44","date_gmt":"2023-12-16T08:29:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=45519"},"modified":"2023-12-16T09:29:47","modified_gmt":"2023-12-16T08:29:47","slug":"cinq-05-conseillers-eres-technique-projet-fm","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/cinq-05-conseillers-eres-technique-projet-fm\/","title":{"rendered":"Cinq (05) Conseillers-\u00e8res Technique \u2013 projet FM"},"content":{"rendered":"\n<p><strong><u>AVIS DE RECRUTEMENT N\u00b0049.122023\/RH\/CCMR<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>CONTEXTE<\/u><\/strong><\/p>\n\n\n\n<p>CARE est pr\u00e9sente dans 100 pays et met en \u0153uvre plus de 1000 projets d\u2019urgence et de d\u00e9veloppement en collaboration avec les acteurs gouvernementaux et les acteurs locaux du d\u00e9veloppement. Notre objectif est de lutter contre toutes formes de pauvret\u00e9, de d\u00e9fendre l&rsquo;acc\u00e8s aux droits fondamentaux, de combattre les injustices sociales.<\/p>\n\n\n\n<p>Au Cameroun depuis 1978, CARE met en \u0153uvre des actions autour de 3 axes strat\u00e9giques : Justice genre, sant\u00e9 et justice climatique et \u00e9conomique. Nos actions s\u2019inscrivent dans les phases d\u2019urgence et r\u00e9silience visant l\u2019autonomisation des femmes et jeunes, renforcement des syst\u00e8mes communautaires, l\u2019accompagnement des processus de d\u00e9centralisation et l\u2019am\u00e9lioration des services et acc\u00e8s \u00e0 la sant\u00e9 sexuelle et de la reproduction.<\/p>\n\n\n\n<p>Dans le cadre de la continuit\u00e9 de son objectif qui vise \u00e0 r\u00e9duire la morbidit\u00e9 et la mortalit\u00e9 associ\u00e9e au VIH et aux Infections Sexuellement Transmissibles (IST), CARE a \u00e9t\u00e9 reconduit par l\u2019ICN comme Premier R\u00e9cipiendaire (PR) pour organiser et coordonner les interventions de la subvention communautaire GC7 (2024-2026). Une unit\u00e9 de gestion sp\u00e9cifique et autonome est mise en place, compos\u00e9e d\u2019une cinquantaine de salari\u00e9s, qui s\u2019appuie sur un dispositif op\u00e9rationnel construit autour de 3 bureaux r\u00e9gionaux avec 4 Sous R\u00e9cipiendaires (SR) et plusieurs dizaines d\u2019Organisations \u00e0 Base Communautaires (SSR) dans les 10 r\u00e9gions du Cameroun.<\/p>\n\n\n\n<p>Dans cette dynamique, CARE recherche&nbsp;:&nbsp;<\/p>\n\n\n\n<p><strong>Poste<\/strong>&nbsp;: Cinq (05) Conseillers-\u00e8res Technique&nbsp;\u2013 projet FM<\/p>\n\n\n\n<p><strong>P\u00f4le :&nbsp;<\/strong>Programme<\/p>\n\n\n\n<p><strong>Forme contrat :&nbsp;<\/strong>CDD de deux (02) ans<\/p>\n\n\n\n<p><strong>Temps de travail&nbsp;:&nbsp;<\/strong>40 heures par semaine (Temps plein)<\/p>\n\n\n\n<p><strong>Rattachement hi\u00e9rarchique&nbsp;:&nbsp;<\/strong>Conseiller-\u00e8re Technique Senior<\/p>\n\n\n\n<p><strong>Lieu du poste :&nbsp;<\/strong>Yaound\u00e9<\/p>\n\n\n\n<p><strong><u>Mission<\/u><\/strong><strong>&nbsp;:<\/strong><\/p>\n\n\n\n<p>Sous la supervision du Conseiller Technique Senior du Projet Fond Mondial, le Conseiller Technique fournit une assistance technique dans la Coordination du programme de pr\u00e9vention et de d\u00e9pistage du VIH. Il\/Elle veille au respect de la qualit\u00e9 des interventions organis\u00e9es aupr\u00e8s des cibles du projet. Il\/Elle oriente la mise en \u0153uvre, l\u2019accompagnement et l\u2019\u00e9valuation des interventions prescrites dans le plan op\u00e9rationnel du PR\/SR. Il\/Elle est responsable de la validation des livrables du SR et assure le renforcement des capacit\u00e9s des \u00e9quipes du SR et des SSRs.&nbsp;&nbsp;Il\/Elle a \u00e9galement la charge de piloter les activit\u00e9s en lien avec la prise en charge des diff\u00e9rentes cibles mis en \u0153uvre par le Principal R\u00e9cipiendaire dans le cadre de la subvention GC7.<\/p>\n\n\n\n<p><strong>PRINCIPALES RESPONSABILITES<\/strong><\/p>\n\n\n\n<p><strong>RESPONSABILITE 1 :<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Coordination du programme de pr\u00e9vention et de d\u00e9pistage du VIH aupr\u00e8s des Adolescents et Jeunes<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Coordination technique du programme de pr\u00e9vention et de d\u00e9pistage du VIH aupr\u00e8s des MSM, TG, UD et UDI<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mettre en \u0153uvre des interventions li\u00e9es \u00e0 l\u2019auto-d\u00e9pistage, \u00e0 la PrEP et aux activit\u00e9s au sein des DIC \u00e0 travers les SR et les Coordinations r\u00e9gionales<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Coordination du programme de pr\u00e9vention et de d\u00e9pistage du VIH aupr\u00e8s des TS\/C<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Coordination de la mise en \u0153uvre des interventions Droits Humains<\/p>\n\n\n\n<p><strong>RESPONSABILITE 2 : Renforcer les capacit\u00e9s des DIC, SR\/SSRs et autres partenaires de mise en des interventions aupr\u00e8s des Adolescents-Jeunes.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.1 : Fournir une assistance technique aux \u00e9quipes du SR et des SSRs Adolescents-Jeunes dans la planification, l\u2019orientation, la mise en \u0153uvre et l\u2019accompagnement des activit\u00e9s prescrites dans leur plan op\u00e9rationnel dans un d\u00e9lai pr\u00e9alablement \u00e9tabli et opportun&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.2: Identifier les besoins en formations des \u00e9quipes du SR et SSRs, les planifier et les mettre en \u0153uvre en collaboration avec les autres membres de l\u2019\u00e9quipe d\u00e9di\u00e9e du programme ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.3 : Mettre \u00e0 disposition des modules de formations valid\u00e9s ainsi que les formateurs qualifi\u00e9s selon les profils recherch\u00e9s ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.4 : Organiser les activit\u00e9s de supervisions des SR et SSR pour le contr\u00f4le qualit\u00e9 et am\u00e9lioration de leurs performances.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.5: Fournir une assistance technique dans le cadre du renforcement des capacit\u00e9s techniques et organisationnelles des partenaires de mise en \u0153uvre des activit\u00e9s Adolescents-Jeunes ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.6 : Organiser des sessions de recyclage et de mentorat pour le personnel des SRs et SSRs selon les besoins exprim\u00e9s en collaboration avec les autres membres de l\u2019\u00e9quipe d\u00e9di\u00e9e ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 2.7: Soumettre des rapports de qualit\u00e9 des activit\u00e9s des partenaires de mise en \u0153uvre et les exploiter pour faire leurs faire des retours appropri\u00e9s selon les normes et les standards.<\/p>\n\n\n\n<p><strong>RESPONSABILITE 3 : Veiller au respect de la qualit\u00e9 des interventions organis\u00e9es aupr\u00e8s des Adolescents-Jeunes<\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.1 : Associer les parties prenantes dans la conception, la production et la disponibilit\u00e9 des outils de contr\u00f4le qualit\u00e9 et de la collecte des donn\u00e9es relative \u00e0 la prise en charge des Adolescents-Jeunes (PR, SR et SSRs).<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.2 : Identifier les forces et les faiblesses des interventions des Adolescents-Jeunes et veiller \u00e0 la mise en \u0153uvre des recommandations ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.3 : Elaborer en collaboration avec le SR et SSRs un plan de communication pour le changement social et de comportement des Adolescents-Jeunes et \u00e9laborer des messages de communication et de plaidoyer pour les audiences cibl\u00e9s ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.4 : Suivre avec le responsable GAS de la disponibilit\u00e9 des produits pharmaceutiques sp\u00e9cifiques Adolescents-Jeunes pour la pr\u00e9vention, le d\u00e9pistage du VIH et des IST.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.5 : Effectuer des visites sur le terrain pour s&rsquo;assurer de la qualit\u00e9 des interventions et v\u00e9rifier l&rsquo;exactitude des donn\u00e9es rapport\u00e9es.<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.6 :&nbsp;&nbsp;Consolider des histoires \u00e0 succ\u00e8s relatives \u00e0 la mise en \u0153uvre des services de pr\u00e9vention et de d\u00e9pistage du VIH aupr\u00e8s des Adolescents-Jeunes ;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 3.7 : Archiver en collaborations avec le MEAL les rapports et autres documents du projet et des SR.<\/p>\n\n\n\n<p><a><\/a><strong>RESPONSABILITE 4 : Autres t\u00e2ches<\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 4.1: Participer aux r\u00e9unions pertinentes avec le bailleur, le minist\u00e8re de la sant\u00e9, les programmes nationaux, le Fonds mondial, le PEPFAR et les donateurs potentiels&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 4.2: Repr\u00e9senter le projet lors de r\u00e9unions et de conf\u00e9rences techniques internes et externes&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 4.3 : Participer activement \u00e0 l\u2019\u00e9laboration des rapports d\u2019activit\u00e9s contractuels du projet Fond Mondial&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 4.4 : Contribuer \u00e0 l\u2019\u00e9laboration des documents de planification strat\u00e9gique du projet&nbsp;;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Activit\u00e9 4.5 : Ex\u00e9cuter toute autre t\u00e2che demand\u00e9e par son superviseur direct.<\/p>\n\n\n\n<p><strong>COMPETENCES ET QUALIFICATIONS REQUISES AU POSTE<\/strong><\/p>\n\n\n\n<p><strong><u>SAVOIR<\/u><\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Dipl\u00f4me : Bac + 4 &#8211; 5 requis Gestion des Projets, Sant\u00e9 Publique, Sciences Sociales, et formations connexes etc\u2026<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Exp\u00e9riences : Au moins entre 2 \u00e0 4 ans dans une ONG, et une exp\u00e9rience dans le financement du Fonds Mondial serait un atout<\/p>\n\n\n\n<p><strong><u>SAVOIR-FAIRE (Est capable de : \u2026)<\/u><\/strong><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong>NIVEAU (1)&nbsp;&nbsp;&nbsp;<strong>A<\/strong>&nbsp;: D\u00e9butant&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>B<\/strong>&nbsp;: Semi -autonome&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>&nbsp;C<\/strong>&nbsp;: Autonome&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>D<\/strong>&nbsp;: Expert<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Appliquer les normes et la r\u00e9glementation en vigueur&nbsp;<strong>\u2013 C<\/strong>&nbsp;Identifier les besoins en formation&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Valider un plan de formation&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;Classer et archiver les documents&nbsp;<strong>\u2013 C&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Organiser les sessions de recyclage du personnel&nbsp;<strong>\u2013 D<\/strong>&nbsp;Evaluer les performances individuelles&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Contr\u00f4ler la r\u00e9gularit\u00e9 des rapports d\u2019activit\u00e9 des partenaires&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Identifier les forces et les faiblesses&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Effectuer des visites sur le terrain&nbsp;<strong>\u2013 D<\/strong>&nbsp;Concevoir les outils de collecte des donn\u00e9es&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Parler\/\u00e9crire l\u2019anglais ou le fran\u00e7ais&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Documenter les bonnes pratiques&nbsp;<strong>\u2013 D&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Elaborer un chronogramme d\u2019activit\u00e9&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;D\u00e9ployer un plan strat\u00e9gique&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Analyser et identifier les risques&nbsp;<strong>\u2013 C<\/strong>&nbsp;Animer une \u00e9quipe&nbsp;<strong>\u2013 D<\/strong>&nbsp;&nbsp;&nbsp;D\u00e9velopper un r\u00e9seau de partenariats&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;R\u00e9diger les \u00e9crits professionnels (comptes rendus, notes d&rsquo;analyses, notes de veille, notes de synth\u00e8se, rapports, \u2026)&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Utiliser les logiciels Word, Excel, Power Point ou toute autre application li\u00e9e \u00e0 l\u2019activit\u00e9&nbsp;<strong>\u2013 C<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong><u>SAVOIR-ETRE<\/u><\/strong><\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Sens de l\u2019organisation, Confidentialit\u00e9, Capacit\u00e9 \u00e0 travailler sous pression<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Orientation r\u00e9sultat, Discr\u00e9tion, Esprit d\u2019\u00e9quipe, Professionnalisme<\/p>\n\n\n\n<p>\u00a7&nbsp;&nbsp;Ecoute active, Flexibilit\u00e9, Capacit\u00e9 d&rsquo;adaptation, Rigueur et m\u00e9thode<\/p>\n\n\n\n<p><strong><u>CONDITIONS ET MODALIT\u00c9S DE CANDIDATURE<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>IMPORTANT &#8211; COMMENT POSTULER (Suivre les instructions SVP)<\/u><\/strong><\/p>\n\n\n\n<p>1-&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Les personnes int\u00e9ress\u00e9es par cette offre sont pri\u00e9es de bien vouloir remplir le formulaire pr\u00e9vu \u00e0 cet effet en suivant le lien ci-dessous&nbsp;:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUNTBZQzdEVEU3U01HTTVZTjNYRFlSWVNWNS4u\n<\/div><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUNTBZQzdEVEU3U01HTTVZTjNYRFlSWVNWNS4u\">https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUNTBZQzdEVEU3U01HTTVZTjNYRFlSWVNWNS4u<\/a><br>\u00a0<\/figcaption><\/figure>\n\n\n\n<p><strong><em>2-&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/em><\/strong>A la fin du formulaire, il vous sera indiqu\u00e9 un autre lien par lequel vous transmettrez&nbsp;<strong><u>UNIQUEMENT<\/u><\/strong>&nbsp;votre&nbsp;<strong><em><u>CV et lettre de motivation<\/u><\/em><\/strong><\/p>\n\n\n\n<p><strong><u>NB<\/u><\/strong>&nbsp;:<\/p>\n\n\n\n<p>1.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Les candidatures f\u00e9minines sont vivement encourag\u00e9es&nbsp;;<\/p>\n\n\n\n<p>2.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Toute candidature transmise par un autre canal que celui indiqu\u00e9 plus haut, ne sera pas prise en compte&nbsp;;<\/p>\n\n\n\n<p>3.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s personnellement&nbsp;;<\/p>\n\n\n\n<p>4.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Dans le cadre de ce processus de recrutement, les candidatures seront trait\u00e9es au fur et \u00e0 mesure. CARE International au Cameroun se r\u00e9serve le droit de cl\u00f4turer le processus avant le terme.<\/p>\n\n\n\n<p>5.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Date de cl\u00f4ture de l\u2019offre&nbsp;:&nbsp;<strong><u>20 d\u00e9cembre 2023 \u00e0 17 heures pr\u00e9cises<\/u><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUNTBZQzdEVEU3U01HTTVZTjNYRFlSWVNWNS4u<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1139,1833,27,2554],"tags":[],"villes":[136],"contrats":[236],"diplomes":[159],"louma_meta":{"emploi_title":"Cinq (05) Conseillers-\u00e8res Technique \u2013 projet FM","emplois_employeur":2916,"emplois_date_publication":"2023-12-16","emplois_heure_publication":"","emplois_date_cloture":"2023-12-20","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"4","emploi_email":"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=tzMy6BNI9U-JP_YPQAv8ukobPkX4LxZEpqNGSp_clydUNTBZQzdEVEU3U01HTTVZTjNYRFlSWVNWNS4u   "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45519"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45519"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2917"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45519"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45519"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45519"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}