{"id":45461,"date":"2023-12-13T10:06:20","date_gmt":"2023-12-13T09:06:20","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=45461"},"modified":"2023-12-13T10:06:24","modified_gmt":"2023-12-13T09:06:24","slug":"warehouse-supervisor-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/warehouse-supervisor-2\/","title":{"rendered":"\u00a0Warehouse Supervisor"},"content":{"rendered":"\n<p><strong>MISSION PRINCIPALE<\/strong><br>Sous la supervision du Planning Manager, le Warehouse Supervisor a pour mission de :<\/p>\n\n\n\n<p>Coordonner les activit\u00e9s des Magasiniers sous sa responsabilit\u00e9,<br>Veiller \u00e0 la bonne tenue des op\u00e9rations de gestion de stock dans les magasins mati\u00e8res premi\u00e8res et conditionnements,<br>Assurer et animer les programmes relatifs \u00e0 l\u2019hygi\u00e8ne, la s\u00e9curit\u00e9 et \u00e0 l\u2019environnement des magasins et zones sous sa responsabilit\u00e9,<br>Coordonner toutes les activit\u00e9s de r\u00e9ception et de livraison des mati\u00e8res premi\u00e8res et emballages des diff\u00e9rents magasins.<\/p>\n\n\n\n<p><strong>QUE FEREZ-VOUS ?<\/strong><\/p>\n\n\n\n<p>Proposer toute \u00e9volution et d\u00e9terminer les moyens \u00e0 mettre en \u0153uvre permettant d\u2019assurer au mieux l\u2019ensemble des responsabilit\u00e9s qui incombent \u00e0 l\u2019activit\u00e9 du magasinier;<br>Organiser avec les achats et suivre les enl\u00e8vements des mati\u00e8res premi\u00e8res locales (Beurres, Tourteaux, ol\u00e9ine, st\u00e9arine);<br>S\u2019assurer de la conformit\u00e9 des quantit\u00e9s et qualit\u00e9 des mati\u00e8res premi\u00e8res mentionn\u00e9es r\u00e9ceptionn\u00e9es par rapport au bon de commande;<br>Assurer toutes les op\u00e9rations de saisies qui concourent aux diff\u00e9rents mouvements de stock dans le syst\u00e8me, hormis les livraisons usine;<br>Veiller \u00e0 l\u2019organisation et la rationalisation de l\u2019espace dans les diff\u00e9rents magasins dont il a la charge;<br>G\u00e9rer de fa\u00e7on proactive les mati\u00e8res premi\u00e8res \u00e0 DLV proche;<br>Tenir \u00e0 jour sur fichier Excel les tableaux r\u00e9ception des arachides par fournisseur, suivi du stock mensuel des arachides, tableaux de bord de suivi des activit\u00e9s des magasins;<br>Coordonner les diff\u00e9rentes op\u00e9rations avant, pendant et apr\u00e8s les inventaires p\u00e9riodiques;<br>A la demande du Planning Manager, r\u00e9aliser toute \u00e9tude ou recherche en rapport avec ses activit\u00e9s.<\/p>\n\n\n\n<p><strong>QUEL SERA VOTRE APPORT ?<\/strong><\/p>\n\n\n\n<p>Qualification : Minimum Bac+3 en logistique et transport \/ Supply chain management<\/p>\n\n\n\n<p>Exp\u00e9rience : Minimum 05 ann\u00e9es d&rsquo;exp\u00e9rience dans la supervision des op\u00e9rations de gestion de stocks et d&rsquo;entrep\u00f4ts.<\/p>\n\n\n\n<p><strong>Exigences particuli\u00e8res :<\/strong><br>-Bonnes notions de gestion des stocks,<br>-Bonnes connaissances informatiques (Word, Excel, Base de donn\u00e9es),<br>-Bonnes connaissances de l&rsquo;ERP Oracle,<br>-Respect des d\u00e9lais,<br>-Rigueur, efficacit\u00e9, int\u00e9grit\u00e9, discr\u00e9tion,<br>-Bonne expression \u00e9crite et orale en Fran\u00e7ais ou en Anglais,<br>-Avoir un Permis de conduire de cat\u00e9gorie B.<\/p>\n\n\n\n<p><strong>COMMENT POSTULER ?<\/strong><\/p>\n\n\n\n<p>Merci de nous transmettre votre CV et lettre de motivation (fichiers pdf) \u00e0 l&rsquo;adresse : Chococam.recruit@tigerbrands.com<br>NB: Bien vouloir indiquer l&rsquo;intitul\u00e9 du poste \u00e0 l&rsquo;objet.<br>Date limite : 13\/12\/2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via Chococam.recruit@tigerbrands.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[113,369],"tags":[],"villes":[135],"contrats":[148],"diplomes":[212],"louma_meta":{"emploi_title":" Warehouse Supervisor","emplois_employeur":5282,"emplois_date_publication":"2023-12-13","emplois_heure_publication":"10:06","emplois_date_cloture":"2023-12-27","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":"Chococam.recruit@tigerbrands.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45461"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45461"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5283"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45461"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45461"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45461"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}