{"id":45368,"date":"2023-12-07T20:30:42","date_gmt":"2023-12-07T20:30:42","guid":{"rendered":""},"modified":"2023-12-07T21:44:58","modified_gmt":"2023-12-07T20:44:58","slug":"assistante-de-direction-service-marketing","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/assistante-de-direction-service-marketing\/","title":{"rendered":"Assistant(e) de direction. Service marketing"},"content":{"rendered":"<p dir=\"ltr\" style=\"line-height: 1.38; margin-top: 12pt; margin-bottom: 12pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">OL POWER TECH SARL <\/span><span style=\"font-size: 10.5pt; font-family: Arial, sans-serif; color: #202124; background-color: #fafafa; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">recherche un(e) Assistant(e) de Direction talentueux(se) et dynamique pour renforcer son \u00e9quipe. D\u00e9marrage au 1er F\u00e9vrier 2024. Poste bas\u00e9 \u00e0 Yaound\u00e9.<\/span><\/p>\n<p><span><span><br \/>\n<\/span><\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; margin-top: 12pt; margin-bottom: 12pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">OL POWER TECH SARL est une soci\u00e9t\u00e9 camerounaise dont le si\u00e8ge social se trouve \u00e0 Yaound\u00e9 dont l\u2019objectif est la promotion, la distribution et la vente du mat\u00e9riel et accessoires pour l\u2019autoconsommation et la distribution des \u00e9nergies renouvelables dans les m\u00e9nages et les entreprises du secteur priv\u00e9 et public.<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-weight: bold; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Profil requis :<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Le (La) candidat(e) \u00e0 retenir :<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013&nbsp; &nbsp; Tranche d\u2019\u00e2ge : 25-35 ans<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013&nbsp; &nbsp; Est titulaire d\u2019un Bac+4\/5 en marketing, gestion d\u2019entreprise, droit, sciences \u00e9conomiques ou \u00e9quivalent<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; A une exp\u00e9rience professionnelle pr\u00e9alable, en Marketing Digital id\u00e9alement<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; A une bonne compr\u00e9hension de l\u2019organisation et du fonctionnement d\u2019une entreprise<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\">&nbsp;<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Savoir-faire :<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; Ma\u00eetrise des outils de marketing digital.<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; Organisation d\u2019\u00e9v\u00e9nements<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; Un excellent niveau de fran\u00e7ais et d\u2019anglais, \u00e0 l\u2019\u00e9crit comme \u00e0 l\u2019oral<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; Excellentes qualit\u00e9s r\u00e9dactionnelles<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: -1pt 0pt 11pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; \u00c0 l\u2019aise avec le pack office<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 11pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013 &nbsp; &nbsp; Dynamique, fiable et organis\u00e9(e)<\/span><\/p>\n<p><span><span><br \/>\n<\/span><\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; margin-top: 0pt; margin-bottom: 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; font-weight: bold; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">T\u00e2ches: entre autres\u2026<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: Roboto, sans-serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013<\/span><span style=\"font-size: 7pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">&nbsp; <\/span><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">G\u00e9rer l\u2019agenda quotidien de la direction g\u00e9n\u00e9rale : prise de RDV, traitement des courrier et e-mails, appels t\u00e9l\u00e9phoniques, cong\u00e9s\u2026<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: Roboto, sans-serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013<\/span><span style=\"font-size: 7pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"> &nbsp; &nbsp; <\/span><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Pr\u00e9parer et organiser les d\u00e9placements et la logistique des \u00e9v\u00e9nements professionnels ;<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: Roboto, sans-serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013<\/span><span style=\"font-size: 7pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\"> &nbsp; &nbsp; <\/span><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Effectuer des recherches sur des sujets sp\u00e9cifiques, collecter, traiter, synth\u00e9tiser et actualiser les informations pertinentes<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-indent: -18pt; text-align: justify; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 12pt 18pt;\"><span style=\"font-size: 12pt; font-family: Roboto, sans-serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013<\/span><span style=\"font-size: 7pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">&nbsp; &nbsp; &nbsp; <\/span><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Planifier la mise en \u0153uvre de projets, superviser et suivre le d\u00e9roulement desdits projets.<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: -1pt 0pt 11pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013&nbsp; &nbsp; Assistance aux activit\u00e9s commerciales telles prospections et promotions<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 11pt 0pt;\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u2013&nbsp; &nbsp; Cr\u00e9ation de contenu sur les r\u00e9seaux sociaux, publications et mise en jour.<\/span><\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; background-color: #ffffff; margin-top: 0pt; margin-bottom: 0pt; padding: 0pt 0pt 11pt 0pt;\">&nbsp;<\/p>\n<p><span id=\"docs-internal-guid-39193c83-7fff-99da-8964-e6ff53ab13a4\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #212529; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; vertical-align: baseline; white-space-collapse: preserve;\">Veuillez envoyer votre, CV et Lettre de motivation \u00e0 l\u2019adresse <\/span><a style=\"text-decoration-line: none;\" href=\"mailto:hr@bisnool.com\"><span style=\"font-size: 12pt; font-family: 'Times New Roman', serif; color: #1155cc; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; text-decoration-line: underline; text-decoration-skip-ink: none; vertical-align: baseline; white-space-collapse: preserve;\">hr@bisnool.com<\/span><\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OL POWER TECH SARL recherche un(e) Assistant(e) de Direction talentueux(se) et dynamique pour renforcer son \u00e9quipe. D\u00e9marrage au 1er F\u00e9vrier 2024. Poste bas\u00e9 \u00e0 Yaound\u00e9.&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[24],"tags":[],"villes":[136],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"Assistant(e) de direction. Service marketing","emplois_employeur":3046,"emplois_date_publication":"2023-12-07","emplois_heure_publication":"","emplois_date_cloture":"2024-01-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"hr@bisnool.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45368"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45368"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45368"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45368"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45368"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}