{"id":45279,"date":"2023-12-04T12:45:24","date_gmt":"2023-12-04T11:45:24","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=45279"},"modified":"2023-12-04T12:45:25","modified_gmt":"2023-12-04T11:45:25","slug":"comptables-niveau-i-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/comptables-niveau-i-2\/","title":{"rendered":"COMPTABLES NIVEAU I &amp; 2"},"content":{"rendered":"\n<p>APPEL A CANDIDATURES EXTERNES<br>Poste \u00e0 pourvoir DES &nbsp; COMPTABLES NIVEAU I &amp; 2<\/p>\n\n\n\n<p><br><strong>MISSIONS DU POSTE<\/strong><br>Assurer le rapprochement et la justification des comptes, la ma\u00eetrise des risques op\u00e9rationnels, le respect des r\u00e8ges comptables COBAC et des proc\u00e9dures .<br>Pr\u00e9parer et assurer la communication des reporting r\u00e8glementaires, du groupe BCP et des donn\u00e9es statistiques<br>Assurer le r\u00e8glement des factures des prestataires locaux et \u00e9trangers tout en veillant \u00e0 l&rsquo;application des normes comptables et fiscales ;<br><br>Participer aux missions des CAC et de la COBAC<br>&nbsp;&nbsp; &nbsp;Analyser &nbsp;&nbsp;&nbsp; suspens et proc\u00e9der aux r\u00e9gularisations ,<br>Identifier les anomalies comptables et d\u00e9clarer les incidents op\u00e9rationnels<br>&nbsp;&nbsp; &nbsp;Pr\u00e9parer $es \u00e9tats de synth\u00e8se sur les suspens pour les &nbsp;&nbsp;&nbsp; comit\u00e9s (DC, Audit<br>Produire les \u00e9tats financiers et notes annexes aux \u00e9tats financiers (\u00e9tat G &amp; H)<br>Produire le reporting CER8ER et autres \u00e9tats annexes (Evaluer ia conformit\u00e9 et\/ou mettre \u00e0 jour les comptes rendus d&rsquo;inventaires CRI CIB, CRI PAR, CRI R&rsquo;S etc&#8230;)<br>Effectuer les contr\u00f4les de coh\u00e9rence entre les donn\u00e9es de gestion des modules p\u00e9riph\u00e9riques\/int\u00e9gr\u00e9s et donn\u00e9es comptables<br>Assurer le traitement des r\u00e9clamations .<br>Participer aux travaux d&rsquo;arr\u00eat\u00e9s<br>Analyser les arr\u00eat\u00e9s comptables de fin de mois (agios, provisions,<br>Codification et saisie des factures. et r\u00e9alisation des rapprochements bancaires ,<\/p>\n\n\n\n<p><strong>PROFIL<\/strong><br>Dipl\u00f4me de I \u2018enseignement sup\u00e9rieur (BACC+ a minimum) Comptabilit\u00e9\/Finance\/ Audit et Contr\u00f4le de Gestion:<br>Exp\u00e9rience professionnelle au moins 12 mois ,<br>\u00catre \u00e2g\u00e9 de 40 ans maximum au 3 1\/ 12\/2023<br>Connaissances<br>Connaissance de l&rsquo;environnement bancaire,<br>Connaissance de la comptabilit\u00e9 bancaire et g\u00e9n\u00e9rale Maitrise du plan comptable bancaire PCEC-CDdAC:<br>Connaissance des r\u00e8glements COBAC et des proc\u00e9dures,<br>Maitrise de l&rsquo;outil informatique Suite MS Office et Amplitude Bank, SQL, Macro, Visual Basic)<br><strong>Savoir-faire et \u00eatre<\/strong><br>Aptitude \u00e0 la communication (interaction avec les utilisateurs de niveaux hi\u00e9rarchiques diff\u00e9rents, clients internes\/externes)<br>Capacit\u00e9 d&rsquo;adaptation ;<br>Rigueur, organisation et m\u00e9thode (pour le respect des \u00e9ch\u00e9ances et des proc\u00e9dures<\/p>\n\n\n\n<p>D\u00e9lai de recevabilit\u00e9 des candidatures : Jeudi 07 D\u00e9cembre 2023 \u00e0 16 heures 30 minutes<\/p>\n\n\n\n<p><br><strong>Canaux :<\/strong>&nbsp;Les candidatures devront \u00eatre achemin\u00e9es \u00e0 l&rsquo;adresse recrutement@bicec.com avec en objet la pr\u00e9cision du poste : Comptables Niveau 1 &amp; 2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  recrutement@bicec.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1594,282,23],"tags":[],"villes":[2714],"contrats":[148],"diplomes":[248,212],"louma_meta":{"emploi_title":"COMPTABLES NIVEAU I & 2","emplois_employeur":9679,"emplois_date_publication":"2023-12-04","emplois_heure_publication":"12:45","emplois_date_cloture":"2023-12-07","emplois_heure_cloture":"16:30","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":" recrutement@bicec.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45279"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45279"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/37715"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45279"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45279"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45279"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}