{"id":45077,"date":"2023-11-17T14:47:07","date_gmt":"2023-11-17T13:47:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=45077"},"modified":"2023-11-17T14:47:08","modified_gmt":"2023-11-17T13:47:08","slug":"responsable-detude-marketing","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/responsable-detude-marketing\/","title":{"rendered":"Responsable d&rsquo;\u00e9tude marketing"},"content":{"rendered":"\n<p>Nous sommes actuellement \u00e0 la recherche d&rsquo;un(e) responsable d&rsquo;\u00e9tude marketing. Sous la supervision g\u00e9n\u00e9rale du PDG de la Holding et la supervision directe du Directeur Marketing, le (la) titulaire du poste aura la responsabilit\u00e9 de :<\/p>\n\n\n\n<p>\u2022 Concevoir des plans d\u2019\u00e9tude (veille concurrentielle, satisfaction clients, parts de march\u00e9s, perception\u2026) : d\u00e9finition des outils (\u00e9tudes de march\u00e9 quantitatives et\/ou qualitatives), d\u00e9termination des moyens (\u00e9chantillon de consommateurs ou d\u2019utilisateurs, entretiens, enqu\u00eates, sondages, questionnaires\u2026).<\/p>\n\n\n\n<p>\u2022 Collecter, exploiter et analyser les informations (m\u00e9thode et techniques statistiques, r\u00e9alisation de tableaux crois\u00e9s dynamiques, traitement des donn\u00e9es en termes de la relation client, CRM\u2026).<\/p>\n\n\n\n<p>\u2022 R\u00e9diger les rapports de synth\u00e8se et d\u2019analyse, pr\u00e9sentation des r\u00e9sultats et recommandations pour orienter les d\u00e9cisions \u00e0 prendre.<\/p>\n\n\n\n<p>\u2022 Analyser l\u2019efficacit\u00e9 des politiques commerciales et marketing.<\/p>\n\n\n\n<p>\u2022 Proposer les strat\u00e9gies marketing d\u00e9coulant des \u00e9tudes (nouveaux produits, strat\u00e9gies tarifaires, offres promotionnelles, argumentaires de vente\u2026)<\/p>\n\n\n\n<p>\u2022 Initier et entretenir les relations avec les partenaires (institut de sondage, agence de publicit\u00e9, centre de documentation, enqu\u00eateurs\u2026).<\/p>\n\n\n\n<p>\u2022 Constituer et Actualiser r\u00e9guli\u00e8rement la base de donn\u00e9es de prospections pour un meilleur ciblage lors des actions de prospection Recueillir et mettre \u00e0 jour toutes les informations susceptibles de faire l&rsquo;objet de questions de la part du client.<\/p>\n\n\n\n<p>\u2022 Transmettre les informations utiles aux autres services comp\u00e9tents au sein de la Holding.<\/p>\n\n\n\n<p>Comment Postulez ? <\/p>\n\n\n\n<p>CV+ lettre de motivation \u00e0 l&rsquo;adresse suivante : recrutement@iccnet.cm<\/p>\n\n\n\n<p>Objet du mail \u00e0 respecter : Responsable d&rsquo;\u00e9tude marketing<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes actuellement \u00e0 la recherche d&rsquo;un(e) responsable d&rsquo;\u00e9tude marketing. Sous la supervision g\u00e9n\u00e9rale du PDG de la Holding et la supervision directe du Directeur&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[24],"tags":[],"villes":[136],"contrats":[234],"diplomes":[248,212],"louma_meta":{"emploi_title":"Responsable d'\u00e9tude marketing","emplois_employeur":15168,"emplois_date_publication":"2023-11-17","emplois_heure_publication":"","emplois_date_cloture":"2023-12-01","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@iccnet.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45077"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=45077"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/45077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/15170"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=45077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=45077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=45077"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=45077"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=45077"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=45077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}