{"id":44995,"date":"2023-11-15T10:20:30","date_gmt":"2023-11-15T09:20:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=44995"},"modified":"2023-11-15T10:20:32","modified_gmt":"2023-11-15T09:20:32","slug":"project-manager-pamppa","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/project-manager-pamppa\/","title":{"rendered":"Project Manager PAMPPA"},"content":{"rendered":"\n<p>Project Manager PAMPPA<br>Yaounde, Cameroon<br>Job Identification : 14607<br>Locations : Yaounde, Cameroon<br>Posting Date : 11\/08\/2023, 02:48 AM<br>Apply Before : 11\/21\/2023, 05:59 AM<br>Job Schedule : Full time<br>Agency : UNDP<br>Grade: NPSA-10<br>Vacancy Type : National Personnel Service Agreement<br>Practice Area : Management<br>Bureau : Regional Bureau for Africa<br>Contract Duration : 1 Year<br>Education &amp; Work Experience : Master&rsquo;s Degree &#8211; 5 year(s) experience OR Bachelor&rsquo;s Degree &#8211; 7 year(s) experience<br>Other Criteria : dans les domaines de l&rsquo;\u00e9conomie, planification, communication, \u00e9ducation ou tout autre domaine reconnu \u00e9quivalent sont requis.<br>Required Languages : francais<br>Desired Languages : english<br>Vacancy Timeline : 2 Weeks<br>https:\/\/estm.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_1\/job\/14607\/?utm_medium=jobshare<br>Copy Link<br>Job Description<br>Background<br><br>&nbsp;Le PNUD s\u2019engage \u00e0 recruter un personnel divers en termes de genre, de nationalit\u00e9 et de culture. Nous encourageons de m\u00eame les personnes issues des minorit\u00e9s ethniques, des communaut\u00e9s autochtones ou handicap\u00e9es \u00e0 postuler. Toutes les candidatures seront trait\u00e9es dans la plus stricte confidentialit\u00e9.<br><br>Le PNUD ne tol\u00e8re pas l\u2019exploitation et \/ ou les atteintes sexuelles, ni aucune forme de harc\u00e8lement, y compris le harc\u00e8lement sexuel, et \/ ou toutes formes de discrimination. Tous\/tes les candidats\/tes s\u00e9lectionn\u00e9s \/\u00e9es devront ainsi se soumettre \u00e0 de rigoureuses v\u00e9rifications relatives aux r\u00e9f\u00e9rences fournies ainsi qu\u2019\u00e0 leurs ant\u00e9c\u00e9dents<br><br><strong>Office\/Unit\/Project Description<\/strong><br>&nbsp;<br>Les le\u00e7ons apprises des pr\u00e9c\u00e9dents cycles de coop\u00e9ration entre le Cameroun et le Programme des Nations Unies pour le D\u00e9veloppement (PNUD) ont r\u00e9v\u00e9l\u00e9 l\u2019importance de la coordination administrative et technique. En plus de faciliter les relations et les \u00e9changes d\u2019informations entre les acteurs impliqu\u00e9s dans la mise en \u0153uvre, la coordination est un atout important pour l\u2019optimisation de l\u2019utilit\u00e9 des ressources mobilis\u00e9es. C\u2019est ainsi que le Projet d\u2019Appui \u00e0 la Mise en \u0153uvre du Programme Pays (PAMPPa) a \u00e9t\u00e9 mis en place pour accompagner et faciliter l\u2019ex\u00e9cution des interventions qui contribuent \u00e0 l\u2019atteinte des r\u00e9sultats.<br><br>Le PAMPPa a \u00e9t\u00e9 \u00e9labor\u00e9 en vue de fluidifier les processus programmatiques et d\u2019am\u00e9liorer l\u2019efficacit\u00e9 globale du programme de Coop\u00e9ration entre le Gouvernement du Cameroun et le PNUD. Ce projet d\u2019appui vise sp\u00e9cifiquement la promotion de la maitrise des processus de Gestion Ax\u00e9e sur les R\u00e9sultats \u00e0 tous les niveaux de la chaine d\u2019ex\u00e9cution des interventions. Le projet assurera l\u2019\u00e9valuation continue des besoins en capacit\u00e9s techniques et manag\u00e9riales des acteurs du Programme et de ses projets, l\u2019identification et la mise en \u0153uvre des actions de r\u00e9sorption des gaps.<br><br>En rapport au mandat du PNUD, le PAMPPa est charg\u00e9 de veiller \u00e0 la prise en compte des approches et principes programmatiques notamment (i) le genre, (ii) les droits humains, (iii) l\u2019inclusion de toutes les couches et cat\u00e9gories cibl\u00e9es, (iv) la collaboration effective avec les autres Agences du Syst\u00e8me des Nations Unies dans le cadre de l\u2019UNSDCF. Il prendra aussi en compte l\u2019alignement de toutes les interventions aux progr\u00e8s vers l\u2019atteinte des cibles des ODDs.<br><br>La mise en \u0153uvre du pr\u00e9sent projet d\u2019appui n\u00e9cessite une forte mobilisation et implication des entit\u00e9s nationales partenaires \u00e0 l\u2019ex\u00e9cution des projets appuy\u00e9s par le PNUD. Cette implication inclura diverses formes de collaboration (intellectuelle, technique, logistique, financi\u00e8re) mais aussi la mutualisation des autres formes de ressources.<br><br>Le projet coordonnera les r\u00e9flexions sur la mise en place d\u2019un m\u00e9canisme efficace de suivi-\u00e9valuation et de coordination, la communication et la mobilisation des ressources. Le projet d\u2019appui est ainsi appel\u00e9 \u00e0 jouer un r\u00f4le de facilitateur pour l\u2019acc\u00e9l\u00e9ration des progr\u00e8s vers l\u2019atteinte des r\u00e9sultats convenus entre le Gouvernement et le PNUD.<br><br>Pour assurer l\u2019animation du PAMPPa, les deux parties ont convenu de la n\u00e9cessit\u00e9 de faire recours \u00e0 une expertise technique ayant une exp\u00e9rience av\u00e9r\u00e9e dans la gestion de la fonction de coordination des Programmes de Coop\u00e9ration. D\u2019o\u00f9 la n\u00e9cessit\u00e9 de recruter un Conseiller Technique Principal pour accompagner techniquement ce projet comme le pr\u00e9voit l\u2019activit\u00e9 5 du produit 5 du document projet : \u00ab Capacit\u00e9s logistiques, organisationnelles, humaines et op\u00e9rationnelles des partenaires camerounais et du PNUD renforc\u00e9es : Capacit\u00e9s suppl\u00e9mentaires, recruter un CTP, un assistant administratif et financier et un chauffeur \u00bb.<br><br>Les pr\u00e9sents termes de r\u00e9f\u00e9rence sont \u00e9labor\u00e9s en vue du recrutement du CTP du PAMPPa et indiquent le but, les principales fonctions assign\u00e9es au poste, l\u2019expertise requise pour l\u2019exercice optimal de la fonction.<br><br>&nbsp;<br><strong>Scope of Work<\/strong><br><br>&nbsp;<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Affect\u00e9 aupr\u00e8s de l\u2019\u00e9quipe en charge de la coordination du Programme de Coop\u00e9ration Cameroun \u2013 PNUD dans les services de la Direction G\u00e9n\u00e9rale de la Coop\u00e9ration et de l\u2019int\u00e9gration r\u00e9gionale du MINEPAT, le Conseiller Technique Principal a pour missions de :<br><br>(a)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; assurer l\u2019animation de la fonction de coordination du Programme de Coop\u00e9ration ;<br><br>(b)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; faciliter les relations entre les acteurs du Programme et les services publics partenaires \u00e0<br><br>l\u2019ex\u00e9cution ;<br><br>(c)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; faciliter la gestion de la performance en partenariat avec les coordonnateurs des projets ;<br><br>(d)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; veiller \u00e0 la maitrise et l\u2019application des principes de la Gestion Ax\u00e9e sur les R\u00e9sultats pour tous les<br><br>projets ;<br><br>(e)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; faciliter les actions de renforcement des capacit\u00e9s aux profit des acteurs du Programme ;<br><br>(f)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; fluidifier la circulation de l\u2019information n\u00e9cessaire \u00e0 la prise de d\u00e9cision ;<br><br>(g)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; promouvoir la gestion de la performance dans toutes les unit\u00e9s op\u00e9rationnelles du Programme ;<br><br>(h)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; planifier et coordonner la mise en \u0153uvre des activit\u00e9s relatives aux fonctions de suivi, d\u2019\u00e9valuation<br><br>(revues p\u00e9riodiques) et de la gestion de la connaissance ;<br><br>(i)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; coordonner la production des rapports de performance du Programme.<br><br>&nbsp;<br><br>Institutional Arrangement<br><br>&nbsp;<br><br>Le Conseiller Technique Principal (CTP) travaillera principalement sous l\u2019autorit\u00e9 du Directeur National du Projet (DNP).&nbsp; Sa supervision sera assur\u00e9e par le Repr\u00e9sentant R\u00e9sident Adjoint du PNUD au Cameroun. Il travaillera en \u00e9troite collaboration avec le sp\u00e9cialiste en suivi-\u00e9valuation du PNUD et de toute autre acteur du Programme de Coop\u00e9ration.<br><br>&nbsp;<br><br>Comp\u00e9tences<br><br>&nbsp;<br><br>Expected Demonstration of Competencies<br><br>&nbsp;<br><br>Core<br>Achieve Results:<br><br>&nbsp;<br><br>LEVEL 3: Set and align challenging, achievable objectives for multiple projects, have lasting impact<br>Think Innovatively:<br><br>&nbsp;<br><br>LEVEL 3: Proactively mitigate potential risks, develop new ideas to solve complex problems<br>Learn Continuously<br><br>&nbsp;<br><br>LEVEL 3: Create and act on opportunities to expand horizons, diversify experiences<br>Adapt with Agility<br><br>&nbsp;<br><br>LEVEL 3: Proactively initiate and champion change, manage multiple competing demands<br>Act with Determination &nbsp;&nbsp;&nbsp; LEVEL 3: Think beyond immediate task\/barriers and take action to achieve greater results<br>Engage and Partner<br><br>&nbsp;<br><br>LEVEL 3: Political savvy, navigate complex landscape, champion inter-agency collaboration<br>Enable Diversity and Inclusion<br><br>&nbsp;<br><br>LEVEL 3: Appreciate benefits of diverse workforce and champion inclusivity<br>&nbsp;<br><br>Cross-Functional &amp; Technical competencies (insert up to 7 competencies)<br><br>Thematic Area&nbsp;&nbsp;&nbsp; Name&nbsp;&nbsp;&nbsp; Definition<br>Ethics&nbsp;&nbsp;&nbsp; UN policy knowledge &#8211; ethics&nbsp;&nbsp;&nbsp; Ethics UN policy knowledge &#8211; ethics Knowledge and understanding of the UN Staff Regulations and Rules and other policies relating to ethics and integrity<br>Strategic Thinking&nbsp;&nbsp;&nbsp; Strategic Thinking&nbsp;&nbsp;&nbsp; Ability to develop effective strategies and prioritized plans in line with UNDP\u2019s objectives, based on the systemic analysis of challenges, potential risks and opportunities; linking the vision to reality on the ground, and creating tangible solutions Ability to leverage learning from a variety of sources to anticipate and respond to future trends; to demonstrate foresight in order to model what future developments and possible ways forward look like for UNDP<br>Entrepreneurial Thinking&nbsp;&nbsp;&nbsp; Entrepreneurial Thinking&nbsp;&nbsp;&nbsp; Ability to create clarity around UNDP value proposition to beneficiaries and partners and to develop service offers responding to client needs based on UNDP\u2019s organizational priorities and mandate<br>Evaluation&nbsp;&nbsp;&nbsp; Evaluation&nbsp;&nbsp;&nbsp; Ability to make an independent judgement based on set criteria and benchmarks &#8211; Ability to anticipate client&rsquo;s upcoming needs and concerns.<br>Business Direction &amp; Strategy&nbsp;&nbsp;&nbsp; System Thinking&nbsp;&nbsp;&nbsp; Ability to use objective problem analysis and judgement to understand how interrelated elements coexist within an overall process or system, and to consider how altering one element can impact on other parts of the system<br>Effective Decision Making&nbsp;&nbsp;&nbsp; Effective Decision Making&nbsp;&nbsp;&nbsp;<br>Ability to take decisions in a timely and efficient manner in line with one\u2019s authority, area of expertise and resources<br><br>&nbsp;<br><br>&nbsp;<br><br>&nbsp;<br><br>&nbsp;<br><br>&nbsp;<br><br>Minimum Qualifications of the Successful NPSA<br><br>&nbsp;<br><br>Min. Academic Education&nbsp;&nbsp;&nbsp;<br>Master Degree ou \u00e9quivalent dans les domaines de l\u2019\u00e9conomie, planification, communication, \u00e9ducation ou tout autre domaine reconnu \u00e9quivalent est requis;<br>Ou<br><br>&nbsp;<br><br>Un dipl\u00f4me d\u2019\u00e9tude de premier cycle dans les domaines de l\u2019\u00e9conomie, planification, communication, \u00e9ducation ou tout autre domaine reconnu \u00e9quivalent avec 2 ann\u00e9es d\u2019exp\u00e9rience suppl\u00e9mentaires pourraient \u00eatre consid\u00e9r\u00e9s en lieu du dipl\u00f4me Master<br><br>&nbsp;<br><br>une sp\u00e9cialisation en question de d\u00e9veloppement et\/ou management des projets est un atout ;<br>Min. years of relevant Work experience &nbsp;&nbsp;&nbsp;<br>Minimum 05 ann\u00e9es (avec le dipl\u00f4me de Master) ou 7 ann\u00e9es (avec le Bachelor) d\u2019experiences professionnelles dans les domaines de l\u2019\u00e9conomie, planification, communication, \u00e9ducation ou tout autre domaine reconnu \u00e9quivalent sont requis.<br><br>&nbsp;<br><br>Avoir au moins 10 ans d\u2019exp\u00e9rience dans la n\u00e9gociation des accords de coop\u00e9ration (souhaitables)<br>Justifier des capacit\u00e9s de n\u00e9gociation et d\u2019interm\u00e9diation entre plusieurs parties ;<br>Avoir une bonne connaissance en informatique de base (Word, Excel, PowerPoint) ;<br>Required&nbsp;&nbsp; skills and competencies&nbsp;&nbsp;&nbsp;<br>Avoir accompagn\u00e9 la coordination des projets de coordination et\/ou avoir occup\u00e9 un poste de responsabilit\u00e9 d\u2019au moins rang de Chef de service dans l\u2019Administration Publique, pendant au moins dix (10) dans un ou plusieurs Minist\u00e8res en charge des questions de coordination des programmes et projets de d\u00e9veloppement serait un atout ;<br>Avoir une bonne connaissance de l\u2019\u00e9laboration des cadres de coop\u00e9ration avec le SNU et les agences EXCOM du SNU (UNDAF, CPD, CPAP, UNSDCF etc)&nbsp; serait un atout;<br>Avoir une bonne exp\u00e9rience de la conduite et de l\u2019approbation des documents de programme pays au niveau national et au conseil d\u2019administration des agences EXCOM&nbsp; est un atout;<br>Avoir une connaissance pratique av\u00e9r\u00e9e des proc\u00e9dures des Bailleurs de Fonds en g\u00e9n\u00e9ral, des Agences EXCOM du Syst\u00e8me des Nations Unies et\/ou du PNUD en particulier est un atout;<br>Une exp\u00e9rience av\u00e9r\u00e9e en formation et renforcement de capacit\u00e9 notamment dans le domaine du HACT et de la GAR&nbsp; est un atout;<br>Desired additional skills and competencies&nbsp;&nbsp;&nbsp;<br>Avoir une excellente capacit\u00e9 de leadership et de gestion des \u00e9quipes pluridisciplinaires et multiculturelles ;<br>\u00catre capable de d\u00e9velopper des relations constructives et durables entre le Gouvernement et les Partenaires Techniques et Financiers\/PNUD ;<br>\u00catre membre d\u2019un cadre de concertation d\u2019\u00e9laboration des rapports sur la mise en \u0153uvre des objectifs de d\u00e9veloppement durable (VNR) est un atout ;<br>\u00catre capable de travailler efficacement sous pression ;<br>Avoir une bonne capacit\u00e9 de r\u00e9daction des rapports ;<br>Une aptitude av\u00e9r\u00e9e au travail en \u00e9quipes, \u00e0 la direction d\u2019\u00e9quipes ainsi qu\u2019au renforcement de l\u2019esprit d\u2019\u00e9quipe ;<br>Avoir une excellente aptitude \u00e0 op\u00e9rer de mani\u00e8re pond\u00e9r\u00e9e, efficace et diplomatique dans un environnement d\u00e9licat et complexe ;<br>&nbsp;<br>Required Language(s) (at working level)&nbsp;&nbsp;&nbsp;<br>Avoir une bonne capacit\u00e9 de communication \u00e9crite et orale ;<br>Justifier de comp\u00e9tences av\u00e9r\u00e9es dans l\u2019usage du Fran\u00e7ais et de l\u2019Anglais (comme un atout) comme langue de travail.<br>Professional Certificates&nbsp;&nbsp;&nbsp; &nbsp;<br>&nbsp;<br><br>Dislaimer<br><br>Les candidatures f\u00e9minines sont fortement encourag\u00e9es.<br><br>Informations importantes pour les candidats<br><br>Tous les postes dans les cat\u00e9gories NPSA sont soumis \u00e0 un recrutement local.<br><br>Informations pour les candidats concernant le \u00ab Roster \u00bb du PNUD<br><br>Note : Le PNUD se r\u00e9serve le droit de s\u00e9lectionner un ou plusieurs candidats de cet avis de vacance.&nbsp; Nous pouvons \u00e9galement conserver les candidatures et prendre en consid\u00e9ration les candidats postulant \u00e0 ce poste pour d&rsquo;autres postes similaires au sein du PNUD, au m\u00eame niveau hi\u00e9rarchique et avec une description de poste, une exp\u00e9rience et des exigences \u00e9ducatives similaires.<br><br>Diversit\u00e9 de la main-d&rsquo;\u0153uvre<br><br>Le PNUD s&rsquo;engage \u00e0 assurer la diversit\u00e9 au sein de son personnel et encourage tous les candidats qualifi\u00e9s, ind\u00e9pendamment de leur sexe, de leur nationalit\u00e9, de leur handicap, de leur orientation sexuelle, de leur culture, de leur religion et de leur origine ethnique, \u00e0 postuler. Toutes les candidatures seront trait\u00e9es dans la plus stricte confidentialit\u00e9. Nous encourageons vivement les candidatures f\u00e9minines.<\/p>\n\n\n\n<p>LES D\u00c9P\u00d4TS DE CANDIDATURES SE FONT UNIQUEMENT SUR LE SITE WEB :&nbsp;<a href=\"https:\/\/estm.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_1\/requisitions\/job\/14607\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/estm.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_1\/requisitions\/job\/14607<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via https:\/\/estm.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_1\/requisitions\/job\/14607<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25,2989],"tags":[],"villes":[136],"contrats":[236],"diplomes":[159],"louma_meta":{"emploi_title":"Project Manager PAMPPA","emplois_employeur":4061,"emplois_date_publication":"2023-11-14","emplois_heure_publication":"","emplois_date_cloture":"2023-11-21","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"10","emploi_email":"https:\/\/estm.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_1\/requisitions\/job\/14607"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44995"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=44995"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4062"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=44995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=44995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=44995"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=44995"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=44995"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=44995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}