{"id":44934,"date":"2023-11-10T12:45:00","date_gmt":"2023-11-10T11:45:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=44934"},"modified":"2023-11-10T12:45:01","modified_gmt":"2023-11-10T11:45:01","slug":"six-06-moniteurs-rices-livelihoods-moyens-de-subsistance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/six-06-moniteurs-rices-livelihoods-moyens-de-subsistance\/","title":{"rendered":"Six (06) Moniteurs-rices Livelihoods (Moyens de subsistance)."},"content":{"rendered":"\n<p>La F\u00e9d\u00e9ration luth\u00e9rienne mondiale (FLM) ou The Lutheran World Federation (LWF)<br>est une communion mondiale d&rsquo;\u00e9glises de foi luth\u00e9rienne comprenant 148 \u00c9glises<br>membres dans 99 pays du monde entier, avec 77 millions de chr\u00e9tiens. L\u2019Entraide<br>Mondiale (World Service) repr\u00e9sente le service humanitaire et de d\u00e9veloppement de<br>la F\u00e9d\u00e9ration dont les actions sont d\u00e9finies autour de trois domaines cl\u00e9s : Les Moyens<br>de subsistance (Livelihoods), les Services de Qualit\u00e9 et la Protection &amp; Coh\u00e9sion<br>Sociale, qui incluent des axes transversaux comme la Justice Climatique, Justice de<br>Genre et le Plaidoyer pour le respect des Droits Fondamentaux.<br>La F\u00e9deration Lutherienne Mondiale a son si\u00e8ge \u00e0 Gen\u00e8ve en Suisse. Elle est<br>pr\u00e9sente au Cameroun depuis 2014 et intervient principalement dans les domaines de<br>moyens de subsistance (Livelihoods), Education, Paix et coh\u00e9sion sociale,<br>Environnement \/ Energie et, Eau, Hygi\u00e8ne et Assainissement (WASH) ; dans quatre<br>r\u00e9gions \u00e0 savoir : l\u2019Est, l\u2019Adamaoua, le Nord et l\u2019Extr\u00eame Nord avec un bureau de<br>repr\u00e9sentation \u00e0 Yaound\u00e9 dans la r\u00e9gion du Centre.<br>Dans le cadre du nouveau projet \u00ab Solutions bas\u00e9es sur la Nature &#8211; NBS \u00bb avec l\u2019appui<br>technique de \u00ab Canadian Lutheran World Relief \u00bb (CLWR) et l\u2019appui financier de<br>\u00ab Global Affairs Canada \u00bb (GAC), la FLM recrute :<br>Intitul\u00e9 du poste : Six (06) Moniteurs-rices Livelihoods (Moyens de subsistance).<br>Relevant : Officier Livelihoods<br>Lieu d\u2019affectation : D\u00e9partement du Logone et Chari<br>Dur\u00e9e du contrat : Une ann\u00e9e renouvelable selon la performance avec 3 mois de<br>p\u00e9riode d\u2019essai.<br>Objectif principal du poste :<br>Le Moniteur livelihoods est responsable de la mise en \u0153uvre et du suivi des activit\u00e9s<br>en moyens de subsistance sur le terrain.<br>Responsabilit\u00e9s sp\u00e9cifiques du poste :<br>\u27a2 Participer au processus de s\u00e9lection des b\u00e9n\u00e9ficiaires\/participants, aux<br>enqu\u00eates et autres \u00e9tudes (impact, march\u00e9, \u2026)<br>\u27a2 Structurer et former les b\u00e9n\u00e9ficiaires\/participants et accompagner les<br>groupements dans le d\u00e9veloppement des activit\u00e9s livelihoods.<br>\u27a2 Animer et suivre les activit\u00e9s des b\u00e9n\u00e9ficiaires\/participants.<br>\u27a2 Encadrer les relais communautaires\/personnes ressources de la communaut\u00e9<br>\u27a2 Participer \u00e0 la formation des b\u00e9n\u00e9ficiaires\/participants et des relais\/ personnes<br>ressources en moyens de subsistance.<br>\u27a2 Collecter et partager les donn\u00e9es et les informations de la zone de travail avec<br>le superviseur direct.<br>\u27a2 Encadre techniquement les b\u00e9n\u00e9ficiaires\/participants dans leurs activit\u00e9s<br>quotidiennes en moyens de subsistance.<br>\u27a2 Fournir les rapports hebdomadaires, mensuel et annuel.<br>\u27a2 Coordonner les activit\u00e9s dans la zone d\u2019intervention du Projet avec les services<br>\u00e9tatiques appropri\u00e9s et les autres acteurs.<br>\u27a2 Veiller sur la bonne gestion des biens et des \u00e9quipements au niveau du terrain.<br>\u27a2 Participer et superviser les diff\u00e9rentes distributions des kits\/intrants en moyens<br>de subsistance dans la zone du Projet.<\/p>\n\n\n\n<p>Qualifications requises<\/p>\n\n\n\n<ol><li>Dipl\u00f4me minimum de Technicien Sup\u00e9rieur (Bac+3) en agriculture,<br>d\u00e9veloppement rural, ou tout dipl\u00f4me reconnu \u00e9quivalent.<\/li><li>Bonne ma\u00eetrise du calendrier agricole et climatique de la zone du projet.<\/li><li>Tr\u00e8s bonne connaissance du fran\u00e7ais et une moyenne connaissance de<br>l\u2019anglais, la maitrise de la langue Arabe Choa constitue un atout.<\/li><li>Exp\u00e9rience requise : Au moins 2 ann\u00e9es d&rsquo;exp\u00e9rience professionnelle<br>av\u00e9r\u00e9e \u00e0 un poste similaire.<\/li><li>Esprit d&rsquo;\u00e9quipe et d\u2019\u00e9coute, aptitudes en construction de relations<br>interpersonnelles, leadership coop\u00e9ratif, flexibilit\u00e9 et excellentes<br>comp\u00e9tences en communication.<\/li><li>Comp\u00e9tences d\u00e9montr\u00e9es en organisation et gestion de travail, esprit<br>d\u2019initiative et capacit\u00e9s de travailler avec un maximum d\u2019autonomie.<br>Proc\u00e9dure de recrutement<br>\u2022 Le recrutement se fera selon la proc\u00e9dure suivante :<\/li><\/ol>\n\n\n\n<ul><li>D\u00e9pouillement des dossiers<\/li><li>Pr\u00e9s\u00e9lection des candidats<\/li><li>Test \u00e9crit\/ et ou entretien oral (Seulement les candidats pr\u00e9s\u00e9lectionn\u00e9s).<br>\u2022 Les dossiers de candidature sont compos\u00e9s de :<\/li><li>Un Curriculum vitae contenant trois (03) personnes de r\u00e9f\u00e9rence<br>mentionnant leurs e-mails et leurs contacts t\u00e9l\u00e9phoniques,<\/li><li>Une lettre de candidature adress\u00e9e au Repr\u00e9sentant Pays de FLM au<br>Cameroun,<\/li><li>Une lettre de motivation adress\u00e9e au Repr\u00e9sentant Pays de FLM au<br>Cameroun,<\/li><li>Un extrait de casier judiciaire bulletin num\u00e9ro 3 datant de moins de trois<br>mois,<\/li><li>Les copies des dipl\u00f4mes\/attestations de travail.<br>Comment postuler<br>\u2022 Les dossiers de candidature doivent mentionn\u00e9es le poste en objet, et<br>uniquement envoy\u00e9s par courriel \u00e0 l\u2019adresse :<br>procurement.cameroon@lutheranworld.org<br>\u2022 Les dossiers constitu\u00e9s seront scann\u00e9s version PDF et transf\u00e9r\u00e9s dans un seul<br>fichier. Les dossiers des candidats, dont les dossiers ne respecteront pas cette<br>instruction et dont le poste ne sera pas mentionn\u00e9 en objet de la messagerie,<br>ne seront pas trait\u00e9s.<br>\u2022 Les candidats pr\u00e9s\u00e9lectionn\u00e9s pr\u00e9senteront les originaux constituant leur<br>dossier de candidature au panel de recrutement avant de passer les tests.<br>\u2022 Le candidat d\u00e9finitivement retenu pr\u00e9sentera les originaux de ses dipl\u00f4mes<br>avant la signature du contrat de travail.<br>La date limite de d\u00e9p\u00f4t des candidatures est fix\u00e9e au 23 Novembre 2023 \u00e0 17 heures<br>pr\u00e9cises.<br>Fait \u00e0 Yaound\u00e9, le 09 Novembre 2023<br>Le Repr\u00e9sentant Pays &#8211; FLM Cameroun<br>Philbert HABONIMANA<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via procurement.cameroon@lutheranworld.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2993],"tags":[],"villes":[291],"contrats":[236],"diplomes":[212],"louma_meta":{"emploi_title":"Six (06) Moniteurs-rices Livelihoods (Moyens de subsistance).","emplois_employeur":4134,"emplois_date_publication":"2023-11-10","emplois_heure_publication":"12:44","emplois_date_cloture":"2023-11-23","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"procurement.cameroon@lutheranworld.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44934"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=44934"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4135"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=44934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=44934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=44934"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=44934"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=44934"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=44934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}