{"id":44405,"date":"2023-10-17T18:06:02","date_gmt":"2023-10-17T16:06:02","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=44405"},"modified":"2023-10-17T18:06:03","modified_gmt":"2023-10-17T16:06:03","slug":"un-01-senior-card-operations","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/un-01-senior-card-operations\/","title":{"rendered":"UN (01) Senior Card Operations"},"content":{"rendered":"\n<p>ECOBANK CAMEROUN S.A. recrute pour les besoins de ses services, UN (01) Senior Card Operations pouvant exercer sur tout le territoire national.<br><br>Ce poste est bas\u00e9 \u00e0 Douala.&nbsp;&nbsp;&nbsp; &nbsp;&nbsp;&nbsp; Job level: 4&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Job grade: 3C<br><br><strong>I.&nbsp; OBJECTIF DU POSTE<\/strong><br><br>\uf0d8&nbsp;&nbsp;&nbsp; Effectuer les op\u00e9rations de r\u00e8glements des tierces partie VISA \/MasterCard\/GIMAC etc\u2026<br>\uf0d8&nbsp;&nbsp;&nbsp; S\u2019assurer du bon d\u00e9nouement comptable des transactions d\u2019acquisition et de r\u00e8glement par carte et via les plateformes digitales<br>\uf0d8&nbsp;&nbsp;&nbsp; R\u00e9concilier les comptes de la mon\u00e9tique et des produits digitaux<br>\uf0d8&nbsp;&nbsp;&nbsp; Aider \u00e0 l\u2019am\u00e9lioration de la qualit\u00e9 de service de la banque<br>\uf0d8&nbsp;&nbsp;&nbsp; Diminuer ou intercepter les actes de fraudes internes<br>\uf0d8&nbsp;&nbsp;&nbsp; Permettre la continuit\u00e9 de l\u2019activit\u00e9 avec les cartes en agissant \u00e0 temps.<br>\uf0d8&nbsp;&nbsp;&nbsp; G\u00e9rer les op\u00e9rations des marchands en conformit\u00e9 avec les politiques du Groupe et les standards<br>\uf0d8&nbsp;&nbsp;&nbsp; Investiguer, \u00e9valuer, r\u00e9soudre et monitorer le processus de r\u00e9clamation li\u00e9e aux transactions d\u2019\u00e9mission et d\u2019acquisition<br><br><strong>II. RESPONSABILITES PRINCIPALES<\/strong><br>\uf0d8&nbsp;&nbsp;&nbsp; Effectuer les r\u00e8glements des parties tierces<br>\uf0d8&nbsp;&nbsp;&nbsp; Effectuer les r\u00e9conciliations journali\u00e8res des comptes de cartes et des produits digitaux et proc\u00e9der \u00e0 la liquidation des suspends<br>\uf0d8&nbsp;&nbsp;&nbsp; Prompt investigation et r\u00e9ponse aux r\u00e9clamations des clients.<br>\uf0d8&nbsp;&nbsp;&nbsp; Veiller \u00e0 l\u2019embarquement des comptes de produits digitaux sur nos plateformes de r\u00e9conciliations.<br>\uf0d8&nbsp;&nbsp;&nbsp; V\u00e9rifier, suivre avec la ligne Commerciale et r\u00e9pondre aux mails des transactions suspectes envoy\u00e9es par le groupe ;<br>\uf0d8&nbsp;&nbsp;&nbsp; Proposer\/initier la revue des proc\u00e9dures relatives \u00e0 la production des cartes, Produits digitaux et gestion des r\u00e9clamations.<br>\uf0d8&nbsp;&nbsp;&nbsp; Participer \u00e0 la supervision des activit\u00e9s des cartes.<br>\uf0d8&nbsp;&nbsp;&nbsp; Fournir les \u00e9l\u00e9ments de statistiques sur toutes les cartes et produits digitaux (cr\u00e9ation ; volume de transactions).<br>\uf0d8&nbsp;&nbsp;&nbsp; Veillez \u00e0 la production des rapports r\u00e9glementaires li\u00e9s \u00e0 cette activit\u00e9.<br>\uf0d8&nbsp;&nbsp;&nbsp; Pr\u00e9parer les dossiers de pr\u00e9financement sur les op\u00e9rations de cartes \u00e0 envoyer \u00e0 la Banque Centrale.<br>\uf0d8&nbsp;&nbsp;&nbsp; Effectuer toutes autres t\u00e2ches d\u00e9finies par la hi\u00e9rarchie.<\/p>\n\n\n\n<p><br><strong>III. LIGNE DE REPORTING<\/strong><br><br><strong>SUP\u00c9RIEUR HI\u00c9RACHIQUE:&nbsp;<\/strong>&nbsp;&nbsp;<br>\u2022&nbsp;&nbsp;&nbsp; Head Cards &amp; Digital Operations<br><br><br><strong>IV. PROFILE DE POSTE<\/strong><br><br><br><strong>Exp\u00e9rience &nbsp;<\/strong>&nbsp;&nbsp; \uf0d8&nbsp;&nbsp;&nbsp; Exp\u00e9rience d\u2019au moins 2 ans la mon\u00e9tique.<br>\uf0d8&nbsp;&nbsp;&nbsp; Bonne maitrise de la r\u00e8glementation des finances et des services bancaires en vigueur.<br><br><br><strong>\u00c9ducation<\/strong><br>&nbsp;&nbsp; &nbsp;\uf0d8&nbsp;&nbsp;&nbsp; Formation sup\u00e9rieure Bac + 4 de pr\u00e9f\u00e9rence Informatique de Gestion, Comptabilit\u00e9 finance ou autres disciplines connexes.<br>Qualit\u00e9s Personnelles&nbsp;&nbsp;&nbsp; \uf0d8&nbsp;&nbsp;&nbsp; Tr\u00e8s bonne maitrise de l\u2019outils Excellente<br>\uf0d8&nbsp;&nbsp;&nbsp; Bonne capacit\u00e9 d\u2019analyse<br>\uf0d8&nbsp;&nbsp;&nbsp; Excellentes aptitudes communicationnelles et du travail en \u00e9quipe<br>\uf0d8&nbsp;&nbsp;&nbsp; Capacit\u00e9 \u00e0 travailler de fa\u00e7on autonome sur des objectifs fix\u00e9s<br>\uf0d8&nbsp;&nbsp;&nbsp; Sens aigu du travail bien fait.<br>\uf0d8&nbsp;&nbsp;&nbsp; Innovation<br>\uf0d8&nbsp;&nbsp;&nbsp; Connaissance en gestion des risques<br>\uf0d8&nbsp;&nbsp;&nbsp; Bilingue Fran\u00e7ais\/Anglais serait un atout<br>\uf0d8&nbsp;&nbsp;&nbsp; Bonne maitrise de la r\u00e8glementation des finances et des services bancaires en vigueur.<br>\uf0d8&nbsp;&nbsp;&nbsp; Bonne maitrise de la r\u00e8glementation en mon\u00e9tique en vigueur<br><br><br><br><strong>V. PROCESSUS DE CANDIDATURE:<\/strong><br><br>Bien vouloir soumettre votre CV et lettre de motivation \u00e0 ECM-Recruit@ecobank.com&nbsp;&nbsp;au plus tard le 27 Octobre 2023 \u00e0 17h00 pr\u00e9cises, en mentionnant en objet \u00ab Senior Card Operations \u00bb<br>NB : Seules les candidatures correspondant aux crit\u00e8res de s\u00e9lection seront convoqu\u00e9es<br><br><em>ECOBANK CAMEROUN SA est une entreprise qui pr\u00f4ne l\u2019\u00e9galit\u00e9 des chances. Nous ne faisons pas de discrimination sur la base du genre, de la religion, de l\u2019appartenance ethnique, du statut social, de l\u2019aptitude physique, etc\u2026<\/em><br><br><br>Visitez notre site www.ecobank.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via ECM-Recruit@ecobank.com\u00a0<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[282,23,22],"tags":[],"villes":[135],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"UN (01) Senior Card Operations","emplois_employeur":4430,"emplois_date_publication":"2023-10-17","emplois_heure_publication":"17:05","emplois_date_cloture":"2023-10-27","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"ECM-Recruit@ecobank.com\u00a0"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44405"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=44405"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4443"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=44405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=44405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=44405"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=44405"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=44405"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=44405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}