{"id":44380,"date":"2023-10-16T23:34:03","date_gmt":"2023-10-16T23:34:03","guid":{"rendered":""},"modified":"2023-10-17T01:46:26","modified_gmt":"2023-10-16T23:46:26","slug":"developpeurse-react-native-experimentee-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/developpeurse-react-native-experimentee-2\/","title":{"rendered":"D\u00c9VELOPPEUR(S)E REACT-NATIVE EXP\u00c9RIMENT\u00c9(E)"},"content":{"rendered":"<h4 id=\"recherche-dune-d\u00e9veloppeurse-react-native-exp\u00e9riment\u00e9e\">RECHERCHE D\u2019UN(E) D\u00c9VELOPPEUR(S)E REACT-NATIVE EXP\u00c9RIMENT\u00c9(E)<\/h4>\n<p>iLink World Corporation, la plateforme num\u00e9rique au service de l&rsquo;inclusion financi\u00e8re , recrute un(e) <strong>D\u00e9veloppeur(s)e React-Native Exp\u00e9riment\u00e9(e)<\/strong>.<\/p>\n<p>Rejoins une \u00e9quipe passionn\u00e9e pour construire des solutions innovantes et efficaces pour faciliter l\u2019acc\u00e8s aux services financiers et soins de sant\u00e9.<\/p>\n<p>Pour en savoir plus sur iLink World Corporation, rendez sur notre site ilink-app.com et sur nos r\u00e9seaux :<\/p>\n<p>Facebook : @iLinkWorldCorporation | X : @IlinkWorld<\/p>\n<p><strong>Missions<\/strong><\/p>\n<ul>\n<li>Vous serez responsable de l\u2019architecture et de la r\u00e9alisation de plusieurs applications mobile<\/li>\n<li>Faire progresser le produit et aussi l\u2019\u00e9quipe sera votre ambition, gr\u00e2ce \u00e0 votre savoir-faire et votre volont\u00e9 d\u2019apprendre, te vous former<\/li>\n<li>Vous travaillerez avec d\u2019autres d\u00e9veloppeurs travaillant sur des parties diff\u00e9rentes du syst\u00e8me. De nombreuses interaction entre les diff\u00e9rentes \u00e9quipes sont donc requises<\/li>\n<li>Pour de meilleures performances, vous utiliserez les API native (Android surtout) pour une meilleure int\u00e9gration et pour obtenir de meilleure performance dans les applications<\/li>\n<li>Vous serez en charge de maintenir le code \u00e9crit par vous et par d\u2019autres, et utiliserez des tests automatiques pour en maintenir la qualit\u00e9.<\/li>\n<\/ul>\n<p><strong>Comp\u00e9tences requises<\/strong><\/p>\n<ul>\n<li>Ma\u00eetrise des technologies React Native, REST-full API, Techniques d&rsquo;optimisation, et du code partag\u00e9 entre les applications mobiles et le site web<\/li>\n<li>Connaissances solides de la programmation orient\u00e9e object<\/li>\n<li>Bonne connaissance IOS &amp; Android natifs pour certaines fonctionnalit\u00e9s cl\u00e9s<\/li>\n<li>Connaissance g\u00e9n\u00e9rale en m\u00e9thodologie agiles tel que SCRUM<\/li>\n<li>Exp\u00e9riment\u00e9 dans le travail \u00e0 distance<\/li>\n<\/ul>\n<p><strong>Profil recherch\u00e9<\/strong><\/p>\n<ul>\n<li>Minimum Bacc +2 en informatique<\/li>\n<li>\u00catre motiv\u00e9, curieux et force de proposition<\/li>\n<li>\u00catre autonome et avoir un tr\u00e8s bon esprit d\u2019\u00e9quipe<\/li>\n<\/ul>\n<p>Si vous \u00eates int\u00e9ress\u00e9(e) par cette offre, envoyez votre CV et lettre de motivation \u00e0 l\u2019adresse <a title=\"mailto:hiring@ilink-app.com\" href=\"mailto:hiring@ilink-app.com\" data-from-md=\"\">hiring@ilink-app.com<\/a> avant le 16 Octobre 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RECHERCHE D\u2019UN(E) D\u00c9VELOPPEUR(S)E REACT-NATIVE EXP\u00c9RIMENT\u00c9(E) iLink World Corporation, la plateforme num\u00e9rique au service de l&rsquo;inclusion financi\u00e8re , recrute un(e) D\u00e9veloppeur(s)e React-Native Exp\u00e9riment\u00e9(e). Rejoins une \u00e9quipe&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"open","template":"","categories":[22],"tags":[],"villes":[135],"contrats":[148],"diplomes":[212],"louma_meta":{"emploi_title":"D\u00c9VELOPPEUR(S)E REACT-NATIVE EXP\u00c9RIMENT\u00c9(E)","emplois_employeur":44376,"emplois_date_publication":"2023-10-16","emplois_heure_publication":"","emplois_date_cloture":"2023-10-16","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"hiring@ilink-app.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44380"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=44380"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/44377"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=44380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=44380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=44380"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=44380"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=44380"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=44380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}