{"id":44193,"date":"2023-10-10T18:21:50","date_gmt":"2023-10-10T16:21:50","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=44193"},"modified":"2023-10-10T18:21:52","modified_gmt":"2023-10-10T16:21:52","slug":"01-officier-ere-finance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/01-officier-ere-finance\/","title":{"rendered":"(01) Officier-\u00e8re Finance"},"content":{"rendered":"\n<p><a href=\"https:\/\/images-docs.minajobs.net\/Avis%20de%20recrutement%20d'un%20Officier%20Finance.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TELECHARGEZ LE DOCUMENT COMPLET EN CLIQUANT ICI<\/strong><\/a><\/p>\n\n\n\n<p>AVIS DE RECRUTEMENT<\/p>\n\n\n\n<p>La F\u00e9d\u00e9ration luth\u00e9rienne mondiale (FLM) ou The Lutheran World Federation (LWF)<br>est une communion mondiale d&rsquo;\u00e9glises de foi luth\u00e9rienne comprenant 148 \u00c9glises<br>membres dans 99 pays du monde entier, avec 77 millions de chr\u00e9tiens. L\u2019Entraide<br>Mondiale (World Service) repr\u00e9sente le service humanitaire et de d\u00e9veloppement de<br>la F\u00e9d\u00e9ration dont les actions sont d\u00e9finies autour de trois domaines cl\u00e9s : Les Moyens<br>de subsistance (Livelihoods), les Services de Qualit\u00e9 et la Protection &amp; Coh\u00e9sion<br>Sociale, qui incluent des axes transversaux comme la Justice Climatique, Justice de<br>Genre et le Plaidoyer pour le respect des Droits Fondamentaux.<br>La F\u00e9deration Lutherienne Mondiale a son si\u00e8ge \u00e0 Gen\u00e8ve en Suisse. Elle est<br>pr\u00e9sente au Cameroun depuis 2014 et intervient principalement dans les domaines de<br>moyens de subsistance (Livelihoods), Education, Paix et coh\u00e9sion sociale,<br>Environnement \/ Energie et, Eau, Hygi\u00e8ne et Assainissement (WASH) ; dans quatre<br>r\u00e9gions \u00e0 savoir : l\u2019Est, l\u2019Adamaoua, le Nord et l\u2019Extr\u00eame Nord avec un bureau de<br>repr\u00e9sentation \u00e0 Yaound\u00e9 dans la r\u00e9gion du Centre.<br>Dans le cadre du nouveau projet \u00ab Solutions bas\u00e9es sur la Nature &#8211; NBS \u00bb avec l\u2019appui<br>technique de \u00ab Canadian Lutheran World Relief \u00bb (CLWR) et l\u2019appui financier de<br>\u00ab Global Affairs Canada \u00bb (GAC), la FLM recrute :<br><strong>Intitul\u00e9 du poste :<\/strong>&nbsp;Un(e) (01) Officier-\u00e8re Finance<br><strong>Relevant :&nbsp;<\/strong>Finance Manager<br><strong>Lieu d\u2019affectation :<\/strong>&nbsp;Kousseri<br><strong>Dur\u00e9e du contrat&nbsp;<\/strong>: Une ann\u00e9e renouvelable selon la performance avec 3 mois de<br>p\u00e9riode d\u2019essai.<br><strong>Objectif principal du poste :<\/strong><br>L\u2019Officier-\u00e8re de Finance appuie la coordination de la zone dans la gestion globale des<br>op\u00e9rations financi\u00e8res et comptables y compris la gestion quotidienne du budget, la<br>production des rapports financiers et les paiements r\u00e9guliers. Il\/Elle sera responsable<br>de l\u2019application stricte des proc\u00e9dures financi\u00e8res et comptables de la FLM ainsi que<br>celle du donateur y compris la v\u00e9rification globale, le traitement des donn\u00e9es et le<br>contr\u00f4le interne de toutes les pi\u00e8ces des transactions du projet pour sa r\u00e9gion<br>d\u2019affectation. Il\/Elle appuiera la coordination de la zone dans la cl\u00f4ture mensuelle, la<br>v\u00e9rification et l&rsquo;examen des finances. Il\/elle aura la charge de la gestion de la<br>comptabilit\u00e9 du projet dans la r\u00e9gion et devra supporter le Coordinateur de zone dans<br>l\u2019\u00e9laboration et la mise \u00e0 jour du plan de d\u00e9penses en relation avec le plan d\u2019actions<br>d\u00e9taill\u00e9 des activit\u00e9s et le plan d\u2019approvisionnement du projet, pour s&rsquo;assurer qu&rsquo;il soit<br>complet et conforme aux normes et aux r\u00e9glementations de la FLM et ses bailleurs.<\/p>\n\n\n\n<p><a href=\"https:\/\/images-docs.minajobs.net\/Avis%20de%20recrutement%20d'un%20Officier%20Finance.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>TELECHARGEZ LE DOCUMENT COMPLET EN CLIQUANT ICI<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via procurement.cameroon@lutheranworld.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[282],"tags":[],"villes":[291],"contrats":[236],"diplomes":[159],"louma_meta":{"emploi_title":"(01) Officier-\u00e8re Finance","emplois_employeur":4134,"emplois_date_publication":"2023-10-10","emplois_heure_publication":"17:21","emplois_date_cloture":"2023-10-13","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"procurement.cameroon@lutheranworld.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44193"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=44193"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4135"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=44193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=44193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=44193"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=44193"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=44193"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=44193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}