{"id":44063,"date":"2023-09-29T13:01:47","date_gmt":"2023-09-29T11:01:47","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=44063"},"modified":"2023-09-29T13:01:48","modified_gmt":"2023-09-29T11:01:48","slug":"officier-logistique-transport","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/officier-logistique-transport\/","title":{"rendered":"Officier Logistique Transport"},"content":{"rendered":"\n<p>JOB DESCRIPTION<br>L\u2019Officier Logistique Transport et Asset a pour mission d\u2019assurer la mise en \u0153uvre au quotidien des responsabilit\u00e9s de la fonction logistique, et plus particuli\u00e8rement la gestion du transport et des Assets \u00e0 NRC Yaound\u00e9.<br><br><strong>RESPONSIBILITIES<\/strong><br><strong>I &#8211; Responsabilit\u00e9s g\u00e9n\u00e9rales<\/strong><br><br>Veiller au respect des politiques, manuels, directives et proc\u00e9dures op\u00e9rationnelles standard (SOP) de NRC et des exigences des bailleurs<br>Ex\u00e9cuter les fonctions logistiques d\u00e9l\u00e9gu\u00e9es conform\u00e9ment au plan d\u2019action<br>M\u00e8ner les activit\u00e9s logistiques op\u00e9rationnelles quotidiennes et assure leur suivi<br>Contribuer \u00e0 l\u2019administration des ressources afin que les livrables soient r\u00e9alis\u00e9s suivant les budgets, les d\u00e9lais et les normes \u00e9tablis<br>Pr\u00e9parer et \u00e9laborer des rapports logistiques suivant les demandes du bureau pays\/de zone<br>Contribuer \u00e0 l\u2019\u00e9laboration de SOP si besoin<br>Veiller au bon archivage de tous les documents justificatifs<br>Promouvoir et partager des id\u00e9es pour am\u00e9liorer la fonction logistique<br>&nbsp;<br><br><strong>II- Responsabilit\u00e9s sp\u00e9cifiques<\/strong><br><br><strong>1- Gestion de la flotte de v\u00e9hicule<\/strong><br><br>Organiser et planifier les d\u00e9placements du personnel sur le terrain par avion et par route<br>Veiller au respect de la proc\u00e9dure de gestion des v\u00e9hicules<br>Superviser et suivre l&rsquo;entretien global des v\u00e9hicules en lien avec les chauffeurs NRC et l&rsquo;agence des v\u00e9hicules de locations<br>Veiller \u00e0 ce que tous les documents et proc\u00e9dures juridiques relatifs aux v\u00e9hicules de toute la mission soient mis \u00e0 jour<br>Assurer l\u2019enregistrement des donn\u00e9es mensuelles des v\u00e9hicules de tout le parc de la mission dans le logiciel TERRAMAR<br>G\u00e9rer l\u2019\u00e9quipe des chauffeurs de la base dans leurs activit\u00e9s quotidiennes<br>Participer \u00e0 la formation g\u00e9n\u00e9rale continue des chauffeurs et tester r\u00e9guli\u00e8rement leurs connaissances<br>Remplir tous les documents n\u00e9cessaires pour le transport des marchandises<br>Assurer l\u2019archivage de tous les documents de gestion des v\u00e9hicules de la mission dans OFFICE 365 sur une base mensuelle<br>Fournir au sup\u00e9rieur hi\u00e9rarchique des pr\u00e9visions mensuelles en termes de maintenances des v\u00e9hicules et de toutes autres d\u00e9penses li\u00e9es aux v\u00e9hicules<br>Faire un retour d&rsquo;information imm\u00e9diat en cas d&rsquo;incident dans et autour de notre zone de travail au sup\u00e9rieur hi\u00e9rarchique<br><strong>2- Gestion des Assets &nbsp;<\/strong><br><br>Assure le maintien du fichier de suivi des actifs<br>Assure le suivi des mouvements des actifs de la mission<br>Assure l\u2019enr\u00e9gistrement et le suivi de tous les actifs de la mission<br>Participe \u00e0 la r\u00e9daction des rapports bailleurs sur les actifs<br>Participe \u00e0 la mise en \u0153uvre op\u00e9rationelle des proc\u00e9dure de gestion des actifs.<br>Prendre une part active aux rencontres p\u00e9riodiques de planification et de revue des activit\u00e9s de son d\u00e9partement<br>R\u00e9diger tous les rapports hebdomadaires et\/ou mensuels qui lui seront demand\u00e9s par le chef d\u2019\u00e9quipe ou le chef de d\u00e9partement dans les d\u00e9lais requis<br>Enum\u00e9rer les difficult\u00e9s rencontr\u00e9es sur la base et proposer des solutions pour leur r\u00e9solution<br><strong>QUALIFICATIONS<\/strong><br><strong>Comp\u00e9tences professionnelles g\u00e9n\u00e9rales :<\/strong><br><br>Avoir au moins une Licence en Logistique et Transport ou Dipl\u00f4me \u00e9quivalent<br>Exp\u00e9rience professionnelle comme Officier dans la logistique, charg\u00e9 des transport dans un contexte humanitaire<br>Bonne comnnaissance de la gestion des Assets<br>Exp\u00e9rience professionnelle ant\u00e9rieure dans des contextes complexes et instables.<br>R\u00e9sultats av\u00e9r\u00e9s sur les responsabilit\u00e9s du poste<br>La connaissance de l&rsquo;anglais est un atout<br>Aptitudes, connaissances et exp\u00e9riences sp\u00e9cifiques au contexte :<br><br>Ax\u00e9 sur les r\u00e9sultats<br>Bonne connaissance de Word, Excel, Powerpoint, teams et internet<br>Savoir s&rsquo;exprimer devant des audiences vari\u00e9es<br>Forte capacit\u00e9 r\u00e9dactionnelle<br>&nbsp;<br><br>Nous offrons:<br><br>CDD de 12 mois (avec possibilit\u00e9 d&rsquo;extension selon la disponibilit\u00e9 des fonds)<br>Salaire\/Avantages: Selon la grille salariale de NRC Cameroun<br>Lieu de travail: Yaound\u00e9<br>Assurance sant\u00e9: 90%<br>&nbsp;<br><br>Le NRC s&rsquo;engage activement en faveur de la diversit\u00e9 et de l&rsquo;inclusion et souscrit pleinement au principe de l&rsquo;\u00e9galit\u00e9 des chances.<br><br>Le recrutement est gratuit, le NRC ne demandera jamais de l&rsquo;argent dans le cadre d&rsquo;une proc\u00e9dure de recrutement.<br><br><br>JOB INFO<br>Job Identification<br>11983<br>Job Category<br>Logistics<br>Posting Date<br>09\/27\/2023, 10:56 AM<br>Apply Before<br>10\/10\/2023, 07:00 PM<br>Degree Level<br>Bachelor&rsquo;s Degree<br>Job Schedule<br>Full time<br>Locations<br>&nbsp;Yaounde<\/p>\n\n\n\n<p><strong>Postulez UNIQUEMENT en ligne via le formulaire disponible&nbsp; \u00e0 l&rsquo;adresse&nbsp; :&nbsp;&nbsp;<a href=\"https:\/\/ekum.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_2019\/requisitions\/preview\/12317\/?location=Cameroon&amp;locationId=300000000306624&amp;locationLevel=country\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/ekum.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_2019\/requisitions\/preview\/11983\/?location=Cameroon&amp;locationId=300000000306624&amp;locationLevel=country<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via \u00a0https:\/\/ekum.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_2019\/requisitions\/preview\/11983\/?location=Cameroon&amp;locationId=300000000306624&amp;locationLevel=country<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[113,369],"tags":[],"villes":[136],"contrats":[148],"diplomes":[212],"louma_meta":{"emploi_title":"Officier Logistique Transport","emplois_employeur":2921,"emplois_date_publication":"2023-09-29","emplois_heure_publication":"12:01","emplois_date_cloture":"2023-10-09","emplois_heure_cloture":"19:00","emplois_experience_min":"1","emplois_experience_max":"","emploi_email":"\u00a0https:\/\/ekum.fa.em2.oraclecloud.com\/hcmUI\/CandidateExperience\/en\/sites\/CX_2019\/requisitions\/preview\/11983\/?location=Cameroon&locationId=300000000306624&locationLevel=country"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44063"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=44063"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/44063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2923"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=44063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=44063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=44063"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=44063"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=44063"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=44063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}