{"id":43956,"date":"2023-09-26T09:59:07","date_gmt":"2023-09-26T07:59:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43956"},"modified":"2023-09-26T09:59:08","modified_gmt":"2023-09-26T07:59:08","slug":"04-cases-managers","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/04-cases-managers\/","title":{"rendered":"04 CASES MANAGERS"},"content":{"rendered":"\n<p>L&rsquo;Organisation HEALTH AND HUMAN RIGHTS CAMEROON, en abr\u00e9g\u00e9 \u00ab 2HRC\u00bb, est une organisation Camerounaise de participation au d\u00e9veloppent \u00e0 travers la promotion de l&rsquo;\u00e9ducation, de la sant\u00e9 et de l&#8217;emploi des couches vuln\u00e9rables ainsi que la lutte pour le respect des droits humains sans discrimination aucune. C&rsquo;est une association \u00e0 but non lucratif dont la cr\u00e9ation trouve son essence dans la volont\u00e9 et l&rsquo;engagement d&rsquo;un groupe de jeunes dynamiques de mettre fin aux maux qui minent la soci\u00e9t\u00e9 camerounaise et d&rsquo;ailleurs. Il est ainsi question d&rsquo;accompagner les organisations internationales et le gouvernement camerounais dans la mise en \u0153uvre des programmes et projets sp\u00e9cifiques en faveur des populations les plus expos\u00e9es aux risques, notamment dans les domaines des droits humains et de la sant\u00e9.<\/p>\n\n\n\n<p><strong>INTITULE DU POSTE : 4 CASE MANAGERS \/ Conseiller Psychosocial<\/strong><br>Dur\u00e9e de l&#8217;emploi : 12 mois renouvelable apr\u00e8s \u00e9valuation, une p\u00e9riode s&rsquo;essaie d&rsquo;au moins un mois sera observ\u00e9e.<br><strong>Objectif du poste<\/strong><br>Le\/la CIXI devra :<br>Mener les activit\u00e9s de suivi des b\u00e9n\u00e9ficiaires apr\u00e8s avoir fait leur Pr\u00e9 et Post test ;<br>Donner la bonne information sur le d\u00e9pistage au b\u00e9n\u00e9ficiaire ;<br>Superviser et \u00e9valuer les activit\u00e9s de pr\u00e9vention men\u00e9es par les pairs \u00e9ducateurs en strat\u00e9gie avanc\u00e9e ;<br>Tenir les registre P+ au jour le jour ;<br>Contribuer \u00e0 l&rsquo;atteinte des indicateurs pour augmenter le YEILD ;<br>Participer aux r\u00e9unions hebdomadaires de consortium et autres li\u00e9es au projet ;<br>S&rsquo;assurer du remplissage de fiches KP PREV produit par les pairs \u00e9ducateurs ;<br>Veiller \u00e0 l&rsquo;enregistrement syst\u00e9matique des donn\u00e9es dans COMECARE ;<br>\u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0 Assurer la distribution du mat\u00e9riel si n\u00e9cessaire ;<br>Le CPS doit travailler en collaboration le CR ;<br>\u00a0\u00a0 \u00a0 \u00a0\u00a0\u00a0 Intervenir dans toute autre activit\u00e9 o\u00f9 leurs comp\u00e9tences sont n\u00e9cessaires.<br><strong>PROFIL DE L&rsquo;EMPLOI<\/strong><br>Education\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>Une formation de niveau secondaire (au minimum niveau bac) et une formation en accompagnement psychosociale serait un atout.<br>Exp\u00e9rience requise\u00a0\u00a0\u00a0 Une exp\u00e9rience pr\u00e9alable d&rsquo;au moins deux ans dans\u00a0les\u00a0\u00a0\u00a0 activit\u00e9s\u00a0\u00a0\u00a0 de\u00a0\u00a0\u00a0 pr\u00e9ventions, d&rsquo;accompagnement et de suivi des P+;<br>Une exp\u00e9rience pertinente dans le travail dans une unit\u00e9 de prise en charge ; Le sens de l&rsquo;organisation;<br>Une bonne moralit\u00e9 ;<br>La capacit\u00e9 de travailler en \u00e9quipe;<br>Le sens de l&rsquo;initiative ;<br>La capacit\u00e9 de jugement;<br>\u00a0 Une parfaite ma\u00eetrise de la langue fran\u00e7aise et bonne connaissance de l&rsquo;anglais ;<br>\u00a0<br>\u00a0\u00a0 \u00a0\u2022 La ma\u00eetrise des logiciels tableurs et de traitement de texte ;<br>Avoir la capacit\u00e9 de travailler sous pression.<br>Aptitudes de leadership et de relations sociales particuli\u00e8res\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>\u00catre bon communicateur, r\u00e9ceptif, conciliateur, lent \u00e0 la col\u00e8re, sens de l&rsquo;innovation, pr\u00eat \u00e0 travailler sous pression et capacit\u00e9 d&rsquo;anticipation.<br>Crit\u00e8re de performance\u00a0\u00a0\u00a0 Atteinte des r\u00e9sultats<br>\u00a0<br>\u00a0<\/p>\n\n\n\n<p><strong>COMPOSITION DU DOSSIER DE CANDIDATURE :<\/strong><br>Une lettre de motivation sign\u00e9e et adress\u00e9e au Directeur Ex\u00e9cutif<br>Un CV d\u00e9taill\u00e9 sign\u00e9<br>Une photocopie du dernier dipl\u00f4me, attestation ou tout autre document probant<br>Une photocopie de la CNI.<br><strong>PROCESSUS DE RECRUTEMENT<\/strong><br>Test \/ et ou entretien<br><strong>D\u00c9P\u00d4T DE CANDIDATURE<\/strong><br>Dossier physique au si\u00e8ge de l\u2019Organisation \u00e0 EKOMBITIE I \u00e0 c\u00f4t\u00e9 de l\u2019\u00e9glise PPC<\/p>\n\n\n\n<p>ou par mail \u00e0 l\u2019adresse 2hrccameroon@gmail.com Tel : 697 914 697<\/p>\n\n\n\n<p>La date limite de d\u00e9p\u00f4t des dossiers est fix\u00e9e pour le jeudi 05 Octobre 2023 \u00e0 12 heures pr\u00e9cises.<br>&nbsp;&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  2hrccameroon@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[354],"tags":[],"villes":[144],"contrats":[236],"diplomes":[162],"louma_meta":{"emploi_title":"04 CASES MANAGERS","emplois_employeur":43953,"emplois_date_publication":"2023-09-26","emplois_heure_publication":"08:59","emplois_date_cloture":"2023-10-05","emplois_heure_cloture":"12:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":" 2hrccameroon@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43956"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43956"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/43954"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43956"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43956"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43956"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}