{"id":43854,"date":"2023-09-21T19:38:25","date_gmt":"2023-09-21T17:38:25","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43854"},"modified":"2023-09-21T19:38:27","modified_gmt":"2023-09-21T17:38:27","slug":"communicateur-trice-bilingue","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/communicateur-trice-bilingue\/","title":{"rendered":"Communicateur (trice) Bilingue"},"content":{"rendered":"\n<p><a><strong><u>RECRUTEMENT<\/u><\/strong><\/a><\/p>\n\n\n\n<p>L\u2019Institut Sup\u00e9rieur KALATA International (ISKA \u2013 International), Institut Priv\u00e9 d\u2019Enseignement Sup\u00e9rieur agr\u00e9e par le MINESUP et le MINEFOP lance le recrutement d\u2019une secr\u00e9taire bilingue et d\u2019un(e) communicateur (trice) bilingue<\/p>\n\n\n\n<p><a><strong>Lieu du travail<\/strong><\/a>&nbsp;: Yaound\u00e9<\/p>\n\n\n\n<p><strong>Date limite de candidature<\/strong>&nbsp;: 29 septembre 2023<\/p>\n\n\n\n<p><strong><u>Recrutement d\u2019un(e) communicateur (trice) bilingue<\/u><\/strong><\/p>\n\n\n\n<p><strong><u>Missions <\/u><\/strong><strong>:<\/strong><\/p>\n\n\n\n<ul><li>\u00c9laborer et proposer une strat\u00e9gie de communication pour l\u2019ISKA, avec \u00e0 l&rsquo;appui des plans d&rsquo;action annuels (actions de visibilit\u00e9) ;<\/li><li>G\u00e9rer les relations publiques (contacts avec les m\u00e9dias\u2026)<\/li><li>D\u00e9velopper les messages cl\u00e9s de communication destin\u00e9e au grand public, au gouvernement, aux bailleurs de fonds et partenaires au d\u00e9veloppement, et aux autres groupes cibles tels qu\u2019identifi\u00e9s dans la strat\u00e9gie de communication&nbsp;;<\/li><li>Assurer le suivi et \u00e9valuation de l\u2019impact des actions prises en mati\u00e8re de communication&nbsp;;<\/li><li>Contribuer \u00e0 la conceptualisation et au lancement des rapports de l\u2019ISKA ;<\/li><li>Concevoir, r\u00e9diger puis diffuser les diff\u00e9rents supports de communication (brochures, affiches, guides, journal interne, annonces presse, newsletters\u2026)&nbsp;;<\/li><li>Organiser les conf\u00e9rences de presse&nbsp;;<\/li><li>R\u00e9aliser ou faire r\u00e9aliser les supports et les actualiser : \u00e9crits, photos, fiches produits, catalogues, films, dossiers presse, campagne publicitaire&nbsp;;<\/li><li>Proposer des actions \u00e9v\u00e8nementielles, comme du sponsoring, et mettre l&rsquo;accent sur une communication m\u00e9diatique dynamique&nbsp;;<\/li><li>Assurer toutes autres t\u00e2ches \u00e0 lui confi\u00e9es par la hi\u00e9rarchie.<\/li><\/ul>\n\n\n\n<ol type=\"1\"><li><strong><u>Formation<\/u><\/strong><\/li><\/ol>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u00catre titulaire au moins d\u2019un Master ou \u00e9quivalent en Communication m\u00e9diatique, ou organisationnelle, ou tout autre domaine pertinent ;<\/p>\n\n\n\n<ul><li><strong><u>Comp\u00e9tences et exp\u00e9rience professionnelle<\/u><\/strong><strong>&nbsp;:<\/strong><\/li><\/ul>\n\n\n\n<ul><li>\u00catre \u00e2g\u00e9 (e ) de 25 ans minimum&nbsp;;<\/li><li>Avoir une parfaite ma\u00eetrise du fran\u00e7ais et de l\u2019anglais (orale et \u00e9crite)&nbsp;;<\/li><li>Justifier d\u2019une exp\u00e9rience professionnelle d\u2019au moins 3 ans dans le domaine de la communication m\u00e9diatique ou organisationnelle&nbsp;;&nbsp;<\/li><li>Avoir une bonne ma\u00eetrise des outils informatiques, des CMS et des m\u00e9dias sociaux, logiciels de traitement de photos, Internet et outils d\u2019\u00e9dition de contenu on-line<\/li><li>\u00catre dot\u00e9 de qualit\u00e9s r\u00e9dactionnelles et d\u2019une aisance orale et relationnelle&nbsp;;<\/li><li>Avoir une capacit\u00e9 d\u2019adaptation et le sens des responsabilit\u00e9s&nbsp;;<\/li><li>Savoir travailler sous pression ;<\/li><li>Avoir le sens de l\u2019\u00e9coute&nbsp;;<\/li><li>Esprit d\u2019\u00e9quipe et capacit\u00e9 \u00e0 travailler en mode projet&nbsp;;<\/li><li>\u00catre polyvalent, dynamique, cr\u00e9atif, curieux d\u2019esprit, pragmatique, disponible, diplomate, esprit de synth\u00e8se&nbsp;;<\/li><li>Cr\u00e9ativit\u00e9, curiosit\u00e9, organisation, souplesse, et capacit\u00e9 \u00e0 travailler avec des interlocuteurs vari\u00e9s (et parfois sensibles)&nbsp;;<\/li><li>Ma\u00eetrise des techniques de communication m\u00e9diatique et des r\u00e8gles d\u00e9ontologiques de&nbsp;&nbsp;&nbsp;&nbsp; la profession&nbsp;;<\/li><\/ul>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &#8211;&nbsp;&nbsp;&nbsp; Ma\u00eetrise d\u2019une autre langue serait un atout.<\/p>\n\n\n\n<ul><li><strong><u>Aptitudes<\/u><\/strong><strong>&nbsp;:<\/strong><\/li><li>Sens du respect des r\u00e8gles de la hi\u00e9rarchie&nbsp;;<\/li><li>Capacit\u00e9 de communication et facilit\u00e9s relationnelles&nbsp;;<\/li><li>Capacit\u00e9 d\u2019\u00e9coute, de conseil&nbsp;;<\/li><li>Excellence capacit\u00e9 d\u2019analyse, de synth\u00e8se et de reporting&nbsp;;<\/li><li>Capacit\u00e9 \u00e0 fournir un travail de qualit\u00e9 dans les d\u00e9lais&nbsp;;<\/li><li>Sens de l\u2019initiative, de l\u2019organisation et des responsabilit\u00e9s&nbsp;;<\/li><li>Polyvalence intellectuelle et professionnelle&nbsp;;<\/li><li>Proactivit\u00e9 et diligence&nbsp;;<\/li><li>Probit\u00e9 et int\u00e9grit\u00e9&nbsp;;<\/li><li>Capacit\u00e9 \u00e0 travailler en \u00e9quipe et sous pression&nbsp;;<\/li><li>Aptitude physique \u00e0 assurer efficacement les exigences du poste&nbsp;;<\/li><li>Sens aig\u00fce de la conscience professionnelle.<\/li><\/ul>\n\n\n\n<p><a><strong>Documents de candidature<\/strong><\/a><\/p>\n\n\n\n<p>Lettre de motivation manuscrite adress\u00e9e au Pr\u00e9sident Fondateur de l\u2019ISKA-International<\/p>\n\n\n\n<p>Curriculum Vitae d\u00e9taill\u00e9<\/p>\n\n\n\n<p>Photocopie du dipl\u00f4me le plus \u00e9lev\u00e9 et des certificats de travail<\/p>\n\n\n\n<p>Certificat de travail<\/p>\n\n\n\n<p>Des pi\u00e8ces compl\u00e9mentaires pourraient \u00eatre demand\u00e9es ult\u00e9rieurement.<\/p>\n\n\n\n<p><strong>D\u00e9lai et lieu du d\u00e9p\u00f4t de dossiers de candidature<\/strong><\/p>\n\n\n\n<p>Les dossiers de candidature sont r\u00e9ceptionn\u00e9s tous les jours ouvrables, entre 8h et 17h jusqu\u2019au vendredi 29 septembre 2023.<\/p>\n\n\n\n<p>Les personnes int\u00e9ress\u00e9es par cette offre d&#8217;emploi sont invit\u00e9es de d\u00e9poser leur dossier de candidature au secr\u00e9tariat de l\u2019ISKA &#8211; International, situ\u00e9 en face de l\u2019Institut Fran\u00e7ais, immeuble annexe de la CNPS, emprunter l\u2019ascenseur pour le 7\u00e8 \u00e9tage. Appeler le 690915585 en cas de besoin.<\/p>\n\n\n\n<p><strong><u>N.B<\/u><\/strong>&nbsp;: les candidatures f\u00e9minines sont fortement encourag\u00e9es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RECRUTEMENT L\u2019Institut Sup\u00e9rieur KALATA International (ISKA \u2013 International), Institut Priv\u00e9 d\u2019Enseignement Sup\u00e9rieur agr\u00e9e par le MINESUP et le MINEFOP lance le recrutement d\u2019une secr\u00e9taire bilingue&#8230;<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25],"tags":[],"villes":[136],"contrats":[148],"diplomes":[248],"louma_meta":{"emploi_title":"Communicateur (trice) Bilingue","emplois_employeur":3046,"emplois_date_publication":"2023-09-21","emplois_heure_publication":"18:38","emplois_date_cloture":"2023-09-29","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43854"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43854"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43854"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43854"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43854"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}