{"id":43769,"date":"2023-09-18T16:44:30","date_gmt":"2023-09-18T14:44:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43769"},"modified":"2023-09-26T16:14:45","modified_gmt":"2023-09-26T14:14:45","slug":"02-assistantes-commerciales-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/02-assistantes-commerciales-2\/","title":{"rendered":"02 Assistantes Commerciales"},"content":{"rendered":"\n<p>Nous recherchons deux(02) Assistantes Commerciales<\/p>\n\n\n\n<p>Elle devra \u00eatre \u00e0 Yaound\u00e9(Domicili\u00e9e non loin de Nkomkana) et \u00e0 Douala.<\/p>\n\n\n\n<p>Profil :<\/p>\n\n\n\n<ul><li>Ag\u00e9e de 24 ans et plus;<\/li><li>Connaissance moyenne en vente et marketing ;<\/li><li>Ma\u00eetrise de la langue fran\u00e7aise, un niveau; moyen en anglais serait un atout;<\/li><li>Tr\u00e8s bonne vendeuse .<\/li><\/ul>\n\n\n\n<p>Attributions :<\/p>\n\n\n\n<ul><li>Recevoir les clients et pr\u00e9senter les services de l\u2019entreprise<\/li><li>Gestion des commandes<\/li><li>Envoi des rapports de vente journalier, hebdo et mensuel<\/li><\/ul>\n\n\n\n<p>Pour postuler, nous faire parvenir votre:<\/p>\n\n\n\n<ul><li>CV;<\/li><li>Lettre de motivations.<\/li><\/ul>\n\n\n\n<p>\u00c0 <em>univers.venus18@gmail.com<\/em> avec object: ASSIST COM(Ville et quartier)<\/p>\n\n\n\n<p>Heures de travail: 8h30-18h Lundi \u00e0 samedi.<br>Salaire : 70 000; les commissions s&rsquo;en suivront avec&nbsp;l&rsquo;exp\u00e9rience.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous recherchons deux(02) Assistantes Commerciales Elle devra \u00eatre \u00e0 Yaound\u00e9(Domicili\u00e9e non loin de Nkomkana) et \u00e0 Douala. Profil : Ag\u00e9e de 24 ans et plus;&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[251,4067],"tags":[],"villes":[135,136],"contrats":[234],"diplomes":[163,162],"louma_meta":{"emploi_title":"02 Assistantes Commerciales","emplois_employeur":41032,"emplois_date_publication":"2023-09-18","emplois_heure_publication":"","emplois_date_cloture":"2023-10-02","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"univers.venus18@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43769"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43769"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/41033"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43769"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43769"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43769"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}