{"id":43751,"date":"2023-09-18T15:53:10","date_gmt":"2023-09-18T13:53:10","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43751"},"modified":"2023-09-18T15:53:11","modified_gmt":"2023-09-18T13:53:11","slug":"02-analystes-risque-et-credit","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/02-analystes-risque-et-credit\/","title":{"rendered":"02 ANALYSTES RISQUE ET CREDIT"},"content":{"rendered":"\n<p>LA REGIONALE BANK 1\u00e8re Institution financi\u00e8re cot\u00e9e \u00e0 la BVMAC recherche pour les besoins de ses services :<\/p>\n\n\n\n<p>NOUS RECRUTONS<br>DEUX ANALYSTES RISQUE ET CREDIT<br><strong>LA REGIONALE BANK<\/strong><br>MISSION G\u00c9N\u00c9RALE<br>Exercer les activit\u00e9s d\u2019analyse du risque cr\u00e9dit et divers en vue de r\u00e9duire les pertes au sein de<br>LA REGIONALE BANK<br>\u2022&nbsp;&nbsp; &nbsp;G\u00e9rer et att\u00e9nuer les risques associ\u00e9s aux pr\u00eats et aux engagements de cr\u00e9dit<br>\u2022&nbsp;&nbsp; &nbsp;Impl\u00e9menter les politiques, les proc\u00e9dures et les crit\u00e8res de souscription de cr\u00e9dit<br>Mener les analyses n\u00e9cessaires au maintien du syst\u00e8me de notation interne (Analyses qualitatives et quantitatives des contreparties&#8230;)<br>Participer aux travaux d&rsquo;appr\u00e9ciation du niveau de provisionnement des engagements et porter une<br>appr\u00e9ciation sur la gestion pr\u00e9visionnelle du co\u00fbt du risque de la Banque<br><br><strong>PROFIL<\/strong><br>&nbsp;&nbsp; &nbsp;Avoir un Bac + 4 en banque, finance, \u00e9conomie,<br>Math\u00e9matiques financi\u00e8res<br>\u2022&nbsp;&nbsp; &nbsp;Avoir un Dipl\u00f4me professionnel de l&rsquo;Institut Technique de Banque serait un atout<br>en pr\u00e9cisant le poste candidat\u00e9<br><br><strong>SAVOIR \u00caTRE&nbsp;<\/strong>&nbsp; &nbsp;<br>Capacit\u00e9s d\u2019analyse et de synth\u00e8se<br>Esprit critique, objectif et constructif<br>\u2022&nbsp;&nbsp; &nbsp;Disposer d&rsquo;une aisance \u00e0 \u00e9changer et \u00e0 argumenter Rigueur<br>\u2022&nbsp;&nbsp; &nbsp;Avoir le sens du risque, de l&rsquo;organisation et du travail en \u00e9quipe<br>\u2022&nbsp;&nbsp; &nbsp;Avoir une bonne capacit\u00e9 r\u00e9dactionnelle<br>\u2022&nbsp;&nbsp; &nbsp;\u00catre bilingue<br>\u2022&nbsp;&nbsp; &nbsp;Maitriser l&rsquo;outil informatique<\/p>\n\n\n\n<p><br><br><strong>Lieu de travail :&nbsp;<\/strong>dans tout le r\u00e9seau de LA REGIONALE BANK<br>Les&nbsp;&nbsp; CV&nbsp;&nbsp; seront envoy\u00e9s \u00e0 l\u2019adresse mail recrutements@laregionalebank.com&nbsp;au plus tard le 22&nbsp; septembre 2023&nbsp;en pr\u00e9cisant le poste candidat\u00e9.<\/p>\n\n\n\n<p><em>N.B : seuls les candidats remplissant les profils seront convoqu\u00e9s.<\/em><br><em>Rejoignez-nous pour lib\u00e9rer votre potentiel<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  recrutements@laregionalebank.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3636,2989,23],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"02 ANALYSTES RISQUE ET CREDIT","emplois_employeur":39723,"emplois_date_publication":"2023-09-18","emplois_heure_publication":"14:43","emplois_date_cloture":"2023-09-22","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":" recrutements@laregionalebank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43751"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43751"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/39724"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43751"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43751"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43751"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}