{"id":43655,"date":"2023-09-14T16:35:46","date_gmt":"2023-09-14T14:35:46","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43655"},"modified":"2023-09-14T16:35:48","modified_gmt":"2023-09-14T14:35:48","slug":"senior-finance-officer-performance-management-mi%ef%bf%bc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/senior-finance-officer-performance-management-mi%ef%bf%bc\/","title":{"rendered":"Senior Finance Officer \u2013 Performance Management &amp; MI\ufffc"},"content":{"rendered":"\n<p>\u00a0ECOBANK CAMEROUN S.A. recrute pour les besoins de ses services, UN (01) Senior Finance Officer \u2013 Performance Management &amp; MIS pouvant exercer sur tout le territoire national.<br><br>Ce poste est bas\u00e9 \u00e0 Douala.\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 Job level: 8\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Job grade: 4B<br><br><strong>I.\u00a0 OBJECTIF DU POSTE<\/strong><br><br>\uf0a7\u00a0\u00a0\u00a0 Prendre le lead pour le d\u00e9veloppement, la consolidation et le suivi du processus budg\u00e9taire<br>\uf0a7\u00a0\u00a0\u00a0 Veiller au d\u00e9veloppement et au respect des proc\u00e9dures de d\u00e9pense et d\u2019investissement<br>\uf0a7\u00a0\u00a0\u00a0 Suivre le reporting de performance par Segment, Client et par Agence<br>\uf0a7\u00a0\u00a0\u00a0 Abonner la revue analytique, le contr\u00f4le de gestion et l\u2019analyse du march\u00e9<br>\uf0a7\u00a0\u00a0\u00a0 Assurer la veille concurrentielle et une bonne mise en \u0153uvre des conditions de banque<br>\uf0a7\u00a0\u00a0\u00a0 Assister le CFO dans la pr\u00e9paration des rapports du Conseil d\u2019Administration et de l\u2019Assembl\u00e9e G\u00e9n\u00e9rale<br><br><br>II. RESPONSABILITES PRINCIPALES<br><br>\uf0a7\u00a0\u00a0\u00a0 R\u00e9diger le rapport mensuel d\u2019analyse des performances par Business Units, par client et Agences<br>\uf0a7\u00a0\u00a0\u00a0 Assurer le contr\u00f4le de gestion et le traitement des demandes d\u2019achats<br>\uf0a7\u00a0\u00a0\u00a0 Assurer la bonne mise en \u0153uvre des conditions de banques<br>\uf0a7\u00a0\u00a0\u00a0 G\u00e9rer mensuellement des provisions, amortissements et des charges comptabilis\u00e9es d\u2019avance<br>\uf0a7\u00a0\u00a0\u00a0 G\u00e9rer le registre des immobilisations de la banque et suivre le budget CAPEX<br>\uf0a7\u00a0\u00a0\u00a0 Veiller \u00e0 la fiabilit\u00e9 des informations sur les charges et revenus contenues dans les \u00e9tats financiers<br>\uf0a7\u00a0\u00a0\u00a0 Faire la revue mensuelle analytique des comptes (bilan, charges et produits)<br>\uf0a7\u00a0\u00a0\u00a0 Prendre le lead et suivi du processus budg\u00e9taire avec les business Units &amp; produits<br>\uf0a7\u00a0\u00a0\u00a0 Reporting de la performance des Business Units, produits, client et des agences.<br>\uf0a7\u00a0\u00a0\u00a0 Pr\u00e9parer et prendre le lead sur le Comit\u00e9 Marketing et de Business Review<br>\uf0a7\u00a0\u00a0\u00a0 S\u2019assurer de la mise \u00e0 jour du MIS (Management Information System) des clients<br>\uf0a7\u00a0\u00a0\u00a0 Suivre le param\u00e9trage des nouveaux produits de la banque dans le syst\u00e8me d\u2019exploitation<br>\uf0a7\u00a0\u00a0\u00a0 Veiller au d\u00e9veloppement et au respect des proc\u00e9dures en la mati\u00e8re<br>\uf0a7\u00a0\u00a0\u00a0 Suivre le reporting de performance par Segment, Client, produit et par Agences,<br>\uf0a7\u00a0\u00a0\u00a0 Abonner la revue analytique, le contr\u00f4le de gestion et l\u2019analyse du march\u00e9<br>\uf0a7\u00a0\u00a0\u00a0 Assister le CFO dans la pr\u00e9paration des reports du Conseil d\u2019Administration et de l\u2019AG<br>\uf0a7\u00a0\u00a0\u00a0 Autres t\u00e2ches confi\u00e9es par le CFO<br><br><br><strong>III. LIGNE DE REPORTING<\/strong><br><br>SUP\u00c9RIEUR HI\u00c9RACHIQUE:<br><br><br><strong>COLLABORATEURS DIRECTS:\u00a0\u00a0\u00a0<\/strong><br>\u2022\u00a0\u00a0\u00a0 Directeur Financier<br>\u2022\u00a0\u00a0\u00a0 Equipe de gestion de la performance, de reporting, Taxe et de gestion de Grands Livres (locale, r\u00e9gion et Groupe)<br><br><strong>IV. PROFILE DE POSTE<\/strong><br><br><br>Exp\u00e9rience \u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>\uf0a7\u00a0\u00a0\u00a0 Exp\u00e9rience de 5 ans dans le m\u00e9tier de la finance bancaire ou \u00e0 un poste similaire.<br>\uf0a7\u00a0\u00a0\u00a0 Tr\u00e8s bonne maitrise de Microsoft Office, \u00eatre \u00e0 l\u2019aise avec les chiffres, qualit\u00e9s techniques personnelles et manag\u00e9riales, une bonne exp\u00e9rience de l\u2019activit\u00e9, des produits bancaires et du traitement de reporting de performance et de pr\u00e9sentations.<br><br>\u00c9ducation<br>\u00a0\u00a0 \u00a0\u2022\u00a0\u00a0\u00a0 Avoir une licence, MBA ou une formation de Bac+4 ou Bac+5 en Science \u00e9conomique, Finance, Comptabilit\u00e9 ou Banque,<br>\u2022\u00a0\u00a0\u00a0 Le bilinguisme (fran\u00e7ais et anglais) est un atout<br>\u2022\u00a0\u00a0\u00a0 \u00catre un expert-comptable<br>Qualit\u00e9s Personnelles\u00a0\u00a0\u00a0 <\/p>\n\n\n\n<p>\u2022\u00a0\u00a0\u00a0 Sens de l\u2019organisation<br>\u2022\u00a0\u00a0\u00a0 Probit\u00e9 Morale<br>\u2022\u00a0\u00a0\u00a0 Capacit\u00e9 \u00e0 travailler sous pression et en toute autonomie<br>\u2022\u00a0\u00a0\u00a0 Sens de l\u2019initiative (Force de proposition)<br>\u2022\u00a0\u00a0\u00a0 Orient\u00e9 r\u00e9sultat<br>\u2022\u00a0\u00a0\u00a0 Coordination de l\u2019\u00e9quipe au sein du Service\u00a0<br>\u2022\u00a0\u00a0\u00a0 Interaction permanente avec les Business Units, la Direction G\u00e9n\u00e9rale, la R\u00e9gion et le Groupe<br><br><br>ECOBANK CAMEROUN SA est une entreprise qui pr\u00f4ne l\u2019\u00e9galit\u00e9 des chances. Nous ne faisons pas de discrimination sur la base du genre, de la religion, de l\u2019appartenance ethnique, du statut social, de l\u2019aptitude physique, etc\u2026<br><br>Visitez notre site www.ecobank.com<br><br><strong>IV.\u00a0 PROCESSUS DE CANDIDATURE :<\/strong><br>Bien vouloir transmettre votre CV et lettre de motivation \u00e0 ECM-Recruit@ecobank.com\u00a0au plus tard le vendredi 20 septembre 2023 \u00e0 17h\u00a0pr\u00e9cises en mentionnant en objet \u00ab\u00a0Senior Finance Officer \u2013 Performance Management &amp; MIS\u00a0\u00bb.<br><br>NB : Seules les candidatures correspondant aux crit\u00e8res de s\u00e9lection seront convoqu\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via  ECM-Recruit@ecobank.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3636,282,2989,23],"tags":[],"villes":[135],"contrats":[148],"diplomes":[212,159],"louma_meta":{"emploi_title":"Senior Finance Officer \u2013 Performance Management & MI","emplois_employeur":4430,"emplois_date_publication":"2023-09-14","emplois_heure_publication":"15:35","emplois_date_cloture":"2023-09-20","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":" ECM-Recruit@ecobank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43655"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43655"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4443"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43655"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43655"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43655"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}