{"id":43640,"date":"2023-09-14T15:36:39","date_gmt":"2023-09-14T13:36:39","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43640"},"modified":"2023-09-14T15:36:40","modified_gmt":"2023-09-14T13:36:40","slug":"responsable-de-department-trade-et-marches","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/responsable-de-department-trade-et-marches\/","title":{"rendered":"Responsable de D\u00e9partment Trade et March\u00e9s"},"content":{"rendered":"\n<p><strong>MISSION<\/strong><br>Sous la supervision du Directeur de la Tr\u00e9sorerie, le titulaire du poste aura pour mission la vente des produits et services financiers, la conservation des actifs, le contr\u00f4le des d\u00e9cisions OPC, respect des ratios r\u00e8glementaires, la Gestion des risques de liquidit\u00e9, du taux d&rsquo;int\u00e9r\u00eat, et d\u00e9veloppement du fonds de commerce institutions\u00a0 financi\u00e8res locales: banques, EMF, assurances entre autres.<br>PROFIL<br>&#8211;\u00a0\u00a0\u00a0 Bacc. +5 en finances et comptabilit\u00e9 ou gestion<br>&#8211;\u00a0\u00a0\u00a0 05 ans d&rsquo;exp\u00e9rience professionnelle<br>&#8211;\u00a0\u00a0\u00a0 Connaissances en Anglais et fran\u00e7ais<br>&#8211;\u00a0\u00a0\u00a0 Un excellent niveau en bureautique (Word, Excel, Powerpoint, Internet)<br>&#8211;\u00a0\u00a0\u00a0 Connaissance d l\u2019amplitude VIO;<br>&#8211;\u00a0\u00a0\u00a0 Bonne connaissance du march\u00e9 Bancaire;<br>&#8211;\u00a0\u00a0\u00a0 Techniques de ventes et de n\u00e9gociations;<br>&#8211;\u00a0\u00a0\u00a0 Techniques de Coordination et impulsion des activit\u00e9s commerciales; <\/p>\n\n\n\n<p>&#8211; Maitrise de la Gestion des risques de march\u00e9s, et op\u00e9rationnels &#8211; Capacit\u00e9 \u00e0 g\u00e9rer des \u00e9quipes:<br>&#8211;\u00a0\u00a0\u00a0 Autonomie La capacit\u00e9 \u00e0 prendre des positions sur le march\u00e9 mon\u00e9taire sur la base des diff\u00e9rents \u00e9tats et pr\u00e9visions; &#8211; Capacit\u00e9 relationnelle, capacit\u00e9 \u00e0 communiquer, capacit\u00e9 r\u00e9dactionnelle, int\u00e9grit\u00e9. &#8211; Sens commercial et exp\u00e9rience en client\u00e8le ; IV PRINCIPALES RESPONSABILIT\u00c9S (1)<\/p>\n\n\n\n<p><strong>RESPONSABILITES<\/strong><br>&#8211;&nbsp;&nbsp;&nbsp; La vente des produits li\u00e9s aux march\u00e9s financiers.<br>&#8211;&nbsp;&nbsp;&nbsp; Informer [&lsquo;OPC des op\u00e9rations relatives aux actifs conserv\u00e9s pour son compte<br>(op\u00e9rations li\u00e9es aux titres, aux esp\u00e8ces, r\u00e8glement\/livraison)<br>&#8211;&nbsp;&nbsp;&nbsp; Fournir \u00e0 la COSUMAF les informations obtenues dans le cadre de ses activit\u00e9s ;<br>&#8211;&nbsp;&nbsp;&nbsp; Etablir un rapport annuel \u00e0 la COSUMAF dans un d\u00e9lai de 3 mois apr\u00e8s la cl\u00f4ture de l&rsquo;exercice ;<br>&#8211;&nbsp;&nbsp;&nbsp; R\u00e9diger les proc\u00e9dures de contr\u00f4le de l&rsquo;activit\u00e9 ;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler la r\u00e9gularit\u00e9 des d\u00e9cisions d&rsquo;investissement ;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler I t\u00e9tablissement de la valeur liquidative ;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler la r\u00e9gularit\u00e9 des d\u00e9cisions d&rsquo;investissement;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler l&rsquo;\u00e9tablissement de la valeur liquidative ;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler les r\u00e8gles relatives au montant de l&rsquo;actif minimum de IOPC;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler l&rsquo;organisation comptable :<br>&#8211;&nbsp;&nbsp;&nbsp; Faire le suivi des r\u00e9gularisations des anomalies remont\u00e9es au gestionnaire : Informer l&rsquo;OPC, lorsque le capital social ou l iactif net atteigne la moiti\u00e9 du montant. Minimum pr\u00e9vu par la r\u00e9glementation ;<br>&nbsp; Respecter la s\u00e9gr\u00e9gation des comptes : Suivre les flux de liquidit\u00e9 de IOPC<br>&nbsp; Informer la COSUMAF de tous transferts des avoirs \u00e0 un autre d\u00e9positaire<br>&#8211;&nbsp;&nbsp;&nbsp; Participer aux \u00e9missions des titres sur le march\u00e9 primaire et animation du march\u00e9 secondaire des SVT; &#8211; G\u00e9rer les exigences du cahier de charges des SVT<br>&#8211;&nbsp;&nbsp;&nbsp; \u00catre le point focal des soci\u00e9t\u00e9s de gestion et autres interm\u00e9diaires financiers<br>&#8211;&nbsp;&nbsp;&nbsp; Prospecter les FCP existants pour \u00eatre leur d\u00e9positaire<br>&#8211; Coanimer le fond CCA PERFORMANCE ;<br>&#8211;&nbsp;&nbsp;&nbsp; Prospecter les soci\u00e9t\u00e9s de bourse non SVT pour passer leurs ordres ;<br>&#8211;&nbsp;&nbsp;&nbsp; Conserver les titres des Soci\u00e9t\u00e9s de bourses ainsi que ceux des autres clients<br>&#8211;&nbsp;&nbsp;&nbsp; Suivre le respect des ratios r\u00e9glementaires ;<br>&#8211;&nbsp;&nbsp;&nbsp; Suivre nos correspondants bancaires ;<br>&#8211;&nbsp;&nbsp;&nbsp; Suivre les relations avec les autorit\u00e9s mon\u00e9taires et de tutelles ;<br>&#8211;&nbsp;&nbsp;&nbsp; Suivre au quotidien la bonne fin de des op\u00e9rations;<br>&#8211;&nbsp;&nbsp;&nbsp; Rechercher des nouveaux correspondants bancaires.<\/p>\n\n\n\n<p>Poste bas\u00e9 \u00e0 : Douala<br>D\u00e9lai de d\u00e9p\u00f4t des candidatures :&nbsp;au plus tard le 18 Septembre 2023 \u00e0 17h00<br>Les CVS (version PDF) sont recevables uniquement via l&rsquo;adresse recrutement@cca-bank.com avec pour objet : \u00ab VOTRE-NOM_RDTM_SEPTEMBRE_2023&Prime;<br>Seuls les candidats s\u00e9lectionn\u00e9s seront convoqu\u00e9s pour la suite du processus de recrutement.<br>La Direction G\u00e9n\u00e9rale<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement@cca-bank.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[282,23],"tags":[],"villes":[135],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"Responsable de D\u00e9partment Trade et March\u00e9s","emplois_employeur":3887,"emplois_date_publication":"2023-09-14","emplois_heure_publication":"14:36","emplois_date_cloture":"2023-09-18","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":"recrutement@cca-bank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43640"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43640"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43640"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43640"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43640"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}