{"id":43580,"date":"2023-09-12T10:33:06","date_gmt":"2023-09-12T08:33:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43580"},"modified":"2023-09-12T10:33:07","modified_gmt":"2023-09-12T08:33:07","slug":"vendeurs-professionnels-et-experimentes","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/vendeurs-professionnels-et-experimentes\/","title":{"rendered":"VENDEURS PROFESSIONNELS ET EXP\u00c9RIMENT\u00c9S"},"content":{"rendered":"\n<ol type=\"1\"><li>Soci\u00e9t\u00e9\u00a0: LA CUISINE DES SAVEURS SARL, situ\u00e9 \u00e0 Yaound\u00e9, au centre ville<\/li><li>Nous recherchons des jeunes de deux sexes dans l\u2019expansion de notre activit\u00e9 sur le march\u00e9 camerounais.<\/li><li>Mission\u00a0: vente de jus de fruits conserver dans les gamelles, partout dans les bureaux, les milieux responsables<\/li><li>La proposition salariale sera au choix de l\u2019employ\u00e9, soit par semaine, par deux semaines, par mois.<\/li><li>Votre responsabilit\u00e9\u00a0: conqu\u00e9rir les clients, prospection, rendement, SAV, \u00eatre entrepreneure, responsables, souriant, accueillir<\/li><li>Horaires du travail, lundi \u00e0 vendredi, 07h30-12h ou par expansion<\/li><li>Objectif\u00a0: 20 gamelles par jour ou une moyenne de 15 sera tol\u00e9rable<\/li><li>Date limite le 30 septembre<\/li><li>Au moins, CAP, probatoire ou baccalaur\u00e9at en vente ou gestion, ou CGL,<\/li><li>AUGMENTATION DE SALAIRE APR\u00c8S UNE P\u00c9RIODE DE 06 MOI<\/li><li>Postuler via <a href=\"mailto:Jacques_piimmbadi@yahoo.fr\">Jacques_piimmbadi@yahoo.fr<\/a> ou <a href=\"mailto:Ritamere@gmail.com\">Ritamere@gmail.com<\/a> ou via WhatsApp au 695081887<\/li><li>Nombre de places\u00a0:5<\/li><li>Lettre de motivation, CV, PHOTOCOPIE DE LA CNI, PLAN DE LOCALISATION<\/li><li>MODALIT\u00c9S DE SALAIRE A N\u00c9GOCI\u00c9 \u00c0 L\u2019ENTRETIEN<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via Jacques_piimmbadi@yahoo.fr ou Ritamere@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,1273],"tags":[],"villes":[136],"contrats":[155],"diplomes":[162,158],"louma_meta":{"emploi_title":"VENDEURS PROFESSIONNELS ET EXP\u00c9RIMENT\u00c9S","emplois_employeur":3046,"emplois_date_publication":"2023-09-12","emplois_heure_publication":"10:33","emplois_date_cloture":"2023-09-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"Jacques_piimmbadi@yahoo.fr ou Ritamere@gmail.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43580"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43580"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43580"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43580"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43580"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}