{"id":43527,"date":"2023-09-08T15:17:09","date_gmt":"2023-09-08T13:17:09","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43527"},"modified":"2023-09-08T15:17:10","modified_gmt":"2023-09-08T13:17:10","slug":"02-stagiaires-dans-le-marketing","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/02-stagiaires-dans-le-marketing\/","title":{"rendered":"02 Stagiaires dans le Marketing"},"content":{"rendered":"\n<p>Nous, KOLA ACADEMY, recherchons 02 Stagiaires dans le Marketing .<\/p>\n\n\n\n<p>MISSIONS :<\/p>\n\n\n\n<p>Sous la supervision du responsable des op\u00e9rations, les stagiaires auront pour missions :<br>\u2022 \u00c9laborer une strat\u00e9gie de communication et commercialisation, planifier et suivre les actions;<br>\u2022 G\u00e9rer les campagnes marketing ;<br>\u2022 G\u00e9rer le portefeuille clients;<br>\u2022 Organiser la prospection cibl\u00e9e et non cibl\u00e9e;<br>\u2022 Faire la Prospecter terrain, num\u00e9rique et t\u00e9l\u00e9phonique;<br>\u2022 Prospection \/ vente \/ suivi client\u00e8le<br>\u2022 Faire de l\u2019animation \u00e9v\u00e8nementielle<br>\u2022 Participer \u00e0 l\u2019\u00e9laboration de nouveaux supports d\u2019aide \u00e0 la vente;<br>\u2022 Faire un REPORTING journalier des actions men\u00e9es.<\/p>\n\n\n\n<p>PROFIL ET EXIGENCE(S) :<\/p>\n\n\n\n<p>\u2022 \u00catre titulaire d&rsquo;un BACCALAUR\u00c9AT ou \u00eatre \u00e9tudiant(e) r\u00e9guli\u00e8rement inscrit, Licence cours du soir dans les fili\u00e8res Marketing ou Vente \/ Action Commerciale\/ Marketing Digital\/Community Management.<br>\u2022 \u00catre disponible durant toute la dur\u00e9e du stage (6 mois renouvelable)<br>\u2022 Maitriser Word, Excel, PowerPoint, etc.<br>\u2022 Poss\u00e9der des aptitudes r\u00e9dactionnelles importantes<br>\u2022 Avoir des connaissances en mati\u00e8re de techniques li\u00e9es \u00e0 la communication digitale;<br>\u2022 Savoir utiliser les logiciels tels que Photoshop et Publisher serait un atout<br>\u2022 Avoir l\u2019esprit d\u2019initiative de m\u00eame que l\u2019esprit d\u2019apprendre<br>\u2022 \u00catre capable de travailler efficacement en \u00e9quipe et sous pression<br>\u2022 Avoir un bon relationnel<\/p>\n\n\n\n<p>DUREE : 06 MOIS RENOUVELABLE<\/p>\n\n\n\n<p>LIEU DE POSTE : BONAMOUSSADI \u2013 DOUALA<\/p>\n\n\n\n<p>COMPOSITION DU DOSSIER :<br>\u2022 Lettre de motivation<br>\u2022 CV d\u00e9taill\u00e9 (au format PDF exclusivement)<\/p>\n\n\n\n<p>DEPOT DE CANDIDATURE :<\/p>\n\n\n\n<p>A l\u2019adresse: recrutement@kola-academy.com<\/p>\n\n\n\n<p>D\u00e9lai de recevabilit\u00e9 des candidatures : 15 Septembre 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via recrutement@kola-academy.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,24,1273],"tags":[],"villes":[135],"contrats":[152],"diplomes":[162,212],"louma_meta":{"emploi_title":" 02 Stagiaires dans le Marketing ","emplois_employeur":22214,"emplois_date_publication":"2023-09-08","emplois_heure_publication":"14:16","emplois_date_cloture":"2023-09-15","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@kola-academy.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43527"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43527"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/22215"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43527"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43527"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43527"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}