{"id":43503,"date":"2023-09-08T13:30:59","date_gmt":"2023-09-08T11:30:59","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43503"},"modified":"2023-09-08T13:31:29","modified_gmt":"2023-09-08T11:31:29","slug":"directeur-daudit-interne","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/directeur-daudit-interne\/","title":{"rendered":"Directeur d&rsquo;Audit Interne"},"content":{"rendered":"\n<p>APPEL A<br>CANDIDATURE<\/p>\n\n\n\n<p>Il est ouvert au sein de CCA-Bank le poste de<br>Directeur d&rsquo;Audit Interne<\/p>\n\n\n\n<p>MISSION; Rattach\u00e9 au Conseil d\u2019Administration de CCA BANK S.A, le titulaire du poste aura pour mission  fondamentale d&rsquo;aider &lsquo;organisation a atteindre ses objectifs en \u00e9valuant par une approche<br>syst\u00e9matique et m\u00e9thodique, ses processus de managements des risques, de controle, et de<br>gouvernement d&rsquo;entreprise, et en faisant des propositions pour renforcer leur efficacit\u00e9..<\/p>\n\n\n\n<p>PROFIL I<\/p>\n\n\n\n<ul><li>Dipl\u00e9me : BAC+4\/5 en science de gestion, ITB management bancaire, ou tout autre diplome<br>\u00e9quivalent ;<\/li><li>Exp\u00e9rience : minimum sept (07) ans en audit interne ;<\/li><li>Avoir de tr\u00e9s bonne connaissance en pratiques de gouvernance et de gestion ;<\/li><li>Avoir une tr\u00e9s bonne connaissance de l&rsquo;environnement, de la r\u00e9glementation et des m\u00e9tiers de<br>la banque;<\/li><li>Avoir une tr\u00e9s bonne connaissance en m\u00e9thodes d&rsquo;\u00e9valuation des risques et des controles y aff\u00e9rents ;<\/li><li>Avoir une bonne connaissance de la d\u00e9ontologie et des normes de l&rsquo;audit interne ;<\/li><li>Maitriser les techniques r\u00e9dactionnelles et la communication orale ;<\/li><li>Bonne connaissance de l&rsquo;environnement r\u00e9glementaire, des cadres de r\u00e9f\u00e9rence d&rsquo;audit et controle ;<\/li><li>Avoir une tr\u00e9s bonne culture comptable et financi\u00e9re ;<\/li><li>Avoir de solides connaissances en comptabilit\u00e9 budg\u00e9taire et analytique, normes ;<\/li><li>Avoir une bonne maitrise des outils d&rsquo;analyse des donn\u00e9es;<\/li><li>Maitrise des outils de reporting.<\/li><\/ul>\n\n\n\n<p>IL\/ELLE DOIT AVOIR<\/p>\n\n\n\n<ul><li>Sens de I&rsquo;\u00e9coute et de synth\u00e9se ;<\/li><li>Rigueur, int\u00e9grit\u00e9 et ouverture d&rsquo;esprit ;<\/li><li>Capacit\u00e9s manage\u00e9riales et qualit\u00e9s relationnelles<\/li><li>Capacit\u00e9 a travailler en \u00e9quipe ;<\/li><li>Organisation et planification ;<\/li><li>Avoir l&rsquo;esprit critique ;<\/li><li>Sens de &lsquo;am\u00e9lioration et de l&rsquo;innovation ;<\/li><li>Avoir un grand sens relationnel ;<\/li><li>Aptitude a apprendre et a s&rsquo;adapter ;<\/li><li>Esprit d&rsquo;analyse et du d\u00e9tail<\/li><li>Capacit\u00e9 a faire une bonne appr\u00e9ciation des risques et des contr\u00e9les ;<\/li><li>Sens de I&rsquo;\u00e9thique et la discr\u00e9tion ;<\/li><li>Capacit\u00e9 a g\u00e9rer les conflits ; <\/li><\/ul>\n\n\n\n<p>PRINCIPALES RESPONSABILITES (1) I<\/p>\n\n\n\n<ul><li>Diriger I&rsquo;\u00e9laboration, la mise en ceuvre et la revue de la charte d&rsquo;audit interne et obtient l&rsquo;avis et<br>I&rsquo;acceptation de la direction g\u00e9n\u00e9rale ainsi que I&rsquo;approbation du Conseil ;<\/li><li>Evaluer p\u00e9riodiquement si la mission, les pouvoirs et les responsabilit\u00e9s d\u00e9finies dans la charte<br>permettent toujours au service d&rsquo;audit interne d&rsquo;atteindre ses objectifs. Le r\u00e9sultat de cette \u00e9valuation<br>p\u00e9riodique devant \u00e9tre communiqu\u00e9 a la direction g\u00e9n\u00e9rale et au conseil ;<\/li><li>Veiller a ce que les r\u00e9gles et proc\u00e9dures cens\u00e9es fournir un cadre a l&rsquo;audit interne soient \u00e9tablies et<br>observ\u00e9s par les auditeurs internes dans le cadre de &lsquo;ex\u00e9cution des activit\u00e9s d&rsquo;audit ;<\/li><li>Veiller a I&rsquo;effectivit\u00e9 permanente de l&rsquo;ind\u00e9pendance de la fonction d&rsquo;audit interne au sein de<br>I&rsquo;\u00e9tablisserent ;<\/li><li>Veiller a ce que le plan d&rsquo;audit soit congu conform\u00e9ment aux exigences du CRIPP d&rsquo;une part et d&rsquo;autre<br>aux exigences de la r\u00e9glementation COBAC en vigueur. Ledit plan devant par ailleurs \u00e9tre soumis a la<br>direction g\u00e9n\u00e9rale pour avis et acceptation et approuv\u00e9 par le comit\u00e9 d&rsquo;audit ou le conseil ;<\/li><\/ul>\n\n\n\n<p>Veiller a ce que les ressources (mat\u00e9rielles, humaines, financi\u00e9res, etc.) soient efficacement allou\u00e9es<br>pour r\u00e9aliser le plan d&rsquo;audit interne approuv\u00e9 ;<\/p>\n\n\n\n<p>G\u00e9rer efficacement l&rsquo;activit\u00e9 d&rsquo;audit interne de fagon a garantir qu&rsquo;elle apporte une valeur ajout\u00e9e a |<br>l&rsquo;organisation, en veillant a ce que les missions d&rsquo;assurance et de conseil (planifi\u00e9es ou non) soient<br>planifi\u00e9es et ex\u00e9cut\u00e9es conform\u00e9ment d&rsquo;une part aux exigences de la documentation de r\u00e9f\u00e9rence en<br>vigueur au sein de I&rsquo;audit interne (CRIPP, manuel d&rsquo;audit interne, \u2026) et d&rsquo;autre part aux exigences de<br>diverses r\u00e9glementations (COBAC, BEAC, MINEF], \u2026) r\u00e9gissant le secteur d&rsquo;activit\u00e9;<\/p>\n\n\n\n<p>Veiller a ce que les processus de gouvernance, de gestion de risques et de contrdle de I&rsquo;\u00e9tablissement<br>soient \u00e9valu\u00e9s et les recommandations appropri\u00e9es formul\u00e9es en vue de leur am\u00e9lioration ;<\/p>\n\n\n\n<p>Veiller a ce que d&rsquo;une part le plan de d\u00e9veloppement professionnel des auditeurs internes soit \u00e9labor\u00e9<br>et mis en ceuvre et d&rsquo;autre part que le programme d&rsquo;assurance et d&rsquo;am\u00e9lioration qualit\u00e9 (PAAQ) soit<br>mis en place;<\/p>\n\n\n\n<p>Veiller a ce que les r\u00e9sultats des missions d&rsquo;audit ainsi que les recommandations y aff\u00e9rentes soient<br>communiqu\u00e9s aux principales parties prenantes dans les meilleurs d\u00e9lais ;<\/p>\n\n\n\n<p>Afin d&rsquo;assurer une couverture ad\u00e9quate et d&rsquo;\u00e9viter les doubles emplois, le responsable de I&rsquo;audit<br>interne devrait partager les informations et coordonner les activit\u00e9s avec les autres prestataires<br>internes et externes d&rsquo;assurance et de conseil ;<\/p>\n\n\n\n<p>Veiller au suivi des recommandations formul\u00e9es et accept\u00e9es dans le cadre des missions d&rsquo;audit<br>internes de fagon a obtenir un taux de mise en ceuvre d&rsquo;au moins 80% en g\u00e9n\u00e9ral, et 100% pour les<br>risques moyens et \u00e9lev\u00e9s en particulier; <\/p>\n\n\n\n<p>PRINCIPALES RESPONSABILITES (2)<\/p>\n\n\n\n<ul><li>Veiller a ce que des m\u00e9canismes soient mis en place pour se rassurer de la conformit\u00e9 des op\u00e9rations<br>bancaires et des dispositifs de contr\u00e9le de celles-ci aux exigences reglementaires ;<\/li><li>Assurer le suivi de tous les projets lanc\u00e9s par &lsquo;entreprise dans le cadre du d\u00e9veloppement de ses activi-<br>t\u00e9s et s&rsquo;assurer de leur alignement sur les strat\u00e9gies et les objectifs de l&rsquo;organisation ;<\/li><li>Evaluer le suivi et la d\u00e9claration des indicateurs cl\u00e9s de performance (ICP) pour d\u00e9terminer si la direc-<br>tion recoit des informations suffisantes et opportunes ;<\/li><li>Veiller a ce que des m\u00e9canismes soient mis en place pour assurer la promotion de l&rsquo;image de l&rsquo;audit in-<br>terne aupr\u00e9s de I&rsquo;ensemble des employ\u00e9s ;<\/li><li>Ex\u00e9cuter toutes les taches confi\u00e9es par la hi\u00e9rarchie.<\/li><\/ul>\n\n\n\n<p>Poste bas\u00e9 a: Douala<\/p>\n\n\n\n<p>D\u00e9lai de depot des candidatures : au plus tard le 12 Septembre 2023 a 17h00<\/p>\n\n\n\n<p>Les CVs (version PDF) sont recevables uniquement via I&rsquo;adresse recrutement@cca-bank.com<br>avec pour objet : \u00ab VOTRE NOM_DAI_AOUT_2023 \u00bb.<\/p>\n\n\n\n<p>Seuls les candidats s\u00e9lectionn\u00e9s seront convoqu\u00e9s pour la suite du processus de recrutement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>APPEL ACANDIDATURE Il est ouvert au sein de CCA-Bank le poste deDirecteur d&rsquo;Audit Interne MISSION; Rattach\u00e9 au Conseil d\u2019Administration de CCA BANK S.A, le titulaire&#8230;<\/p>\n","protected":false},"author":63,"comment_status":"open","ping_status":"closed","template":"","categories":[1594,1139],"tags":[],"villes":[135],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"Directeur d'Audit Interne","emplois_employeur":3887,"emplois_date_publication":"2023-09-08","emplois_heure_publication":"","emplois_date_cloture":"2023-09-12","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":" recrutement@cca-bank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43503"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43503"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43503"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43503"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43503"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}