{"id":43457,"date":"2023-09-06T19:56:39","date_gmt":"2023-09-06T17:56:39","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43457"},"modified":"2023-09-06T19:56:40","modified_gmt":"2023-09-06T17:56:40","slug":"operateurs-machines","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/operateurs-machines\/","title":{"rendered":"Op\u00e9rateurs Machines"},"content":{"rendered":"\n<p>Je suis \u00e0 la recherche des op\u00e9rateurs machines pour une industrie agroalimentaire situ\u00e9e \u00e0 bonaberi-Bekoko.<\/p>\n\n\n\n<p>\u00catre titulaire d\u2019un bac technique<br>Avoir une exp\u00e9rience professionnelle d\u2019un an \u00e0 un poste similaire de pr\u00e9f\u00e9rence au sein d\u2019une industrie agroalimentaire.<br>Bonne connaissance des \u00e9quipements de production en agro-industrie et des bonnes pratiques d\u2019hygi\u00e8ne de production.<\/p>\n\n\n\n<p>candidatures@wity.cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je suis \u00e0 la recherche des op\u00e9rateurs machines pour une industrie agroalimentaire situ\u00e9e \u00e0 bonaberi-Bekoko. \u00catre titulaire d\u2019un bac techniqueAvoir une exp\u00e9rience professionnelle d\u2019un an&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[4027],"tags":[],"villes":[135],"contrats":[234,150],"diplomes":[156,164,162],"louma_meta":{"emploi_title":"Op\u00e9rateurs Machines","emplois_employeur":37403,"emplois_date_publication":"2023-09-06","emplois_heure_publication":"","emplois_date_cloture":"2023-09-12","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"candidatures@wity.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43457"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43457"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/37404"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43457"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43457"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43457"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}