{"id":4344,"date":"2020-07-01T03:29:54","date_gmt":"2020-07-01T01:29:54","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=4344"},"modified":"2020-07-01T03:29:57","modified_gmt":"2020-07-01T01:29:57","slug":"secretaire-bureautique","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/secretaire-bureautique\/","title":{"rendered":"Secr\u00e9taire Bureautique"},"content":{"rendered":"\n<p>Secr\u00e9taire Bureautique<\/p>\n\n\n\n<p>Un cyber de la place recherche pour les besoins de ses services 01 secr\u00e9taire pour un stage professionnel.<\/p>\n\n\n\n<p>Poste : Secr\u00e9taire<br>D\u00e9lais de candidature : 05 juillet 2020<br>Villes : Douala, Cameroun<br>Domaine d&rsquo;activit\u00e9 : Informatique, bureautique, Informatique de Gestion, Marketing \/ Vente<br>Salaire mensuel : 40 000 FCFA<br>Horaires de travail : Temps Plein (08h-17h)<br>Jours de travail : Tous les jours ouvrables (Lundi \u00e0 vendredi de 08h-17h) et le samedi (08h-14h)<br>Profil candidat<\/p>\n\n\n\n<p>\u2022 Langues : Fran\u00e7ais et Anglais<br>\u2022 \u00c9tudes : minimum CAP, BAC avec une formation en bureautique ou exp\u00e9rience justifi\u00e9e.<br>\u2022 Ann\u00e9es d&rsquo;exp\u00e9rience : 0 &#8211; 5 an(s)<br>\u2022 Tranche d&rsquo;\u00e2ge : 20 &#8211; 35 ans<br>Comp\u00e9tences Requises<br>\u2022 Bonne connaissance de l&rsquo;outil informatique et ma\u00eetrise de l&rsquo;utilisation de ses p\u00e9riph\u00e9ries (imprimantes, photocopieur, scanneur, plastifieuse,\u2026)<br>\u2022 Savoir-faire : Ma\u00eetrise des logiciels bureautique (Microsoft Office) et autres (Photoshop, Illustrator, \u2026) archivage des documents, prospection t\u00e9l\u00e9phonique, etc\u2026<br>\u2022 Savoir-\u00eatre : \u00catre de bonne moralit\u00e9, qualit\u00e9s relationnelles, ma\u00eetrise de soi, bonne pr\u00e9sentation, accepter les critiques et s&rsquo;am\u00e9liorer \u00e0 travers l&rsquo;autoformation et la formation, savoir appliquer les instructions.<br>\u2022 Parler et \u00e9crire correctement le fran\u00e7ais et l&rsquo;anglais.<br>\u2022 D\u00e9butante accept\u00e9e Pr\u00e9sentable \u00e2g\u00e9e de 20 \u00e0 35 ans<br>\u2022 Dipl\u00f4me: minimum CAP, BAC avec une formation en bureautique ou exp\u00e9rience justifi\u00e9e.<br>\u2022 R\u00e9sider aux environs de logbaba, ndogpassi, shell, etc\u2026<br>Pi\u00e8ces jointes requises<br>\u2022 Curriculum Vitae (en pr\u00e9cisant votre lieu de r\u00e9sidence)<br>\u2022 Lettre de motivation<br>Mail \u00e0 : infosejobs@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cyber de la place recherche pour les besoins de ses services 01 secr\u00e9taire pour un stage professionnel.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[397],"villes":[136],"contrats":[236,234],"diplomes":[],"louma_meta":{"emploi_title":"Secr\u00e9taire Bureautique","emplois_employeur":3046,"emplois_date_publication":"2020-07-01","emplois_heure_publication":"","emplois_date_cloture":"2020-08-01","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"Mail \u00e0 : infosejobs@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4344"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=4344"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=4344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=4344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=4344"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=4344"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=4344"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=4344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}