{"id":43363,"date":"2023-09-01T12:53:27","date_gmt":"2023-09-01T10:53:27","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43363"},"modified":"2023-09-01T12:53:29","modified_gmt":"2023-09-01T10:53:29","slug":"responsable-reseau%ef%bf%bc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/responsable-reseau%ef%bf%bc\/","title":{"rendered":"Responsable R\u00e9seau\ufffc"},"content":{"rendered":"\n<p>Nombre de poste : 01<br>Type de contrat : Contrat \u00e0 dur\u00e9e ind\u00e9termin\u00e9e (CDI). &nbsp;<\/p>\n\n\n\n<p>Vous \u00eates jeune, ambitieux, dynamique et amoureux du challenge, alors cette offre est pour vous.<br>Acteur majeur du secteur de la microfinance et membre du r\u00e9seau FINAFRICA, FOCEP SA se positionne sur le march\u00e9 de la microfinance parmi les leaders gr\u00e2ce \u00e0 une exp\u00e9rience forte dans les services financiers et la qualit\u00e9 de ses ressources humaines. &nbsp;<br>FINAFRICA a \u00e9t\u00e9 fond\u00e9e en 2018 avec l\u2019objectif de b\u00e2tir un acteur de r\u00e9f\u00e9rence de la finance et de l\u2019assurance inclusive en Afrique, au service de l\u2019entreprenariat et du d\u00e9veloppement \u00e9conomique et social du continent. Elle regroupe dans son r\u00e9seau en Afrique, des entreprises, des institutions de microfinance et des compagnies d\u2019assurance. &nbsp;<br>Dans le cadre de ses activit\u00e9s, FOCEP S.A recrute un Responsable R\u00e9seau.<\/p>\n\n\n\n<p><strong>VOTRE&nbsp; MISSION.<\/strong><\/p>\n\n\n\n<p>Le Responsable R\u00e9seau a pour mission principale le pilotage, l\u2019animation et de la rentabilit\u00e9 de son r\u00e9seau. Il\/elle est responsable de la mise en \u0153uvre de la politique de la direction g\u00e9n\u00e9rale en mati\u00e8re de collecte des ressources, gestion des cr\u00e9dits, gestion des transferts d\u2019argents et autres services \u00e0 valeur ajout\u00e9e de l\u2019agence. Plac\u00e9 sous la responsabilit\u00e9 du Directeur G\u00e9n\u00e9ral Adjoint en charge de l\u2019Exploitation, ses principales activit\u00e9s sont les suivantes :<br>I.&nbsp;&nbsp;&nbsp; La mise en place des cr\u00e9dits<br>&#8211;&nbsp;&nbsp;&nbsp; Mettre en \u0153uvre suivant la politique de cr\u00e9dit du FOCEP les op\u00e9rations de cr\u00e9dits des agences sous sa responsabilit\u00e9 ;<br>&#8211;&nbsp;&nbsp;&nbsp; Veiller au respect des proc\u00e9dures d\u2019octroi de cr\u00e9dit dans son r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Coordonner toutes les activit\u00e9s de cr\u00e9dits de son r\u00e9seau ainsi que la collecte des ressources;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler l\u2019ensemble des dossiers de cr\u00e9dits de son r\u00e9seau avant, le d\u00e9boursement dans la limite des pouvoirs qui lui sont confi\u00e9es ;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler et valider toutes les donn\u00e9es relatives aux dossiers de cr\u00e9dit de son r\u00e9seau et transmettre les statistiques y relatives pour les besoins de rapprochement de la direction d\u2019exploitation ;<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer que toutes les actions administratives en rapport avec les op\u00e9rations de cr\u00e9dits du r\u00e9seau sont bien men\u00e9es (conformit\u00e9 des dossiers, constitution et prise de garanties, caution, nantissements, lev\u00e9es d\u2019hypoth\u00e8ques\u2026).<br>II.&nbsp;&nbsp;&nbsp; Coordonner le suivi des clients ainsi que les remboursements<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer de la production r\u00e9guli\u00e8re des \u00e9tats sur les clients, (journalier, hebdomadaire et mensuel) ;<br>&#8211;&nbsp;&nbsp;&nbsp; D\u00e9finir et fait mettre en \u0153uvre les strat\u00e9gies d\u2019actions de suivi de cr\u00e9dits pour garantir un bon taux de remboursement et le respect des \u00e9ch\u00e9ances ;<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer du bon suivi des clients financ\u00e9s ;<br>&#8211;&nbsp;&nbsp;&nbsp; Recevoir les clients d\u00e9faillants et ceux d\u00e9sirant sortir du portefeuille.<br>III.&nbsp;&nbsp;&nbsp; Assurer la gestion administrative et financi\u00e8re de son r\u00e9seau<br>&#8211;&nbsp;&nbsp;&nbsp; Ordonner de mani\u00e8re d\u00e9l\u00e9gu\u00e9&nbsp; et contr\u00f4ler toutes les d\u00e9pense de son r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Elaborer les \u00e9tats mensuels, base de production du rapport trimestriel du r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Effectuer le suivi des \u00e9tats de rapprochement des comptes de liaison de son r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Etablir de fa\u00e7on trimestrielle et annuelle la situation des immobilisations de son r\u00e9seau, la situation concernant le mat\u00e9riel et le mobilier de bureau.<br>IV.&nbsp;&nbsp;&nbsp; Am\u00e9lioration&nbsp; de la politique de cr\u00e9dit et de gestion des garanties<br>&#8211;&nbsp;&nbsp;&nbsp; Faire des suggestions pour le bon fonctionnement des&nbsp; conditions de cr\u00e9dits, les proc\u00e9dures d\u2019octroi et de suivi des cr\u00e9dits, les modalit\u00e9s d\u2019assistance des clients ;<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer de la bonne impl\u00e9mentation des partenariats sign\u00e9s par le FOCEP.<\/p>\n\n\n\n<p><strong>VOTRE PROFIL.<\/strong><br>Vous \u00eates titulaire d\u2019un BAC+5 en banque et finance, en comptabilit\u00e9, \u00e9conomie ou tout autre dipl\u00f4me \u00e9quivalent.<br>Vous avez une exp\u00e9rience professionnelle av\u00e9r\u00e9e de 05 ans au moins dans un poste similaire et dans le secteur de la microfinance.<br>Vous avez une maitrise de l\u2019usage de l\u2019outil informatique, des logiciels Ms OFFICE (WORD, EXCEL, ETC), NETSOFT, PERFECT.<br>Vous avez une forte capacit\u00e9 r\u00e9dactionnelle et relationnelle, un esprit de synth\u00e8se, une grande capacit\u00e9 d\u2019analyse.<br>Vous \u00eates capable de travailler sous pression et de g\u00e9rer une \u00e9quipe.<br>Vous \u00eates proactif, rigoureux et avez le sens du d\u00e9tail<\/p>\n\n\n\n<p><strong>LE PLUS DE L\u2019OFFRE.<\/strong><br>Vous b\u00e9n\u00e9ficierez de l\u2019avantage d\u2019un environnement de travail sain et professionnel, d\u2019une technologie avanc\u00e9e dans les processus,&nbsp; d\u2019une exp\u00e9rience candidat enrichissante \u00e0 travers des \u00e9changes avec des experts dans le secteur de la micro finance.&nbsp;&nbsp; &nbsp;<\/p>\n\n\n\n<p><strong>CETTE OFFRE VOUS INTERESSE ?\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><br>Transmettez-nous votre CV et lettre de motivation \u00e0 l\u2019adresse suivante :<\/p>\n\n\n\n<p>Nombre de poste : 01<br>Type de contrat : Contrat \u00e0 dur\u00e9e ind\u00e9termin\u00e9e (CDI). &nbsp;<\/p>\n\n\n\n<p>Vous \u00eates jeune, ambitieux, dynamique et amoureux du challenge, alors cette offre est pour vous.<br>Acteur majeur du secteur de la microfinance et membre du r\u00e9seau FINAFRICA, FOCEP SA se positionne sur le march\u00e9 de la microfinance parmi les leaders gr\u00e2ce \u00e0 une exp\u00e9rience forte dans les services financiers et la qualit\u00e9 de ses ressources humaines. &nbsp;<br>FINAFRICA a \u00e9t\u00e9 fond\u00e9e en 2018 avec l\u2019objectif de b\u00e2tir un acteur de r\u00e9f\u00e9rence de la finance et de l\u2019assurance inclusive en Afrique, au service de l\u2019entreprenariat et du d\u00e9veloppement \u00e9conomique et social du continent. Elle regroupe dans son r\u00e9seau en Afrique, des entreprises, des institutions de microfinance et des compagnies d\u2019assurance. &nbsp;<br>Dans le cadre de ses activit\u00e9s, FOCEP S.A recrute un Responsable R\u00e9seau.<\/p>\n\n\n\n<p><strong>VOTRE&nbsp; MISSION.<\/strong><\/p>\n\n\n\n<p>Le Responsable R\u00e9seau a pour mission principale le pilotage, l\u2019animation et de la rentabilit\u00e9 de son r\u00e9seau. Il\/elle est responsable de la mise en \u0153uvre de la politique de la direction g\u00e9n\u00e9rale en mati\u00e8re de collecte des ressources, gestion des cr\u00e9dits, gestion des transferts d\u2019argents et autres services \u00e0 valeur ajout\u00e9e de l\u2019agence. Plac\u00e9 sous la responsabilit\u00e9 du Directeur G\u00e9n\u00e9ral Adjoint en charge de l\u2019Exploitation, ses principales activit\u00e9s sont les suivantes :<br>I.&nbsp;&nbsp;&nbsp; La mise en place des cr\u00e9dits<br>&#8211;&nbsp;&nbsp;&nbsp; Mettre en \u0153uvre suivant la politique de cr\u00e9dit du FOCEP les op\u00e9rations de cr\u00e9dits des agences sous sa responsabilit\u00e9 ;<br>&#8211;&nbsp;&nbsp;&nbsp; Veiller au respect des proc\u00e9dures d\u2019octroi de cr\u00e9dit dans son r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Coordonner toutes les activit\u00e9s de cr\u00e9dits de son r\u00e9seau ainsi que la collecte des ressources;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler l\u2019ensemble des dossiers de cr\u00e9dits de son r\u00e9seau avant, le d\u00e9boursement dans la limite des pouvoirs qui lui sont confi\u00e9es ;<br>&#8211;&nbsp;&nbsp;&nbsp; Contr\u00f4ler et valider toutes les donn\u00e9es relatives aux dossiers de cr\u00e9dit de son r\u00e9seau et transmettre les statistiques y relatives pour les besoins de rapprochement de la direction d\u2019exploitation ;<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer que toutes les actions administratives en rapport avec les op\u00e9rations de cr\u00e9dits du r\u00e9seau sont bien men\u00e9es (conformit\u00e9 des dossiers, constitution et prise de garanties, caution, nantissements, lev\u00e9es d\u2019hypoth\u00e8ques\u2026).<br>II.&nbsp;&nbsp;&nbsp; Coordonner le suivi des clients ainsi que les remboursements<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer de la production r\u00e9guli\u00e8re des \u00e9tats sur les clients, (journalier, hebdomadaire et mensuel) ;<br>&#8211;&nbsp;&nbsp;&nbsp; D\u00e9finir et fait mettre en \u0153uvre les strat\u00e9gies d\u2019actions de suivi de cr\u00e9dits pour garantir un bon taux de remboursement et le respect des \u00e9ch\u00e9ances ;<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer du bon suivi des clients financ\u00e9s ;<br>&#8211;&nbsp;&nbsp;&nbsp; Recevoir les clients d\u00e9faillants et ceux d\u00e9sirant sortir du portefeuille.<br>III.&nbsp;&nbsp;&nbsp; Assurer la gestion administrative et financi\u00e8re de son r\u00e9seau<br>&#8211;&nbsp;&nbsp;&nbsp; Ordonner de mani\u00e8re d\u00e9l\u00e9gu\u00e9&nbsp; et contr\u00f4ler toutes les d\u00e9pense de son r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Elaborer les \u00e9tats mensuels, base de production du rapport trimestriel du r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Effectuer le suivi des \u00e9tats de rapprochement des comptes de liaison de son r\u00e9seau ;<br>&#8211;&nbsp;&nbsp;&nbsp; Etablir de fa\u00e7on trimestrielle et annuelle la situation des immobilisations de son r\u00e9seau, la situation concernant le mat\u00e9riel et le mobilier de bureau.<br>IV.&nbsp;&nbsp;&nbsp; Am\u00e9lioration&nbsp; de la politique de cr\u00e9dit et de gestion des garanties<br>&#8211;&nbsp;&nbsp;&nbsp; Faire des suggestions pour le bon fonctionnement des&nbsp; conditions de cr\u00e9dits, les proc\u00e9dures d\u2019octroi et de suivi des cr\u00e9dits, les modalit\u00e9s d\u2019assistance des clients ;<br>&#8211;&nbsp;&nbsp;&nbsp; S\u2019assurer de la bonne impl\u00e9mentation des partenariats sign\u00e9s par le FOCEP.<\/p>\n\n\n\n<p><strong>VOTRE PROFIL.<\/strong><br>Vous \u00eates titulaire d\u2019un BAC+5 en banque et finance, en comptabilit\u00e9, \u00e9conomie ou tout autre dipl\u00f4me \u00e9quivalent.<br>Vous avez une exp\u00e9rience professionnelle av\u00e9r\u00e9e de 05 ans au moins dans un poste similaire et dans le secteur de la microfinance.<br>Vous avez une maitrise de l\u2019usage de l\u2019outil informatique, des logiciels Ms OFFICE (WORD, EXCEL, ETC), NETSOFT, PERFECT.<br>Vous avez une forte capacit\u00e9 r\u00e9dactionnelle et relationnelle, un esprit de synth\u00e8se, une grande capacit\u00e9 d\u2019analyse.<br>Vous \u00eates capable de travailler sous pression et de g\u00e9rer une \u00e9quipe.<br>Vous \u00eates proactif, rigoureux et avez le sens du d\u00e9tail<\/p>\n\n\n\n<p><strong>LE PLUS DE L\u2019OFFRE.<\/strong><br>Vous b\u00e9n\u00e9ficierez de l\u2019avantage d\u2019un environnement de travail sain et professionnel, d\u2019une technologie avanc\u00e9e dans les processus,&nbsp; d\u2019une exp\u00e9rience candidat enrichissante \u00e0 travers des \u00e9changes avec des experts dans le secteur de la micro finance.&nbsp;&nbsp; &nbsp;<\/p>\n\n\n\n<p><strong>CETTE OFFRE VOUS INTERESSE ?&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><br>Transmettez-nous votre CV et lettre de motivation \u00e0 l\u2019adresse suivante : rh@focep.cm en pr\u00e9cisant en objet l\u2019intitul\u00e9 du poste \u00abResponsable R\u00e9seau&nbsp;\u00bb au plus tard le 24 09 2023.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p> en pr\u00e9cisant en objet l\u2019intitul\u00e9 du poste \u00abResponsable R\u00e9seau\u00a0\u00bb au plus tard le 24 09 2023.\u00a0\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via rh@focep.cm<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[282,23],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"","emplois_employeur":25397,"emplois_date_publication":"2023-09-01","emplois_heure_publication":"11:53","emplois_date_cloture":"2023-09-24","emplois_heure_cloture":"17:00","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":"rh@focep.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43363"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43363"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/25398"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43363"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43363"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43363"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}