{"id":4333,"date":"2020-06-30T14:18:01","date_gmt":"2020-06-30T12:18:01","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=4333"},"modified":"2020-06-30T14:19:01","modified_gmt":"2020-06-30T12:19:01","slug":"coordinateur-maintenance-securite","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/coordinateur-maintenance-securite\/","title":{"rendered":"Coordinateur Maintenance &amp; S\u00e9curit\u00e9"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>ANNONCE DE VACANCE<\/p>\n\n\n\n<h1 class=\"wp-block-heading\">BACM\/DRH\/26-06-2020<\/h1>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Intitul\u00e9 du poste<\/td><td>\u2022 Coordinateur Maintenance &amp; S\u00e9curit\u00e9<\/td><\/tr><tr><td>Service<\/td><td>Moyen G\u00e9n\u00e9raux<\/td><\/tr><tr><td>Lieu de fonction<\/td><td>\u2022 Douala (Si\u00e8ge)<\/td><\/tr><tr><td>Statut<\/td><td>\u2022 Agent de ma\u00eetrise<\/td><\/tr><tr><td>Contrat<\/td><td>\u2022 \u00c0 Dur\u00e9e Ind\u00e9termin\u00e9e (CDI)<\/td><\/tr><tr><td>Zone de publication<\/td><td>\u2022 Interne \/ Externe<\/td><\/tr><tr><td>Mission principale<\/td><td>: garantir le respect de la r\u00e9glementation des \u00e9quipements et de la s\u00e9curit\u00e9<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>des 6\u00edens et des personnes au se\u00edn de (a banque.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>OBJECTIFS ET ACTIVITES PRI CIPALES<\/td><\/tr><tr><td>Garant de la maintenance et de la s\u00e9curit\u00e9 des installations de la banque, le Coordinateur Maintenance et S\u00e9curit\u00e9 est charg\u00e9 de Superviser les activit\u00e9s suivantes : Activit\u00e9s de maintenance Maintenance pr\u00e9ventive &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Proposer des &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; d&rsquo;am\u00e9lioration des performances des \u00e9quipements \u00c9laborer le planning de maintenance pr\u00e9ventive des installations Assurer une veille r\u00e9glementaire, technique et technologique du b\u00e2timent Assurer le suivi des maintenances syst\u00e9matiques Veiller aux travaux de maintenance niveau 1 des prestataires Maintenance curative Suivi des indicateurs de performances immobili\u00e8res Effectuer le traitement des besoins relatifs \u00e0 la maintenance des immobiliers et mobiliers Assurer le suivi des incidents au sein des agences et du si\u00e8ge Activit\u00e9 de s\u00e9curit\u00e9 S\u00e9curit\u00e9 logique Contr\u00f4ler les dispositifs de vid\u00e9o surveillance Contr\u00f4ler des dispositifs de d\u00e9tection d&rsquo;intrusion Contr\u00f4ler les installations de contr\u00f4le d&rsquo;acc\u00e8s biom\u00e9triques et badges S\u00e9curit\u00e9 physique G\u00e9rer les contrats avec les sous-traitants de maintenance, de gardiennage et d&rsquo;entretien s\u00e9curitaire Assurer le turn over des effectifs de gardiennage Veiller \u00e0 la s\u00e9curit\u00e9 du personnel, des biens et des visiteurs Assurer le suivi des agents de s\u00e9curit\u00e9 et d&rsquo;entretien Suivre les relations avec les prestataires de s\u00e9curit\u00e9 permanents et occasionnels<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h1 class=\"wp-block-heading\">banque atlantique Cameroun<\/h1>\n\n\n\n<p>Si\u00e8ge social: Akwa Douala B.P. 2933 Douala &#8211; Cameroun<\/p>\n\n\n\n<p>T\u00e9l.: (237) 233 42 10 66 &#8211; Fax : (237) 233 42 10 71 SA au capital social de : 13.000.000.000 Frs CFA<\/p>\n\n\n\n<p>R.C. N <sup>O <\/sup>DLA\/2008\/B\/1195 &#8211; N <sup>O <\/sup>Contrib MAAA 9DFB 08W7 00 &#8211; Agr\u00e9ment N <sup>O <\/sup>00000 322\/MlNFl du 06 Juillet 2015 &#8211; www.banqueatlantique.net<\/p>\n\n\n\n<p>D\u00e9p\u00f4t des Candidatures<\/p>\n\n\n\n<p>Envoyez votre lettre de motivation et votre curriculum vitae \u00e0 <img loading=\"lazy\" decoding=\"async\" width=\"239\" height=\"14\" src=\"\">&nbsp;au plus tard le vendredi 03 juillet 2020, en pr\u00e9cisant en objet \u00ab Coordinateur Maintenance &amp; S\u00e9curit\u00e9 \u00bb.<\/p>\n\n\n\n<p>Toute candidature re\u00e7ue par un canal autre que celui indiqu\u00e9 ne sera pas consid\u00e9r\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>QUALIFICATIONS ET EXP\u00c9RIENCE REQUISES<\/td><td>COMP\u00c9TENCES REQUISES<\/td><\/tr><tr><td>Bac + 4 ou 5 en Maintenance Industrielle, Electricit\u00e9, M\u00e9canique, G\u00e9nie civil, G\u00e9nie climatique et froid, QHSE, ou toute discipline similaire Exp\u00e9rience minimum de quatre (04) ans \u00e0 un poste identique, de pr\u00e9f\u00e9rence dans le secteur bancaire<\/td><td>Savoirs Solides connaissances des r\u00e8gles QHSE Maitrise des logiciels de Gestion de maintenance assist\u00e9e par Ordinateur (GMAC)) Savoir-faire Maitrise des Progiciels de Gestion Int\u00e9gr\u00e9e PGI, Entreprise Resource Planning ERP Maitrise des Technologies de Groupe Assist\u00e9e par Ordinateur TGAO Maitrise des outils bureautiques Savoir-\u00eatre Personne de terrain et de contactOrganisation et autonomieAnalyste et orient\u00e9 r\u00e9sultats R\u00e9activit\u00e9<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>C.<\/td><td>Gestion des contrats et du budget Elaborer le reporting financier de chaque projet de maintenance et de s\u00e9curit\u00e9 G\u00e9rer le budget et la pr\u00e9vision des investissements \u00e0 venir Superviser l&rsquo;exploitation des installations techniques et des mat\u00e9riels li\u00e9s \u00e0 la s\u00e9curit\u00e9 incendie Suivre les travaux de construction des agences&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Trois semaines apr\u00e8s cette date, si vous n&rsquo;avez pas \u00e9t\u00e9 contact\u00e9(e), merci de consid\u00e9rer que votre candidature n&rsquo;a pas \u00e9t\u00e9 retenue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toutes les Offres d&#8217;emplois et les recrutements disponible \u00e0  banque atlantique Cameroun.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[72],"villes":[136],"contrats":[234],"diplomes":[],"louma_meta":{"emploi_title":" Coordinateur Maintenance & S\u00e9curit\u00e9","emplois_employeur":2974,"emplois_date_publication":"2020-06-30","emplois_heure_publication":"","emplois_date_cloture":"2020-07-03","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"www.banqueatlantique.net"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4333"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=4333"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=4333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=4333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=4333"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=4333"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=4333"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=4333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}