{"id":43326,"date":"2023-08-29T10:38:44","date_gmt":"2023-08-29T08:38:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=43326"},"modified":"2023-08-29T10:38:46","modified_gmt":"2023-08-29T08:38:46","slug":"infirmier-diplome-detat-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/infirmier-diplome-detat-h-f\/","title":{"rendered":"Infirmier dipl\u00f4m\u00e9 d\u2019Etat H\/F"},"content":{"rendered":"\n<p><strong>\u00a0 Missions Infirmier Dipl\u00f4m\u00e9 d\u2019Etat\u00a0H\/F : <\/strong>\u00a0IF400-DSS-CMC NDR<\/p>\n\n\n\n<p>&nbsp;&nbsp; En qualit\u00e9 d\u2019Infirmier Dipl\u00f4m\u00e9 d\u2019Etat au CMC NDR vos missions seront les suivantes&nbsp;:<\/p>\n\n\n\n<ul><li>Accueillir, rassurer, informer sur les proc\u00e9dures et protocoles \u00e0 mettre en \u0153uvre aupr\u00e8s des patients pour mener \u00e0 bien leur prise en charge&nbsp;;<\/li><li>Faire des soins infirmiers \u2013 Mettre en \u0153uvre les protocoles de diff\u00e9rents soins<\/li><li>Pr\u00e9parer, administrer et Surveiller les malades ou des soins ou des traitements sp\u00e9cifiques&nbsp;;<\/li><li>\u00catre Polyvalence dans la dispensation administration des soins (Intervenir en soins gyn\u00e9cologiques, obst\u00e9triques, P\u00e9diatrie petite chirurgie..etc,<\/li><li>Recueillir et transmettre les informations adapt\u00e9es pour que le malade soit bien soign\u00e9 et bien inform\u00e9<\/li><li>Communiquer et conduire une relation dans un contexte de soins,<\/li><li>Assurer l&rsquo;entretien du mat\u00e9riel, la propret\u00e9 de la salle (nettoyage st\u00e9rilisation les proc\u00e9dures d&rsquo;\u00e9limination des d\u00e9chets\u2026)<\/li><li>Appliquer et faire appliquer dans tous les soins et au sein de la structure hospitali\u00e8re les mesures de pr\u00e9vention des infections nosocomiales, etc\u2026<\/li><li>Initier et mettre en \u0153uvre des soins \u00e9ducatifs et pr\u00e9ventifs,<\/li><li>Organiser et coordonner le travail des aides-soignants sous votre responsabilit\u00e9.<\/li><li>Accueillir et encadrer les autres personnels de sant\u00e9&nbsp;: les diff\u00e9rents stagiaires dans les services<\/li><li>Enregistrer les donn\u00e9es li\u00e9es \u00e0 l&rsquo;activit\u00e9&nbsp;;<\/li><li>Envisager la recherche en sant\u00e9 dans son domaine, \u00e0 partir de ces activit\u00e9s journali\u00e8res.<\/li><\/ul>\n\n\n\n<ul><li><strong>Profil du Infirmier Dipl\u00f4m\u00e9 d\u2019Etat&nbsp;H\/F : <\/strong>IF400-DSS-CMC NDR<\/li><\/ul>\n\n\n\n<p>Le profil recherch\u00e9 est le suivant<\/p>\n\n\n\n<ul><li>\u00catre titulaire d\u2019un Dipl\u00f4me d\u2019infirmier dipl\u00f4m\u00e9 d\u2019Etat ou de tout autre dipl\u00f4me \u00e9quivalent;<\/li><li>Justifiez d\u2019une exp\u00e9rience &nbsp;d\u2019au moins deux ans dans la gestion des soins de sant\u00e9 primaires en g\u00e9n\u00e9ral. Dont au moins un an dans la gestion de sant\u00e9 de la reproduction et de la prise en charge de nouveau-n\u00e9e en particulier&nbsp;;<\/li><li>Avoir le sens des priorit\u00e9s&nbsp;;<\/li><li>\u00catre organiser et proactif&nbsp;;<\/li><\/ul>\n\n\n\n<ul><li><strong>Comp\u00e9tences Infirmier Dipl\u00f4m\u00e9 d\u2019Etat&nbsp;H\/F :<\/strong> IF400-DSS-CMC NDR<\/li><\/ul>\n\n\n\n<ul><li><strong>Comp\u00e9tences&nbsp; m\u00e9dico sanitaire<\/strong><\/li><\/ul>\n\n\n\n<ul><li>G\u00e9rer et organiser une unit\u00e9 de soin ou un centre de sant\u00e9 ;<\/li><li>Former et encadrer d\u2019autres personnels de sant\u00e9 sous sa responsabilit\u00e9 ;<\/li><li>Assurer des prestations de soin ;<\/li><li>Promouvoir la sant\u00e9, pr\u00e9venir des maladies et favoriser la r\u00e9adaptation chez les individus, les familles et les collectivit\u00e9s ;<\/li><li>Envisager la recherche en sant\u00e9 dans son domaine, \u00e0 partir de ces activit\u00e9s journali\u00e8res.<\/li><\/ul>\n\n\n\n<ul><li><strong>Comp\u00e9tences techniques administratives<\/strong><\/li><li>Ma\u00eetrise des outils bureautiques de base (Word, Excel, PowerPoint),<\/li><li>aptes \u00e0 utiliser les E-Mails&nbsp;; la Vision Conf\u00e9rence&nbsp;; les r\u00e9seaux sociaux et la plupart des NTIC;<\/li><li>Bonnes capacit\u00e9s r\u00e9dactionnelles et de synth\u00e8se;<\/li><li>Savoir pr\u00e9parer et pr\u00e9senter les rapports comptes rendus et\/ou les r\u00e9sultats, par \u00e9crit et\/ou en public.<\/li><\/ul>\n\n\n\n<ul><li><strong>Comp\u00e9tences comportementales<\/strong><\/li><\/ul>\n\n\n\n<ul><li>Capacit\u00e9 \u00e0 travailler sous pression&nbsp;et \u00e0 g\u00e9rer les situations de crise et de fort stress&nbsp;;<\/li><li>Capacit\u00e9 \u00e0 travailler de mani\u00e8re autonome et\/ou en \u00e9quipe;<\/li><li>Capacit\u00e9 d\u2019adaptation<\/li><li>Sens de la responsabilit\u00e9, de la rigueur et de l\u2019\u00e9thique&nbsp;;<\/li><li>Sens&nbsp; du d\u00e9tail, de l&rsquo;observation, de l&rsquo;analyse et de la synth\u00e8se.<\/li><li>\u00catre minutieux, concentr\u00e9, pr\u00e9cis&nbsp;;<\/li><li>Forte capacit\u00e9 d&rsquo;\u00e9coute, d\u2019empathie&nbsp;;<\/li><li>Disposition \u00e0 s\u2019investir humainement.<\/li><li>Aptitudes relationnelles et p\u00e9dagogiques,<\/li><\/ul>\n\n\n\n<ul><li><strong>Conditions du Poste\u00a0: Infirmier Dipl\u00f4m\u00e9 d\u2019Etat\u00a0H\/F : <\/strong>\u00a0IF400-DSS-CMC NDR<\/li><li>R\u00e9f\u00e9rence du Poste\u00a0: IF400-DSS-CMC NDR;<\/li><li>Intitul\u00e9 du Poste\u00a0: Infirmier Dipl\u00f4m\u00e9 d\u2019Etat H\/F\u00a0;<\/li><li>Classification du poste : Agent de ma\u00eetrise ;<\/li><li>Salaire\u00a0: \u00e0 n\u00e9gocier;\u00a0<\/li><li>Rattachement hi\u00e9rarchique : Chef de D\u00e9pmt. Services Soignants;<\/li><li>P\u00e9riode de Probation\u00a0: 03 mois renouvelables 1 fois\u00a0;<\/li><li>Type de contrat de travail : CDD de un an renouvelable 1 fois et pouvant\u00a0\u00a0 aboutir \u00e0 un CDI\u00a0;<\/li><li>Heures de travail\u00a0: \u00e0 temps plein (48 heures par semaine)\u00a0;<\/li><li>Localit\u00e9 d\u2019affectation du poste : CMC NDR lieu-dit Carrefour des s\u0153urs Simbock Yaound\u00e9 Cameroun.<\/li><li>Date de Prise de Fonction 30 Octobre 2023.<\/li><\/ul>\n\n\n\n<h6 class=\"wp-block-heading\"><\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via centremedicalcatholiquendr@yahoo.com <\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[27],"tags":[],"villes":[136],"contrats":[148],"diplomes":[278],"louma_meta":{"emploi_title":"Infirmier dipl\u00f4m\u00e9 d\u2019Etat H\/F","emplois_employeur":3046,"emplois_date_publication":"2023-08-29","emplois_heure_publication":"09:38","emplois_date_cloture":"2023-09-22","emplois_heure_cloture":"17:00","emplois_experience_min":"2","emplois_experience_max":"","emploi_email":"centremedicalcatholiquendr@yahoo.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43326"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=43326"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/43326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=43326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=43326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=43326"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=43326"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=43326"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=43326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}