{"id":42887,"date":"2023-07-25T13:36:11","date_gmt":"2023-07-25T11:36:11","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=42887"},"modified":"2023-07-25T13:36:12","modified_gmt":"2023-07-25T11:36:12","slug":"42887","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/42887\/","title":{"rendered":"(title)"},"content":{"rendered":"\n<p>FORMATION EN CHAPELLERIE DANS LES ATELIERS FABY HOUSE CR\u00c9ATION Devenir le chapelier de demain gr\u00e2ce aux formations que nous offrons. Un chapelier confectionne des chapeaux, il s\u2019agit d\u2019une profession tr\u00e8s sp\u00e9cialis\u00e9e. C\u2019est un m\u00e9tier pointu, o\u00f9 les cr\u00e9ations sont uniques ou en petite s\u00e9ries et qui demande un bon sens esth\u00e9tique et de la technique. Comment s\u2019en sortir sur le plan financier ? comment diversifier ses revenus si on a d\u00e9j\u00e0 un emploi ?C\u2019est dans cette optique que les ATELIERS FABY HOUSE CREATION offre une formation exceptionnelle en pr\u00e9sentielle tous les jours dans sa structure dans la ville de Yaound\u00e9 sis au quartier Nkoldongo Descente BOCOM entr\u00e9e \u00e9glise \u00e9vang\u00e9lique Nkoldongo I. cette formation est une aubaine pour les vacanciers.<br>LES MODULES DE FORMATIONS AU PROGRAMME<br>MODULE I : PAILLE FRAN\u00c7AISE Co\u00fbt de la formation 50 000 FCFA (tous les mat\u00e9riels \u00e0 utiliser compris) CHAPEAU EN PAILLE FRANCAISE :<br>Il s\u2019agit de :<br>Fabrication des chapeaux moyens en paille ;<br>Fabrication des grands chapeaux large bord ;<br>Confection des minis barettes ;<br>Fabrication des bibis<br>;Coupes, montage \u2013 moulage ;Confection des p\u00f4chettes ; d\u00e9coration ; finitions<\/p>\n\n\n\n<p>NB : le prix d\u2019achats et les boutiques qui vendent le mat\u00e9riel vous seront enseigner les techniques de ventes \u00e9galement vous seront enseigner<br>pour ce module, \u00e0 la fin de la formation l\u2019apprenant rentre avec un chapeau moyen, la barette et la pochette.<\/p>\n\n\n\n<p>MODULE II : LES FOULARDS co\u00fbt de la formation 35 000FCFA (mat\u00e9riel y compris)CHAPEAUX FOULARDS Il s\u2019agit ici : De la confection des foulards en<br>Sego nig\u00e9rian (gel\u00e9 nig\u00e9rian) style en \u00e9ventail ;<br>Foulard surfil\u00e9 au fil de p\u00eache ;<br>Foulard ZARA ; D\u00e9coration et finition.<\/p>\n\n\n\n<p>MODULE III : CRINOLINE co\u00fbt 30 000 FCFA (mat\u00e9riels y compris)CHAPEAU EN CRINOLINEIl s\u2019agit ici de :La manipulation de la crinoline ;La confection des barettes ;La confection des chapeau ;Commet utiliser la crinoline pour d\u00e9corer diff\u00e9rents types de chapeaux.<\/p>\n\n\n\n<p>MODULE IV : MONTAGE \u00c9VENTAIL Co\u00fbt 25 000 FCFA Il s\u2019agit ici de :La customisation des \u00e9ventails ;Confection des \u00e9ventails en pl\u00fbmes.<\/p>\n\n\n\n<p>DUR\u00c9E DE LA FORMATION :Elle d\u00e9pendra de l\u2019aptitude de l\u2019apprenant car chacune de ces formations peuvent se faire m\u00eame en trois jours.Tel Whatsapp : 699.243.581<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FORMATION EN CHAPELLERIE DANS LES ATELIERS FABY HOUSE CR\u00c9ATION Devenir le chapelier de demain gr\u00e2ce aux formations que nous offrons. Un chapelier confectionne des chapeaux,&#8230;<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[48],"tags":[],"villes":[136],"contrats":[149],"diplomes":[156],"louma_meta":{"emploi_title":"","emplois_employeur":3046,"emplois_date_publication":"2023-07-25","emplois_heure_publication":"","emplois_date_cloture":"2023-09-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/42887"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=42887"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/42887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=42887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=42887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=42887"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=42887"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=42887"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=42887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}