{"id":42491,"date":"2023-07-07T22:15:35","date_gmt":"2023-07-07T20:15:35","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=42491"},"modified":"2023-07-07T22:15:36","modified_gmt":"2023-07-07T20:15:36","slug":"stagiaire-marketing-logistique-et-qualite","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/stagiaire-marketing-logistique-et-qualite\/","title":{"rendered":"Stagiaire Marketing, Logistique et Qualit\u00e9"},"content":{"rendered":"\n<div>Une entreprise de distribution de la place recrute des stagiaires professionnels dans diff&eacute;rents domaines : marketing et vente; Logistique et transport; Gestion de la qualit&eacute;, niveau Bacc+4.<\/div> <div>Une r&eacute;mun&eacute;ration &agrave; n&eacute;gocier;<\/div> <div>&bull; Un dispositif d&rsquo;int&eacute;gration garantissant une prise de fonction r&eacute;ussie.<\/div> <div>&bull; Des conditions de travail agr&eacute;ables et une vie d&rsquo;entreprise anim&eacute;e<\/div> <div>Envoyez votre cv a l &lsquo; adresse suivante : cegedisdouala@gmail.com<\/div> <div>NB : la date limite des d&eacute;p&ocirc;ts : 07\/07\/2023<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Une entreprise de distribution de la place recrute des stagiaires professionnels dans diff&eacute;rents domaines : marketing et vente; Logistique et transport; Gestion de la qualit&eacute;,&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[113,24,4057],"tags":[],"villes":[135,136],"contrats":[152],"diplomes":[163,162],"louma_meta":{"emploi_title":"Stagiaire Marketing, Logistique et Qualit\u00e9","emplois_employeur":3046,"emplois_date_publication":"2023-07-07","emplois_heure_publication":"","emplois_date_cloture":"2023-07-21","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"cegedisdouala@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/42491"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=42491"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/42491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=42491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=42491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=42491"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=42491"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=42491"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=42491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}