{"id":42479,"date":"2023-07-07T21:36:29","date_gmt":"2023-07-07T19:36:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=42479"},"modified":"2023-07-07T21:36:31","modified_gmt":"2023-07-07T19:36:31","slug":"web-designer-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/web-designer-3\/","title":{"rendered":"Web Designer"},"content":{"rendered":"\n<div>Poste : Web designer<\/div> <div>Entreprise :&nbsp; Startup Agence de d&eacute;veloppement web (KRM Soft) bas&eacute;e &agrave; Douala<\/div> <div>Type d&#8217;emploi : Temps plein<\/div> <div>&nbsp;<\/div> <div>Description du poste :<\/div> <div>Nous sommes &agrave; la recherche d&rsquo;un talentueux Web designer passionn&eacute; par la cr&eacute;ation de sites web esth&eacute;tiques et fonctionnels. En tant que membre de notre &eacute;quipe cr&eacute;ative, vous serez responsable de la conception et de la mise en &oelig;uvre de sites web attrayants et conviviaux pour nos clients. Voici quelques d&eacute;tails suppl&eacute;mentaires sur le poste :<\/div> <div>&nbsp;<\/div> <div>Responsabilit&eacute;s :<\/div> <div>&#8211; Collaborer avec l&rsquo;&eacute;quipe de d&eacute;veloppement pour convertir les maquettes en sites web fonctionnels.<\/div> <div>&#8211; Assurer une exp&eacute;rience utilisateur optimale en cr&eacute;ant des interfaces intuitives et faciles &agrave; naviguer.<\/div> <div>&#8211; Optimiser les sites web pour un chargement rapide et une compatibilit&eacute; multiplateforme.<\/div> <div>&#8211; Int&eacute;grer des &eacute;l&eacute;ments interactifs tels que des animations et des effets visuels.<\/div> <div>&#8211; Maintenir une veille technologique constante pour rester &agrave; jour sur les nouvelles tendances du design web.<\/div> <div>&nbsp;<\/div> <div>Exigences :<\/div> <div>&#8211; Exp&eacute;rience prouv&eacute;e en tant que Web designer, de pr&eacute;f&eacute;rence avec une connaissance approfondie du codage HTML, CSS et JavaScript.<\/div> <div>&#8211; Maitrise des cms en occurence WordPress<\/div> <div>&#8211; Capacit&eacute; &agrave; travailler en &eacute;quipe et &agrave; collaborer efficacement avec les d&eacute;veloppeurs.<\/div> <div>&#8211; Souci du d&eacute;tail et passion pour la cr&eacute;ation de designs esth&eacute;tiques et fonctionnels.<\/div> <div>&#8211; Bonnes comp&eacute;tences en communication pour comprendre les besoins des clients et y r&eacute;pondre de mani&egrave;re appropri&eacute;e.<\/div> <div>&#8211; Portfolio d&eacute;montrant vos comp&eacute;tences en design web et en codage.<\/div> <div>&nbsp;<\/div> <div>Si vous &ecirc;tes int&eacute;ress&eacute; par cette offre, veuillez envoyer votre CV et votre portfolio &agrave; contact@groupkrm.com . Nous sommes impatients de voir vos cr&eacute;ations et de discuter de votre contribution potentielle &agrave; notre &eacute;quipe ! Bonne chance dans votre recherche d&#8217;emploi !<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Poste : Web designer Entreprise :&nbsp; Startup Agence de d&eacute;veloppement web (KRM Soft) bas&eacute;e &agrave; Douala Type d&#8217;emploi : Temps plein &nbsp; Description du poste&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[2027,4101,22],"tags":[],"villes":[135],"contrats":[234,148],"diplomes":[163,248],"louma_meta":{"emploi_title":"Web Designer","emplois_employeur":23104,"emplois_date_publication":"2023-07-07","emplois_heure_publication":"","emplois_date_cloture":"2023-07-08","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"contact@groupkrm.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/42479"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=42479"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/42479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/23105"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=42479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=42479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=42479"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=42479"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=42479"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=42479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}