{"id":4243,"date":"2020-06-26T18:43:28","date_gmt":"2020-06-26T16:43:28","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=4243"},"modified":"2020-06-26T18:43:30","modified_gmt":"2020-06-26T16:43:30","slug":"responsable-financements-structures-societe-generale-cameroun","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/responsable-financements-structures-societe-generale-cameroun\/","title":{"rendered":"RESPONSABLE FINANCEMENTS STRUCTURES Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Cameroun"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Description:<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>LA SOCI\u00c9T\u00c9 G\u00c9N\u00c9RALE CAMEROUN RECHERCHE POUR SA DIRECTION G\u00c9N\u00c9RALE UN (01) RESPONSABLE FINANCEMENTS STRUCTURES<\/strong><\/h3>\n\n\n\n<p><strong>RESPONSABILIT\u00c9S PRINCIPALES<\/strong><\/p>\n\n\n\n<p>Le Responsable Financements Structur\u00e9s participe au d\u00e9veloppement des op\u00e9rations de financements structur\u00e9s pour la zone CEMAC , en proposant aux portefeuilles de clients de la banque dans le ou les pays dont il est responsable des solutions de financement (li\u00e9es aux mati\u00e8res premi\u00e8res, export, infrastructures, \u00e9nergie, LBOs ou titrisation), tout en appr\u00e9ciant le risque que repr\u00e9sente chaque projet. Il s\u2019appuie sur le pool d\u2019analystes de SFG\/AFS et fait valider ses solutions par un Director\/MD.<\/p>\n\n\n\n<p><strong>MISSIONS<\/strong><em><strong>Origination et Structuration<\/strong><\/em><\/p>\n\n\n\n<ul><li>\uf0a7 Identifier et exploiter les opportunit\u00e9s commerciales sur les portefeuilles d\u2019intervention (d\u00e9finir un plan d\u2019action commerciale r\u00e9aliste et ambitieux) ;<\/li><li>\uf0a7 Rechercher les synergies au sein du groupe SG ;<\/li><li>\uf0a7 Contr\u00f4ler la mod\u00e9lisation financi\u00e8re et les calculs de rentabilit\u00e9 ;<\/li><li>\uf0a7 Participer \u00e0 l\u2019\u00e9laboration et \u00e0 la pr\u00e9sentation des offres ;*<\/li><li>\uf0a7 Contr\u00f4ler le strict respect des proc\u00e9dures du Groupe SG dans le cadre de la structuration et de l\u2019ex\u00e9cution des op\u00e9rations relevant de son portefeuille (validations RISQ, notifications, validations de la conformit\u00e9, coordination avec le middle office).<\/li><\/ul>\n\n\n\n<p><strong><em>Ex\u00e9cution \/ Distribution<\/em><\/strong><\/p>\n\n\n\n<ul><li>\uf0a7 N\u00e9gocier la documentation juridique avec l\u2019emprunteur en liaison avec les juristes (internes et \/ ou externes) ;<\/li><li>\uf0a7 Mener les discussions et n\u00e9gociations visant \u00e0 d\u00e9finir la structure et effectuer les recherches n\u00e9cessaires \u00e0 la ma\u00eetrise de toutes les contraintes et tous les risques li\u00e9s \u00e0 la structure retenue ;<\/li><li>\uf0a7 Coordonner et suivre les actions des diff\u00e9rents intervenants internes (RISQ, CPLE, RSE, coverage, ing\u00e9nieurs-conseils, AFMO, GLBA\u2026) et externes (consultants techniques, juridiques et fiscaux, march\u00e9s\u2026) ;<\/li><li>\uf0a7 \u00c9laborer et\/ou assurer la revue de m\u00e9morandums d\u2019information, de mod\u00e8les financiers et de term sheet dans le cadre des transactions pilot\u00e9es par le hub SFG ;<\/li><li>\uf0a7 Proposer des strat\u00e9gies de syndication et participer \u00e0 leur mise en \u0153uvre : pr\u00e9sentation de m\u00e9morandums d\u2019information, n\u00e9gociation avec les banques locales et constitution des consortiums finaux ;<\/li><li>\uf0a7 Encadrer les analystes dans la gestion du portefeuille et dans la r\u00e9daction des livrables.<\/li><\/ul>\n\n\n\n<p><strong><em>Suivi des Transactions<\/em><\/strong><\/p>\n\n\n\n<ul><li>\uf0a7 Assurer le bon suivi des op\u00e9rations \u00e0 travers la transmission exhaustive au Back Office de la filiale concern\u00e9e et au Middle Office du hub SFG des informations n\u00e9cessaires \u00e0 la gestion du dossier et, si n\u00e9cessaire, l\u2019intervention sur des op\u00e9rations existantes en proposant des solutions adapt\u00e9es pour contribuer \u00e0 leur bon d\u00e9nouement ;<\/li><li>\uf0a7 Intervenir sur des op\u00e9rations existantes et participer si n\u00e9cessaire \u00e0 la sortie d\u2019anciennes op\u00e9rations en proposant les solutions adapt\u00e9es ;<\/li><li>\uf0a7 Etre responsable \u00e0 son niveau de l\u2019application de toutes les proc\u00e9dures en vigueur.<\/li><li>Pour ce poste de 11e cat\u00e9gorie, le candidat devra avoir les comp\u00e9tences suivantes :<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences techniques<\/strong><\/p>\n\n\n\n<ul><li>\u2022 Solide connaissance du secteur bancaire et de sa r\u00e9glementation, des banques de la place, de leur organisation et de leurs processus de d\u00e9cision ;<\/li><li>\u2022 Solides connaissances en finance, droit des soci\u00e9t\u00e9s, droit des affaires et fiscalit\u00e9 ;<\/li><li>\u2022 Mod\u00e9lisation financi\u00e8re ;<\/li><li>\u2022 Fortes aptitudes commerciales ;<\/li><li>\u2022 Forte capacit\u00e9 de n\u00e9gociation ;<\/li><li>\u2022 Ma\u00eetrise des logiciels de bureautique Excel, Powerpoint, Word) et outils de communication ;<\/li><li>\u2022 Tr\u00e8s bonne pratique de l\u2019anglais (niveau professionnel)<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences comportementales<\/strong><\/p>\n\n\n\n<ul><li>\u2022 Autonomie ;<\/li><li>\u2022 R\u00e9activit\u00e9 ;<\/li><li>\u2022 Rigueur ;<\/li><li>\u2022 Curiosit\u00e9 ;<\/li><li>\u2022 Implication ;<\/li><li>\u2022 Esprit de synth\u00e8se et d\u2019analyse dans la r\u00e9daction des rapports ;<\/li><li>\u2022 Go\u00fbt pour le travail en \u00e9quipe ;<\/li><li>\u2022 Tr\u00e8s bon relationnel ;<\/li><li>\u2022 Sens de la confidentialit\u00e9.<\/li><\/ul>\n\n\n\n<p><strong>PARTICULARIT\u00c9S DU POSTE\u00a0<\/strong><\/p>\n\n\n\n<ul><li>\u2022 Se tenir \u00e0 jour de l\u2019actualit\u00e9 \u00e9conomique nationale et internationale ;<\/li><li>\u2022 D\u00e9placements dans les pays de sa zone ;<\/li><li>\u2022 Participation ponctuelle \u00e0 des r\u00e9unions internes des filiales de la zone.<\/li><\/ul>\n\n\n\n<p><strong>PROFIL DU CANDIDAT\u00a0<\/strong><\/p>\n\n\n\n<ul><li>\u2022 Minimum BAC+ 5 en Finance, Gestion, Corporate Finance \u2013 Financements structur\u00e9s ou \u00e9quivalent ;<\/li><li>\u2022 Exp\u00e9rience (au moins 5 ans) dans les activit\u00e9s de financement et d\u2019investissement et\/ou dans la gestion client\u00e8le d\u2019un portefeuille de Grandes Entreprises ou encore dans le domaine de l\u2019analyse financi\u00e8re des grands projets d\u2019investissement.<\/li><\/ul>\n\n\n\n<p><strong>DATE LIMITE DE R\u00c9CEPTION DES CANDIDATURES<\/strong>\u00a0: Vendredi, le 10 juillet 2020 A 17 HEURES.<em><strong>NB : SEULES LES CANDIDATURES RETENUES SERONT CONTACT\u00c9ES ULT\u00c9RIEUREMENT.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Cameroun Recrute un responsable des financements strucutres \u00e0 douala<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[23,346],"tags":[93,94,33,34],"villes":[135],"contrats":[234],"diplomes":[163,159],"louma_meta":{"emploi_title":"RESPONSABLE FINANCEMENTS STRUCTURES","emplois_employeur":3502,"emplois_date_publication":"2020-06-26","emplois_heure_publication":"18:00","emplois_date_cloture":"2020-07-10","emplois_heure_cloture":"23:59","emplois_experience_min":"5","emplois_experience_max":"","emploi_email":"https:\/\/www.talenteo.com\/job-apply\/b6609fc11550c3177273"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4243"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=4243"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/4243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3503"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=4243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=4243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=4243"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=4243"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=4243"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=4243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}