{"id":41963,"date":"2023-06-15T18:51:31","date_gmt":"2023-06-15T16:51:31","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=41963"},"modified":"2023-06-15T18:51:33","modified_gmt":"2023-06-15T16:51:33","slug":"stagiaires-agents-de-credit-et-de-recouvrement","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/stagiaires-agents-de-credit-et-de-recouvrement\/","title":{"rendered":"Stagiaires Agents de Cr\u00e9dit et de Recouvrement"},"content":{"rendered":"\n<p>Dans le cadre du renforcement de l&rsquo;effectif de sa force de vente, PECTEN EMPLOYEES COOPERATIVE CREDIT UNION (PECCU \u2013 BOD) recrute des Agents de cr\u00e9dit et de recouvrement stagiaires avec possibilit\u00e9 d&rsquo;\u00eatre confirm\u00e9s au poste apr\u00e8s leur p\u00e9riode d\u2019essai.<\/p>\n\n\n\n<p><strong>Nombre de places:\u00a0<\/strong>05<br>Lieu de travail: Douala<br><strong>Missions:<\/strong><br>Plac\u00e9 sous la responsabilit\u00e9 du Directeur General, l&rsquo;agent de cr\u00e9dit et de recouvrement stagiaire a pour principales missions de cr\u00e9er, d\u00e9velopper, g\u00e9rer un portefeuille sain de cr\u00e9dits et proc\u00e9der au recouvrement des cr\u00e9ances douteuses et immobilis\u00e9es.<\/p>\n\n\n\n<p><strong>Principales Activit\u00e9s : \u00a0<\/strong><\/p>\n\n\n\n<p>\u2022\u00a0\u00a0 \u00a0Prospecter les clients;<br>\u2022\u00a0\u00a0 \u00a0Analyser les demandes de cr\u00e9dit;<br>\u2022\u00a0\u00a0 \u00a0D\u00e9terminer la solvabilit\u00e9 des clients;<br>\u2022\u00a0\u00a0 \u00a0D\u00e9terminer la capacit\u00e9 de remboursement en fonction de la demande de cr\u00e9dit;<br>\u2022\u00a0\u00a0 \u00a0Analyser l&rsquo;ensemble des risques inh\u00e9rents \u00e0 un dossier de pr\u00eat;<br>\u2022\u00a0\u00a0 \u00a0R\u00e9diger les notes de synth\u00e8se pour le comit\u00e9 de cr\u00e9dit;<br>\u2022\u00a0\u00a0 \u00a0Suivre les \u00e9tapes du processus cr\u00e9dit;<br>\u2022\u00a0\u00a0 \u00a0Veiller au remboursement des pr\u00eats des clients de son portefeuille ;<br>\u2022\u00a0\u00a0 \u00a0Suivre l&rsquo;\u00e9volution de l&rsquo;activit\u00e9 des clients et l&rsquo;utilisation qu&rsquo;ils font de leur pr\u00eat;<br>\u2022\u00a0\u00a0 \u00a0Assurer la gestion du pr\u00e9contentieux aupr\u00e8s des clients d\u00e9faillants dans le respect des r\u00e8gles en vigueur ;<br>\u2022\u00a0\u00a0 \u00a0La v\u00e9rification du niveau de provision des cr\u00e9ances compromises de l\u2019institution ainsi que les reprises de provisions;<br>\u2022\u00a0\u00a0 \u00a0La conduite des actions propres au pr\u00e9contentieux (visites terrain, \u00e9valuation du patrimoine, r\u00e9daction des protocoles d\u2019accord\u2026) ;<br>\u2022\u00a0\u00a0 \u00a0La validation des notes de synth\u00e8se dans chaque dossier retra\u00e7ant l\u2019historique des relations avec le d\u00e9biteur et indiquant les montants \u00e0 recouvrer et les actions men\u00e9es ;<br>\u2022\u00a0\u00a0 \u00a0La pr\u00e9paration et la participation aux comit\u00e9s contentieux\/recouvrement, puis la r\u00e9daction des comptes rendus y relatifs;<br>\u2022\u00a0\u00a0 \u00a0Le reporting mensuel des activit\u00e9s de son champ d\u2019activit\u00e9 (r\u00e9cup\u00e9ration, entr\u00e9es de dossiers, saisies-ventes, etc\u2026.<br>\u2022\u00a0\u00a0 \u00a0Vendre l&rsquo;ensemble des produits et services offerts par l&rsquo;institution \u00e0 tout client potentiel.<br><strong>Comp\u00e9tences requises:<\/strong><br>\u2022\u00a0\u00a0 \u00a0Bonne connaissance en analyse financi\u00e8re;<br>\u2022\u00a0\u00a0 \u00a0Bonne connaissance du secteur de la microfinance et\/ou du secteur bancaire;<br>\u2022\u00a0\u00a0 \u00a0Connaissance des techniques de vente et n\u00e9gociation commerciale;<br>\u2022\u00a0\u00a0 \u00a0Bonne connaissance des outils bureautiques : Word et Excel.<br><strong>Profil requis: \u00a0<\/strong><br><strong>Aptitudes comportementales:<\/strong><br>Int\u00e9grit\u00e9 et sens des valeurs morales;<br>Orientation clients et orientation r\u00e9sultats;<br>Capacit\u00e9 d&rsquo;analyse et de synth\u00e8se;<br>Aisance communicationnelle;<br>Esprit d&rsquo;\u00e9quipe;<br>Ouverture d&rsquo;esprit et dynamisme.<br><br><strong>Formation :<\/strong><br>Minimum BAC+3 en Sciences de gestion, Marketing, Commerce et vente, Comptabilit\u00e9, Banque et Finance, Droit ou autres disciplines connexes;<br>Le bilinguisme fran\u00e7ais-anglais serait un atout.<br>Une exp\u00e9rience dans le domaine du cr\u00e9dit est souhait\u00e9e.<br><strong>COMMENT POSTULER?<\/strong><br>Postulez en envoyant votre CV et une lettre de motivation pr\u00e9cisant votre ville de r\u00e9sidence \u00e0 l&rsquo;adresse : rh.recrutement0623@gmail.com .<br>D\u00e9lai de r\u00e9ception des candidatures : 30 Juin 2023.<br><br><br>As part of the reinforcement of its sales force, PECTEN EMPLOYEES COOPERATIVE CREDIT UNION (PECCU \u2013 BOD) is recruiting trainee Credit and Collection Officers with the possibility of being confirmed in the position after their probationary period.<br>Number of trainee: 05<br>Place of work: Douala<br><br><strong>Missions:<\/strong><br>Placed under the responsibility of the Director General, the main missions of the trainee loan and collection officer are to create, develop, manage a healthy portfolio of credits and recover doubtful and immobilized debts.<br><br><strong>Main activities: \u00a0<\/strong><br><strong>\u2022 Prospect customers;<\/strong><br><strong>\u2022 Analyze credit applicatio<\/strong>ns;<br>\u2022 Determine the creditworthiness of customers;<br>\u2022 Determine repayment capacity based on credit demand;<br>\u2022 Analyze all the risks inherent in a loan file;<br>\u2022 Draft briefing notes for the credit committee;<br>\u2022 Follow the steps of the credit process;<br>\u2022 Ensure the repayment of loans from clients in its portfolio;<br>\u2022 Monitor the evolution of clients&rsquo; activity and the use they make of their loan;<br>\u2022 Ensure the management of pre-litigation with defaulting clients in compliance with the rules in force;<br>\u2022 Verification of the level of provision of impaired claims of the institution as well as reversals of provisions;<br>\u2022 The conduct of actions specific to pre-litigation (field visits, heritage evaluation, drafting of memoranda of understanding, etc.) ;<br>\u2022 The validation of summary notes in each file retracing the history of relations with the debtor and indicating the amounts to be recovered and the actions taken;<br>\u2022 Preparation and participation in litigation\/recovery committees, followed by drafting of related reports; \u00a0<br>\u2022 The monthly reporting of the activities of its field of activity (recovery, file entries, sales seizures, etc &#8230;.<br>\u2022 Sell all products and services offered by the institution to any potential client.<br><br><strong>Required skills:<\/strong><br>\u2022 Good knowledge of financial analysis;<br>\u2022 Good knowledge of the microfinance and\/or banking sector;<br>\u2022 Knowledge of sales techniques and commercial negotiation;<br>\u2022 Good knowledge of office tools: Word and Excel.<br><br><strong>Required profile: \u00a0<\/strong><br><strong>Behavioural skills:<\/strong><br>Integrity and sense of moral values;<br>Client orientation and results orientation;<br>Analytical and synthesis skills;<br>Communicational skills;<br>Teamwork;<br>Open-mindedness and dynamism.<br><br><strong>Formation:<\/strong><br>Minimum BAC+3 in Management Sciences, Marketing, Commerce and Sales, Accounting, Banking and Finance, Law or other related disciplines;<br>English\u2013French bilingualism would be an asset.<br>Experience in the field of credit is desirable.<br><br><strong>HOW TO POSTULATE?<\/strong><br>Apply by sending your CV and a cover letter specifying your city of residence to: rh.recrutement0623@gmail.com . \u00a0<br>Deadline for receipt of applications: 30th June 2023.<br><br><br><\/p>\n\n\n\n<p><a href=\"https:\/\/affpa.top\/L?tag=d_85717m_2896c_Formation&amp;site=85717&amp;ad=2896&amp;r=bonus\/rules\/1st\/\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via rh.recrutement0623@gmail.com . \u00a0<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,282,1139,24,1273],"tags":[],"villes":[135],"contrats":[152],"diplomes":[212,159],"louma_meta":{"emploi_title":"","emplois_employeur":3046,"emplois_date_publication":"2023-06-15","emplois_heure_publication":"17:51","emplois_date_cloture":"2023-06-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"rh.recrutement0623@gmail.com . \u00a0"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41963"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=41963"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=41963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=41963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=41963"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=41963"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=41963"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=41963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}