{"id":41892,"date":"2023-06-13T11:50:10","date_gmt":"2023-06-13T09:50:10","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=41892"},"modified":"2023-06-13T11:50:13","modified_gmt":"2023-06-13T09:50:13","slug":"chef-dagence-h-f-ref-cag0123","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/chef-dagence-h-f-ref-cag0123\/","title":{"rendered":"CHEF D\u2019AGENCE H\/F (R\u00e9f. CAG0123)"},"content":{"rendered":"\n<p>CDI bas\u00e9 \u00e0 Douala<br><br>BASSAGAL CONSULTING AFRICA recrute, pour un de ses clients du secteur de la<br>communication.<\/p>\n\n\n\n<p><br>Vous aurez pour activit\u00e9s principales :<br>\u2022 Repr\u00e9senter l\u2019agence aupr\u00e8s des clients et des prospects ;<br>\u2022 Initier avec l\u2019\u00e9quipe les r\u00e9flexions strat\u00e9giques des campagnes en analysant les besoins par<br>un brief et ensuite r\u00e9diger et pr\u00e9senter une recommandation (cahier des charges d\u00e9finissant<br>la cible, l\u2019axe et les th\u00e8mes publicitaires, le message et le budget) ;<br>\u2022 Superviser la r\u00e9alisation de la campagne jusqu\u2019\u00e0 sa finalisation ;<br>\u2022 \u00catre le garant de la bonne gestion de la relation client, de la qualit\u00e9 du travail r\u00e9alis\u00e9, du<br>respect des budgets et des d\u00e9lais impartis ;<br>\u2022 Dresser le bilan de la campagne achev\u00e9e par le contr\u00f4le et l\u2019analyse des r\u00e9sultats quantitatifs<br>et qualitatifs ;<br>\u2022 Planifier les diff\u00e9rentes activit\u00e9s de l\u2019agence ;<br>\u2022 Encadrer et superviser les collaborateurs ;<br>\u2022 Assurer les objectifs de rentabilit\u00e9 et la marge brute r\u00e9alis\u00e9e sur chaque op\u00e9ration ;<br>\u2022 \u00catre responsable de la conformit\u00e9 de la prestation par rapport \u00e0 la demande du client ;<br>\u2022 \u00catre responsable de la fid\u00e9lisation du portefeuille de clients ;<br>\u2022 Faire le reporting \u00e0 la direction et assurer la gestion op\u00e9rationnelle de la relation client.<\/p>\n\n\n\n<p><br>Profil:<br>\u2022 De formation sup\u00e9rieure en Communication ou \u00e9quivalent ou en Gestion,<br>\u2022 Vous justifiez d\u2019une exp\u00e9rience pertinente \u00e0 un poste similaire ;<br>\u2022 Vous justifiez d\u2019une exp\u00e9rience d\u2019au moins 5 ans en agence ou en entreprise ;<br>\u2022 \u00catre Bilingue ;<br>\u2022 Avoir au minimum 35 ans ;<br>\u2022 \u00catre titulaire d\u2019un permis de conduire B ;<br>\u2022 Sens de l\u2019\u00e9coute, de la gestion et de l\u2019organisation ;<br>\u2022 Gout des contacts humains ;<br>\u2022 Forte capacit\u00e9 d\u2019analyse, de synth\u00e8se et de r\u00e9daction ;<br>\u2022 Cr\u00e9ativit\u00e9, dynamisme, combativit\u00e9;<br>\u2022 Curiosit\u00e9, souplesse d\u2019esprit et bonne r\u00e9sistance au stress ;<br>\u2022 Rigoureux et organis\u00e9;<br>\u2022 Diplomatie et bon relationnel ;<br>\u2022 Adaptabilit\u00e9 \/flexibilit\u00e9 ;<br>\u2022 Bon commercial.<\/p>\n\n\n\n<p>Les candidats int\u00e9ress\u00e9s devront envoyer leur CV en pr\u00e9cisant la r\u00e9f\u00e9rence \u00ab CAG0123 \u00bb \u00e0 l\u2019adresse<br>suivant<br>yannick.billigha@bassagal-consulting.com<br>La date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 19 Juin 2023.<br>Seuls les candidats shortlist\u00e9s (r\u00e9pondant au profil) seront contact\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>contact pour postuler : yannick.billigha@bassagal-consulting.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[25,1139],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159,2259],"louma_meta":{"emploi_title":"CHEF D'AGENCE","emplois_employeur":4772,"emplois_date_publication":"2023-06-13","emplois_heure_publication":"10:50","emplois_date_cloture":"2023-06-19","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"5","emploi_email":"yannick.billigha@bassagal-consulting.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41892"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=41892"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=41892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=41892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=41892"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=41892"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=41892"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=41892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}