{"id":41744,"date":"2023-06-07T15:40:53","date_gmt":"2023-06-07T13:40:53","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=41744"},"modified":"2023-06-07T15:43:47","modified_gmt":"2023-06-07T13:43:47","slug":"officier-nutrition%ef%bf%bc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/officier-nutrition%ef%bf%bc\/","title":{"rendered":"OFFICIER NUTRITION\ufffc"},"content":{"rendered":"\n<p>Titre du poste: OFFICIER NUTRITION<br>Rel\u00e8ve de: Chef de Projet Adjoint<br>Lieu d\u2019affectation Maroua<br>Type de contrat CDD<br>Dur\u00e9e du contrat:<br>07 mois<br>Disponibilit\u00e9: Juin 2023<br><strong>Objectifs Principaux<\/strong><\/p>\n\n\n\n<p>Sous la supervision du Chef de Projet Adjoint, l\u2019Officier Nutrition est responsable du suivi de la mise en place de la qualit\u00e9 des activit\u00e9s de pr\u00e9vention, d\u00e9tection et de traitement de la malnutrition dans les zones d\u2019intervention du projet. Il\/elle veillera \u00e0 ce que les besoins en formation et en renforcement des capacit\u00e9s du personnel sur le terrain soient trait\u00e9s en temps utile.<br><strong>Missions et Responsabilit\u00e9s<\/strong><\/p>\n\n\n\n<p><strong>1. Coordination et repr\u00e9sentation ext\u00e9rieure<\/strong><br>&#8211; Assurer la bonne compr\u00e9hension des diff\u00e9rentes activit\u00e9s d&rsquo;INTERSOS et \u00e9tablir de bonnes relations avec toutes les parties prenantes du projet dans les zones d&rsquo;intervention sous la supervision du Chef de Projet Adjoint;<br>&#8211; Sous la supervision du Chef de Projet Adjoint, assurer une pr\u00e9sence r\u00e9guli\u00e8re et active aux r\u00e9unions<br>techniques et g\u00e9n\u00e9rales au niveau local (dans toutes les localit\u00e9s o\u00f9 le projet est mis en \u0153uvre);<br>&#8211; Veiller \u00e0 la collecte et \u00e0 la qualit\u00e9 des informations partag\u00e9es sous le contr\u00f4le du Chef de Projet Adjoint;<br>&#8211; Sous la supervision du Chef de Projet Adjoint et en suivant la charte de communication, assurer une<br>communication efficace et opportune avec le personnel du PAM sur les op\u00e9rations de terrain ;<\/p>\n\n\n\n<p><strong>2. Supervision et suivi<\/strong><\/p>\n\n\n\n<p>Former les ASC\/relais\/points focaux sur le d\u00e9pistage de la malnutrition ;<br>&#8211; Appuyer la formation des b\u00e9n\u00e9ficiaires sur le d\u00e9pistage de la malnutrition ;<br>&#8211; Apporter un support aux \u00e9quipes sur l\u2019organisation du travail et suivre et \u00e9valuer la r\u00e9alisation ;<br>&#8211; Faire le suivi des enfants (MAS) r\u00e9f\u00e9r\u00e9s vers les structures de prise en charge conjointement avec les<br>acteurs communautaires;<br>&#8211; Coordonner avec les officier meal le suivi et le reporting mensuelle des visites \u00e0 domiciles (VAD) et les<br>d\u00e9pistages communautaires ;<br>&#8211; En relation avec le Chef de Projet Adjoint, participe \u00e0 l\u2019\u00e9laboration de la strat\u00e9gie op\u00e9rationnelle pour tout<br>le travail de terrain, y compris la mobilisation communautaire;<br>&#8211; Coordonne les proc\u00e9dures de paiement, y compris la documentation et les rapports pour assurer la<br>responsabilit\u00e9 envers le donateur et l&rsquo;organisation;- Avec le soutien du Chef de Projet Adjoint, assure la conformit\u00e9 administrative des activit\u00e9s aux autorit\u00e9s<br>au niveau op\u00e9rationnel et organise le suivi appropri\u00e9 de toute question en suspens ou en cours;<br>&#8211; Avec l&rsquo;appui du Chef de Projet Adjoint, assure la conformit\u00e9 des activit\u00e9s avec les diff\u00e9rents d\u00e9partements<br>(finances, s\u00e9curit\u00e9, logistique et MEAL) et suit tout processus en cours \u00e0 cet \u00e9gard.<br>&#8211; Veille \u00e0 la bonne utilisation des outils techniques valid\u00e9s et, si le contexte le n\u00e9cessite, propose leur<br>modification ou la mise en place de nouveaux outils.<\/p>\n\n\n\n<p><strong>3. Impl\u00e9mentation des activit\u00e9s de nutrition<\/strong><\/p>\n\n\n\n<p>&#8211; Proposer un planning de distribution et des activit\u00e9s connexes et organise la sensibilisation des diff\u00e9rentes<br>parties prenantes \u00e0 l\u2019op\u00e9ration (comit\u00e9s, autorit\u00e9s et b\u00e9n\u00e9ficiaires);<br>&#8211; Identifier les b\u00e9n\u00e9ficiaires qui auront besoin d\u2019appui sp\u00e9cifique dans le domaine de l\u2019ANJE ;<br>&#8211; Garantir la disponibilit\u00e9 et la conformit\u00e9 aux normes fix\u00e9es par PAM du mat\u00e9riel de distribution et signaler<br>ce qui manque pour un compl\u00e9ment \u00e9ventuel ;<br>&#8211; Organiser avec les moniteurs\/ agents terrain la r\u00e9ception des vivres, l\u2019organisation dans les magasins d\u00e9di\u00e9s<br>et le renseignement des fiches de r\u00e9ception suivant les normes du PAM ;<br>&#8211; Planifier le transport et le stockage des intrants sur les sites de distribution ;<br>&#8211; V\u00e9rifie si les quantit\u00e9s seront suffisantes pour couvrir toute la population avant la distribution;<br>&#8211; Mettre en place et former les comit\u00e9s de distribution selon les besoins identifi\u00e9s lors de leur prestation en<br>collaboration avec les autres partenaires ;<br>&#8211; Coordonner les proc\u00e9dures de paiement, y compris la documentation et les rapports pour assurer la<br>redevabilit\u00e9 envers le donateur et l&rsquo;organisation.<\/p>\n\n\n\n<p>4. Gestion des ressources humaines<\/p>\n\n\n\n<p>&#8211; Contr\u00f4ler, responsabiliser et \u00e9valuer les performances de toute l&rsquo;\u00e9quipe de projet sous sa supervision<br>direct ;<br>&#8211; Avec l\u2019appui du Chef de Projet Adjoint, d\u00e9finir les termes de r\u00e9f\u00e9rence des Animateurs Terrain Nutrition,<br>encadre leur suivi par les Agents de Terrain Nutrition ;<br>&#8211; Clarifier les r\u00f4les, attribuer des t\u00e2ches\/responsabilit\u00e9s claires et \u00e9tablir des plans de travail et des feuilles<br>de route pour chaque membre de l&rsquo;\u00e9quipe sous sa supervision directe ;<br>&#8211; Assurer une d\u00e9l\u00e9gation claire des responsabilit\u00e9s et responsabilise les membres de l&rsquo;\u00e9quipe sous sa<br>supervision ;<br>&#8211; Relayer les questions RH soulev\u00e9es par les \u00e9quipes aupr\u00e8s du Chef de Projet.<\/p>\n\n\n\n<p><br>5. Gestion des donn\u00e9es<br>&#8211; En collaboration avec l\u2019\u00e9quipe M&amp;E, faciliter la collecte et la compilation des donn\u00e9es des diff\u00e9rents<br>indicateurs ;<br>&#8211; S&rsquo;assurer que la qualit\u00e9 des donn\u00e9es collect\u00e9es soit correctement trait\u00e9e avant leur soumission au Chef de<br>projet ;<\/p>\n\n\n\n<p>6. Rapportage<br>&#8211; Contribuer \u00e0 la mise en place de syst\u00e8mes efficaces de rapportage, de suivi et d&rsquo;\u00e9valuation du programme,<br>\u00e0 usage interne et externe, en coordination avec les autres membres du personnel du programme ;- Fournir des informations sur l\u2019ensemble des activit\u00e9s \u00e0 la demande du gestionnaire de projet ou de l&rsquo;\u00e9quipe<br>de S&amp;E ;<br>&#8211; Fournir des rapports quotidiens et hebdomadaires sur le terrain, faisant \u00e9tat de l&rsquo;avancement des activit\u00e9s,<br>des le\u00e7ons apprises et des r\u00e9ussites du programme suivant le format du PAM ;<br>&#8211; V\u00e9rifier la coh\u00e9rence et la qualit\u00e9 des informations fournies par les \u00e9quipes et assurer leur compilation et<br>leur validation par le Chef de Projet Adjoint ;<br>&#8211; Participer aux rapports des donateurs et \u00e0 la pr\u00e9paration de nouvelles propositions.<\/p>\n\n\n\n<p>7. Analyse et strat\u00e9gie<\/p>\n\n\n\n<p>\u00a0Analyser les points faibles et les points forts du projet \u00e0 travers les enqu\u00eates d\u2019impacts et les descentes<br>de monitoring ;<br>&#8211; Analyser le contexte op\u00e9rationnel, identifier les opportunit\u00e9s de financement et les diff\u00e9rents risques<br>pour le projet et l&rsquo;organisation ;<br>&#8211; Participer \u00e0 l\u2019\u00e9laboration de nouvelles propositions.<\/p>\n\n\n\n<p><strong>8. Redevabilit\u00e9<\/strong><\/p>\n\n\n\n<p>&#8211; En collaboration avec le point focal de la redevabilit\u00e9, s&rsquo;assurer que tous les outils de redevabilit\u00e9 sont mis<br>en \u0153uvre \u00e0 toutes les \u00e9tapes du projet et veiller \u00e0 leur fonctionnement optimal.<br>&#8211; Engage les \u00e9quipes et signale activement les cas de fraude ou d&rsquo;abus, y compris les cas d&rsquo;EES constat\u00e9s<br>par les \u00e9quipes ou les partenaires, en liaison avec le point focal PSEA.<br>&#8211; Par la tenue d&rsquo;un registre, s&rsquo;assure que les avis et suggestions des b\u00e9n\u00e9ficiaires sur les activit\u00e9s du projet<br>sont pris en compte.<br>Exigences du poste<\/p>\n\n\n\n<p><strong>Education Qualification :<\/strong>\u00a0agronome<\/p>\n\n\n\n<p><strong>o Profil Nutritionniste :\u00a0<\/strong>dipl\u00f4me d\u2019Infirmier Dipl\u00f4m\u00e9 d\u2019Etat (Bac+3),<br>dipl\u00f4me de Master (Bac+5) en Nutrition, en agroalimentaire ou tout autre<br>domaine scientifique connexe.<\/p>\n\n\n\n<p><strong>Exp\u00e9riences\u00a0professionnelles<\/strong><\/p>\n\n\n\n<p>o Minimum de 2 ans d&rsquo;exp\u00e9rience dans un contexte humanitaire, dans une<br>association, une ONG ou une ONGI, avec au moins 2 ans d&rsquo;exp\u00e9rience de<br>travail sur le terrain dans un contexte de crise humanitaire.<br>o Exp\u00e9rience professionnelle coh\u00e9rente avec les modalit\u00e9s d&rsquo;assistance<br>alimentaire du PAM dans un contexte similaire.<br>Exp\u00e9rience de la gestion d&rsquo;\u00e9quipe d&rsquo;au moins 1 an ; toute exp\u00e9rience<br>pertinente \u00e0 un niveau de responsabilit\u00e9 similaire serait un atout.<br>Langage o Ma\u00eetrise du fran\u00e7ais formel \u00e9crit et oral<br>o Fortes comp\u00e9tences r\u00e9dactionnelles et communicationnelles<br>o Ma\u00eetrise d\u2019une langue vernaculaire locale exig\u00e9e (Fufuld\u00e9, Mafa, Mandara<br>ou arabe Choa), la ma\u00eetrise de plusieurs serait un atout<br>Informatique o Connaissance avanc\u00e9e Microsoft Office (Word, Excel, Outlook),<br>o Outils SIG humanitaires de base (OpenStreetMaps, Google Earth et Google<br>Custom maps)o Navigateurs web courants (Google Chrome, Microsoft Edge, Mozilla<br>Firefox)<br>o Outils\/plateformes de chat et de conf\u00e9rence grand public bas\u00e9s sur le Web<br>(Skype, Teams, Zoom et WebEx) o Outils Web 2.0 (stockage cloud, Webmail et autres)<\/p>\n\n\n\n<p>Envoyez votre CV et lettre de motivation en suivant le lien ci-apr\u00e8s:\u00a0<a href=\"https:\/\/urlz.fr\/mcUq\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/urlz.fr\/mcUq<\/a><br>NB: Seules candidatures pr\u00e9s\u00e9lectionn\u00e9es seront contact\u00e9es pour le test.<br>Le delai de d\u00e9p\u00f4t de candidature est fix\u00e9 au 13 Juin 2023 \u00e0 17 H .<br><em>HR-Department<\/em><\/p>\n\n\n\n<p><em>INTERSOS \u2013 Cameroun<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Envoyez votre CV et lettre de motivation en suivant le lien ci-apr\u00e8s:\u00a0https:\/\/urlz.fr\/mcUq<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[2993,354],"tags":[],"villes":[141],"contrats":[236],"diplomes":[212,159],"louma_meta":{"emploi_title":"OFFICIER NUTRITION","emplois_employeur":4116,"emplois_date_publication":"2023-06-07","emplois_heure_publication":"","emplois_date_cloture":"2023-06-13","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"2","emploi_email":"https:\/\/urlz.fr\/mcUq"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41744"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=41744"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4117"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=41744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=41744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=41744"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=41744"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=41744"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=41744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}