{"id":41555,"date":"2023-05-29T10:58:17","date_gmt":"2023-05-29T08:58:17","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=41555"},"modified":"2023-05-29T10:58:19","modified_gmt":"2023-05-29T08:58:19","slug":"responsable-controle-interne-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2023\/responsable-controle-interne-2\/","title":{"rendered":"RESPONSABLE CONTR\u00d4LE INTERNE"},"content":{"rendered":"\n<p>UN RESPONSABLE CONTROLE INTERNE (R\u00e9f. RCI0123)<br>Poste bas\u00e9 hors de Douala et Yaound\u00e9<br><\/p>\n\n\n\n<p>BASSAGAL CONSULTING AFRICA recrute, pour une multinationale du secteur del\u2019agroindustrie :<br>Vous aurez pour activit\u00e9s principales : <\/p>\n\n\n\n<p>\uf0b7 Mettre en place, piloter et \u00e9valuer les dispositifs de contr\u00f4le interne ; <\/p>\n\n\n\n<p>\uf0b7 Assurer la mise en place et le suivi des plans de contr\u00f4le ; <\/p>\n\n\n\n<p>\uf0b7 \u00c9tudier les risques li\u00e9s aux activit\u00e9s de l\u2019entreprise et en \u00e9tablir la cartographie ; <\/p>\n\n\n\n<p>\uf0b7 D\u00e9finir et r\u00e9diger les dispositifs de contr\u00f4le interne ; <\/p>\n\n\n\n<p>\uf0b7 D\u00e9finir des axes d\u2019am\u00e9liorations et formuler des pr\u00e9conisations pour garantir unecouverture optimale des risques et le respect des exigences r\u00e9glementaires ; <\/p>\n\n\n\n<p>\uf0b7 R\u00e9diger des rapports de contr\u00f4le, de reporting, et les plans de continuit\u00e9 des activit\u00e9s; <\/p>\n\n\n\n<p>\uf0b7 Animer, former et informer le r\u00e9seau des correspondants du contr\u00f4le interne ;<br><\/p>\n\n\n\n<p>Profil : <\/p>\n\n\n\n<p>\uf0b7 De formation sup\u00e9rieure en Audit, Fiscalit\u00e9, Contr\u00f4le Interne ou tout dipl\u00f4me \u00e9quivalent;<\/p>\n\n\n\n<p>\uf0b7 Vous justifiez d\u2019une exp\u00e9rience pertinente dans un environnement agro-industriel ; <\/p>\n\n\n\n<p>\uf0b7 Vous justifiez d\u2019une exp\u00e9rience pertinente \u00e0 un poste similaire ; <\/p>\n\n\n\n<p>\uf0b7 Avoir une aisance relationnelle, un bon esprit d\u2019analyse et de synth\u00e8se ; <\/p>\n\n\n\n<p>\uf0b7 \u00catre curieux et ouvert d\u2019esprit ; <\/p>\n\n\n\n<p>\uf0b7 Avoir le sens de la discr\u00e9tion et de la diplomatie ;<br>Avoir des notions en analyse des donn\u00e9es ; <\/p>\n\n\n\n<p>\uf0b7 Avoir une ma\u00eetrise du pack office. Les candidats int\u00e9ress\u00e9s devraient envoyer leur CV en pr\u00e9cisant la r\u00e9f\u00e9rence RCI0123 \u00e0 l\u2019adresse suivante : yannick.billigha@bassagal-consulting.comLa date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 05 juin 2023. Seuls les candidats short list\u00e9s seront contact\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Postulez via yannick.billigha@bassagal-consulting.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1594,346,1139],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE CONTR\u00d4LE INTERNE","emplois_employeur":4772,"emplois_date_publication":"2023-05-29","emplois_heure_publication":"09:58","emplois_date_cloture":"2023-06-05","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"1","emploi_email":"yannick.billigha@bassagal-consulting.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41555"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=41555"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/41555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=41555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=41555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=41555"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=41555"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=41555"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=41555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}